
{"id":2206,"date":"2018-01-30T02:23:56","date_gmt":"2018-01-30T01:23:56","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=2206"},"modified":"2018-02-14T01:45:29","modified_gmt":"2018-02-14T00:45:29","slug":"seminaire3","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/","title":{"rendered":"Troisi\u00e8me s\u00e9ance \u00e0 l&#8217;Universit\u00e9 Populaire : les piliers des semeurs du changement"},"content":{"rendered":"<p><i>Flash-Backs et Flash Forward sur ce s\u00e9minaire o\u00f9 les curieux et les fronceurs de sourcils sont les bienvenus !\u00a0<\/i><\/p>\n<p><em>Prochaine s\u00e9ance le <strong>dimanche 11 f\u00e9vrier \u00e0 14h30<\/strong> (et non 16h30 comme les autres fois pour les habitu\u00e9s !)<\/em><\/p>\n<p><strong>Ils ont de<\/strong>\u00a025 \u00e0 75 ans.\u00a0<strong>Ils sont <\/strong>paysan, sculpteur, chanteur, boxeur, boulanger, \u00e9leveur de chevaux, coiffeur, chef d\u2019entreprise, m\u00e9decin\u2026<strong>Ils vivent <\/strong>au onzi\u00e8me \u00e9tage d\u2019une tour de banlieue, dans une maison de pierre au bout d\u2019une piste d\u2019un hameau de montagne, dans un petit pavillon en ville, dans une yourte sur une ferme.\u00a0En Normandie, en Picardie, en Ari\u00e8ge, en Savoie, \u00e0 Paris, Marseille, Besan\u00e7on, Lyon.\u00a0<strong>Ils <\/strong>r\u00e9inventent d\u2019autres mani\u00e8res de faire, recalibrent leurs priorit\u00e9s, r\u00e9orientent leurs objectifs<\/p>\n<p><strong>La premi\u00e8re s\u00e9ance<\/strong> du s\u00e9minaire a permis de faire connaissance avec quelques semeurs du changement, de d\u00e9finir ce qu\u2019ils sont et surtout ce qu\u2019ils ne sont pas, pourquoi il \u00e9tait n\u00e9cessaire d\u2019en parler et de quelle mani\u00e8re, en grattant la carte postale de l\u2019alternatif. Pour cette premi\u00e8re s\u00e9ance, la voix de l\u2019acteur Jacques Gamblin nous a accompagn\u00e9e, exhortant les m\u00e9dias \u00e0 &#8220;d\u00e9ployer les gorges de ces inconnus qui inventent de l\u2019alternatif positif tous les jours au r\u00e9veil.&#8221;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.mixcloud.com\/widget\/iframe\/?hide_cover=1&amp;light=1&amp;feed=%2FSarahRoubato%2Fjacques-gamblin-offrez-nous-de-beaux-exemples-nous-avons-besoin-dadmirer-pour-imiter%2F\" width=\"100%\" height=\"120\" frameborder=\"0\"><\/iframe><strong>La seconde s\u00e9ance<\/strong> s\u2019est attard\u00e9e sur l\u2019origine de leurs d\u00e9marches et leur statut dans la soci\u00e9t\u00e9. Qu\u2019est-ce qui les a amen\u00e9s \u00e0 faire ces choix de vie\u00a0? Comment sont-ils per\u00e7us dans leur famille, leur coin de pays, dans la soci\u00e9t\u00e9\u00a0? Ce qui nous a permis de questionner ce qu\u2019\u00e9tait la marge dans une soci\u00e9t\u00e9, et notre rapport au risque. Cette fois, c\u2019est la voix de Jacques Brel qui nous a exhort\u00e9s \u00e0 nous m\u00e9fier du culte de la prudence, \u00e0 &#8220;choisir : priorit\u00e9 aux r\u00eaves ou priorit\u00e9 \u00e0 son petit confort&#8221;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.mixcloud.com\/widget\/iframe\/?hide_cover=1&amp;light=1&amp;feed=%2FSarahRoubato%2Fjacques-brel-les-infirmes-ce-sont-les-hommes-prudents-entre-un-risque-et-une-certitude%2F\" width=\"100%\" height=\"120\" frameborder=\"0\"><\/iframe><strong>Pour cette troisi\u00e8me s\u00e9ance,<\/strong> nous plongerons au c\u0153ur de ce qui selon moi constitue les piliers de ce changement\u00a0: le temps la diversit\u00e9 et l\u2019autonomie. En d\u00e9calant les urgences et les priorit\u00e9s, en s\u2019autorisant le vide au creux de l\u2019urgence, en accueillant les ruptures et les changements, en s\u2019adaptant constamment, ils impriment un tempo \u00e0 leur vie qui leur permet d\u2019embrasser une diversit\u00e9 de savoir-faires et d\u2019exp\u00e9riences au sein d\u2019une m\u00eame activit\u00e9. C\u2019est ainsi qu\u2019ils tendent vers une forme d\u2019autonomie, mat\u00e9rielle, \u00e9conomique ou spirituelle. Nous serons \u00e0 nouveau accompagn\u00e9s par une voix d&#8217;artiste&#8230; surprise&#8230; Et nous finirons la s\u00e9ance en plongeant dans l\u2019exp\u00e9rience d\u2019un portrait sonore.<\/p>\n<div style=\"position: relative; height: 0; padding-bottom: 56.25%;\"><iframe loading=\"lazy\" style=\"position: absolute; width: 25%; height: 25%; left: 0;\" src=\"https:\/\/www.youtube.com\/embed\/QGBidhVUC0Q?ecver=2\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<div style=\"position: relative; height: 0; padding-bottom: 56.25%;\"><iframe loading=\"lazy\" style=\"position: absolute; width: 25%; height: 25%; left: 0;\" src=\"https:\/\/www.youtube.com\/embed\/blqTpFfeqcA?ecver=2\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<div style=\"position: relative; height: 0; padding-bottom: 56.25%;\"><iframe loading=\"lazy\" style=\"position: absolute; width: 25%; height: 25%; left: 0;\" src=\"https:\/\/www.youtube.com\/embed\/SFxhmRaM_2Q?ecver=2\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p><strong><br \/>\n<a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/construction-semeurs.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-2208\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/construction-semeurs.jpg\" alt=\"construction semeurs\" width=\"382\" height=\"343\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/construction-semeurs.jpg 880w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/construction-semeurs-150x135.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/construction-semeurs-300x269.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/construction-semeurs-600x539.jpg 600w\" sizes=\"auto, (max-width: 382px) 100vw, 382px\" \/><\/a><\/strong>Un professeur d\u2019anthropologie britannico-canadien disait toujours\u00a0: &#8220;Vous n\u2019obtiendrez rien \u00e0 demander aux gens pourquoi ils font ce qu\u2019ils font. En revanche si vous leur demandez pourquoi ils ne font pas telle chose ou telle autre, vous ouvrez la bo\u00eete \u00e0 Pandore.&#8221;<\/p>\n<p><strong>Alors donc, qu\u2019est-ce que ce s\u00e9minaire n\u2019est pas\u00a0?<\/strong><\/p>\n<p><strong><em>Un catalogue des h\u00e9ros de l\u2019alternatif\u00a0: <\/em><\/strong>Je ne fais pas\u00a0le r\u00e9cit de la vie de chaque semeur, car ce s\u00e9minaire ne cherche pas \u00e0 montrer des exemples sur comment\u00a0g\u00e9rer une ferme par traction animale ou comment vivre quand on est artiste de sc\u00e8ne, mais \u00e0 entrevoir d&#8217;autres possibles\u00a0par-dessus leur \u00e9paule. Si un jour nous disposons de plus de s\u00e9ances, je pourrais passer une s\u00e9ance par portrait et d\u00e9plier les enjeux\u00a0de chaque personnage. Si vous \u00eates int\u00e9ress\u00e9s \u00e0 le faire, proposez-moi une soir\u00e9e chez vous, \u00e0 votre bureau, dans un lieu associatif. (cliquez\u00a0<strong><a href=\"https:\/\/dev.sarahroubato.com\/contact\/\">ici<\/a>\u00a0<\/strong>pour me contacter)<\/p>\n<p><strong><em>La pr\u00e9sentation d\u2019une \u00e9tude anthropologique\u00a0: <\/em><\/strong>Ce s\u00e9minaire tisse des pistes de r\u00e9flexions anthropologiques mais ne pr\u00e9sente pas le fruit d\u2019une \u00e9tude, qui aurait n\u00e9cessit\u00e9 de passer au moins un an avec chaque personne.<\/p>\n<p><strong><em>Une s\u00e9ance de reconversion\u00a0: <\/em><\/strong>J\u2019invite les sceptiques et les fronceurs de sourcils \u00e0 venir \u00e0 ce s\u00e9minaire car leurs questions et remarques permettent de pr\u00e9ciser l\u2019analyse et le discours. Ce s\u00e9minaire n\u2019est pas une s\u00e9ance de reconversion mais cherche \u00e0 mettre en perspective le regard que nous portons sur ceux qui tentent d\u2019inventer d\u2019autres mani\u00e8res de faire. Ce n\u2019est qu\u2019ainsi que peut s&#8217;envisager leur r\u00f4le\u00a0dans la soci\u00e9t\u00e9.<\/p>\n<p>Au plaisir de vous y rencontrer, et n&#8217;h\u00e9sitez pas \u00e0 prendre le temps de la rencontre \u00e0 la fin de la s\u00e9ance !<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-NB.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-696\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-NB-1024x494.png\" alt=\"signature Sarah NB\" width=\"330\" height=\"159\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flash-Backs et Flash Forward sur ce s\u00e9minaire o\u00f9 les curieux et les fronceurs de sourcils sont les bienvenus !\u00a0 Prochaine s\u00e9ance le dimanche 11 f\u00e9vrier \u00e0 14h30 (et non 16h30 comme les autres fois pour les habitu\u00e9s !) Ils ont de\u00a025 \u00e0 75 ans.\u00a0Ils sont paysan, sculpteur, chanteur, boxeur, boulanger, \u00e9leveur de chevaux, coiffeur, chef [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[471],"tags":[393],"class_list":["post-2206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","tag-changement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Troisi\u00e8me s\u00e9ance \u00e0 l&#039;Universit\u00e9 Populaire : les piliers des semeurs du changement - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Troisi\u00e8me s\u00e9ance \u00e0 l&#039;Universit\u00e9 Populaire : les piliers des semeurs du changement - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Flash-Backs et Flash Forward sur ce s\u00e9minaire o\u00f9 les curieux et les fronceurs de sourcils sont les bienvenus !\u00a0 Prochaine s\u00e9ance le dimanche 11 f\u00e9vrier \u00e0 14h30 (et non 16h30 comme les autres fois pour les habitu\u00e9s !) Ils ont de\u00a025 \u00e0 75 ans.\u00a0Ils sont paysan, sculpteur, chanteur, boxeur, boulanger, \u00e9leveur de chevaux, coiffeur, chef [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-30T01:23:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-14T00:45:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/semeur-van-gogh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/semeur-van-gogh.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/semeur-van-gogh.jpg\",\"width\":550,\"height\":384,\"caption\":\"Le Semeur, Van Gogh.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/\",\"name\":\"Troisi\u00e8me s\u00e9ance \u00e0 l'Universit\u00e9 Populaire : les piliers des semeurs du changement - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#primaryimage\"},\"datePublished\":\"2018-01-30T01:23:56+00:00\",\"dateModified\":\"2018-02-14T00:45:29+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Troisi\u00e8me s\u00e9ance \u00e0 l&#8217;Universit\u00e9 Populaire : les piliers des semeurs du changement\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Troisi\u00e8me s\u00e9ance \u00e0 l'Universit\u00e9 Populaire : les piliers des semeurs du changement - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/","og_locale":"en_US","og_type":"article","og_title":"Troisi\u00e8me s\u00e9ance \u00e0 l'Universit\u00e9 Populaire : les piliers des semeurs du changement - Sarah Roubato","og_description":"Flash-Backs et Flash Forward sur ce s\u00e9minaire o\u00f9 les curieux et les fronceurs de sourcils sont les bienvenus !\u00a0 Prochaine s\u00e9ance le dimanche 11 f\u00e9vrier \u00e0 14h30 (et non 16h30 comme les autres fois pour les habitu\u00e9s !) Ils ont de\u00a025 \u00e0 75 ans.\u00a0Ils sont paysan, sculpteur, chanteur, boxeur, boulanger, \u00e9leveur de chevaux, coiffeur, chef [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2018-01-30T01:23:56+00:00","article_modified_time":"2018-02-14T00:45:29+00:00","og_image":[{"width":550,"height":384,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/semeur-van-gogh.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Written by":"Sarah Roubato","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#primaryimage","inLanguage":"en-US","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/semeur-van-gogh.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/01\/semeur-van-gogh.jpg","width":550,"height":384,"caption":"Le Semeur, Van Gogh."},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/","name":"Troisi\u00e8me s\u00e9ance \u00e0 l'Universit\u00e9 Populaire : les piliers des semeurs du changement - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#primaryimage"},"datePublished":"2018-01-30T01:23:56+00:00","dateModified":"2018-02-14T00:45:29+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/agenda\/seminaire3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Troisi\u00e8me s\u00e9ance \u00e0 l&#8217;Universit\u00e9 Populaire : les piliers des semeurs du changement"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":5,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/2206\/revisions"}],"predecessor-version":[{"id":2222,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/2206\/revisions\/2222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media\/2209"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media?parent=2206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/categories?post=2206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/tags?post=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}