
{"id":305,"date":"2018-01-30T08:33:00","date_gmt":"2018-01-30T07:33:00","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=305"},"modified":"2021-04-12T15:30:18","modified_gmt":"2021-04-12T13:30:18","slug":"maisons-de-retraite","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/en\/cequinousarrive\/maisons-de-retraite\/","title":{"rendered":"Maisons de retraite : comment mourront nos parents demain ?"},"content":{"rendered":"<p>\u00ab\u00a0Tiens Monsieur C.\u00a0! D\u00e9j\u00e0 r\u00e9veill\u00e9\u00a0?\u00a0\u00bb<\/p>\n<p><em>\u00c7a fait d\u00e9j\u00e0 plusieurs heures que Monsieur C. est r\u00e9veill\u00e9. La t\u00eate tourn\u00e9e vers la fen\u00eatre qui donne sur un mur. \u00c7a fait des heures qu\u2019il attend, assis au bord du lit. Il a r\u00e9ussi \u00e0\u00a0s&#8217;extirper\u00a0du matelas et \u00e0 pivoter pour s&#8217;asseoir.\u00a0Il n\u2019a pas trouv\u00e9 pas la manette pour redresser le lit. Il reste l\u00e0, en attendant. Impossible de mettre la t\u00e9l\u00e9, il est trop t\u00f4t. Il ne peut pas sonner. D&#8217;ailleurs on lui a dit d\u2019arr\u00eater de sonner pour rien. Lui tout ce qu\u2019il voudrait, c\u2019est parler un peu.<\/em><\/p>\n<p><em>Les rayons du soleil se sont mis \u00e0 \u00e9clairer les visages sur le panneau de photos \u00e0 l\u2019entr\u00e9e de la chambre. Dans toutes les chambres il y a le m\u00eame panneau en li\u00e8ge. Entre les photos on voit encore \u00a0les trous qu\u2019ont fait ceux qui \u00e9taient l\u00e0 avant. Avant que quelqu&#8217;un d\u00e9croche les photos en pleurant. Sur les photos tout le monde sourit. \u00c7a respire la joie, la sant\u00e9 et la vie. Lui aussi il a fini par mettre ses photos sur le panneau en li\u00e8ge, histoire de se rappeler qu\u2019il a \u00e9t\u00e9 un homme, un mari, un p\u00e8re, un coll\u00e8gue, un grand-p\u00e8re.<\/em><\/p>\n<p><em>Cet apr\u00e8s-midi\u00a0c\u2019est la petite qui va venir le voir. Faudrait pas qu&#8217;il se plaigne, pour d&#8217;autres personnes ne vient. Mais elle va encore lui demander s\u2019il a pass\u00e9 une bonne semaine. Elle n&#8217;a pas compris qu&#8217;ici il n\u2019y a plus de semaine, ni vraiment de jour et de nuit. Ici le temps marche avec un d\u00e9ambulateur. Il avance par petites tranches de t\u00e2ches \u00e0 accomplir\u00a0: la toilette quotidienne avec le gant, la grande exp\u00e9dition \u00e0 la douche une fois par semaine, la promenade dans le couloir, se rendre jusqu\u2019\u00e0 la salle \u00e0 manger\u2026 Bon dieu c&#8217;que \u00e7a peut \u00eatre loin une salle \u00e0 manger. Monsieur C. d\u00e9teste cette salle. Tous ces \u00a0dentiers qui mastiquent, c&#8217;est le temps qui lui fait la grimace. Pourtant parfois il rit, \u00e7a lui rappelle la caf\u00e9t\u00e9ria quand il \u00e9tait m\u00f4me, et celle de l&#8217;arm\u00e9e. Et puis \u00e7a le change du lit et de la chaise pr\u00e8s de la fen\u00eatre qui donne sur un mur.\u00a0Ce lit, c&#8217;est l\u00e0 o\u00f9 il va passer de\u00a0plus en plus de temps. C&#8217;est l\u00e0 qu&#8217;il attendra que la douleur passe, l\u00e0 qu\u2019un jour la douleur passera tout \u00e0 fait. C&#8217;est sign\u00e9. La derni\u00e8re sc\u00e8ne de sa vie se passera l\u00e0, dans\u00a0ce lit qui n&#8217;est pas le sien, qui sera celui d&#8217;un autre une semaine plus tard, dans des draps qui n&#8217;ont plus l&#8217;odeur d&#8217;un chez soi. La derni\u00e8re chose qu&#8217;il verra ce seront ces murs d&#8217;un\u00a0blanc trop propre.\u00a0<\/em>(extrait d&#8217;un manuscrit :\u00a0<em>Quelque chose tombe et ce n&#8217;est pas la nuit<\/em>)<\/p>\n<p>Combien parmi nos parents vivront cette fin de vie\u00a0? Dans notre soci\u00e9t\u00e9 est vieillissante, le nombre de retrait\u00e9s d\u00e9passera bient\u00f4t le nombre d\u2019actifs. Si le d\u00e9bat sur la fin de vie est souvent relanc\u00e9, celui sur l\u2019existence m\u00eame des maisons de retraite ne semble pas poser probl\u00e8me. Pourtant les maisons de retraite sont un choix de soci\u00e9t\u00e9, qui r\u00e9pond \u00e0 des\u00a0normes anthropologiques.<\/p>\n<p>Lorsque les conditions dans lesquelles vivent beaucoup de personnes plac\u00e9es en maison de retraite surgissent dans l&#8217;actualit\u00e9, le d\u00e9bat public se tourne vers comment offrir de meilleures conditions de vie, comment mieux placer les retrait\u00e9s. Mais la question culturelle de fond n&#8217;est pas abord\u00e9e.<\/p>\n<p><em><strong><a href=\"http:\/\/paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1778 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/10\/Capture-d\u2019e\u0301cran-2017-10-28-a\u0300-01.23.41.png\" alt=\"Capture d\u2019e\u0301cran 2017-10-28 a\u0300 01.23.41\" width=\"588\" height=\"247\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/10\/Capture-d\u2019e\u0301cran-2017-10-28-a\u0300-01.23.41.png 726w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/10\/Capture-d\u2019e\u0301cran-2017-10-28-a\u0300-01.23.41-150x63.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/10\/Capture-d\u2019e\u0301cran-2017-10-28-a\u0300-01.23.41-300x126.png 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/10\/Capture-d\u2019e\u0301cran-2017-10-28-a\u0300-01.23.41-600x252.png 600w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/a><\/strong><\/em><\/p>\n<p><strong>Nos parents\u00a0: les futurs improductifs<br \/>\n<\/strong><\/p>\n<p>&#8220;Je ne sers plus \u00e0 rien&#8221;, &#8220;Je ne veux plus emb\u00eater personne&#8221;. Le taux de suicide chez les 75\/84 ans est le seul qui augmente en France.<a href=\"#_ftn1\" name=\"_ftnref\">[1]<\/a><\/p>\n<p>Dans nos soci\u00e9t\u00e9s modernes, la norme familiale est la famille nucl\u00e9aire &#8211; p\u00e8re, m\u00e8re, enfant. L\u2019\u00e9clatement familial, les familles recompos\u00e9es, la mobilit\u00e9 des m\u00e9nages \u00e9loigne beaucoup d&#8217;enfants de leurs parents.\u00a0Les maisons de retraite apparaissent donc comme\u00a0le seul choix possible, mais elles r\u00e9pondent en fait d&#8217;avantage \u00e0 des normes culturelles encourageant l&#8217;isolement des g\u00e9n\u00e9rations, l&#8217;enfermement, le culte de la vie et la primaut\u00e9 de la sant\u00e9 du corps sur la sant\u00e9 \u00e9motionnelle. Mais surtout, la notion d&#8217;utilit\u00e9 de l&#8217;individu dans une soci\u00e9t\u00e9 productiviste.<\/p>\n<p>Dans une soci\u00e9t\u00e9 o\u00f9 le but assign\u00e9 \u00e0 l&#8217;individu est de produire de la valeur \u00e9conomique, le fait qu&#8217;une personne puisse se mettre \u00e0 travailler \u00e0 mi temps pour s&#8217;occuper de ses parents n&#8217;est pas envisageable. On accorde des cong\u00e9s maternit\u00e9, mais pas de cong\u00e9 filial.<\/p>\n<p>Les improductifs sont rel\u00e9gu\u00e9s \u00e0 des milieux d\u2019enfermement\u00a0: l\u2019\u00e9cole, les h\u00f4pitaux psychiatriques, les prisons, les foyers pour personnes \u00e0 la rue, les maisons de retraite. Bien s\u00fbr certains sont l\u00e0 pour apprendre, d\u2019autres pour payer une dette envers la soci\u00e9t\u00e9, d\u2019autres pour qu\u2019on prenne soin d\u2019eux. Milieu d\u2019enfermement n\u2019a pas ici une connotation p\u00e9jorative\u00a0: c\u2019est un fait, nous enfermons ceux que nous voulons punir, former ou aider. Pourtant\u00a0il n\u2019est pas universel de consid\u00e9rer que l\u2019apprentissage, la punition ou l\u2019aide passent n\u00e9cessairement par un isolement. Dans nombre de soci\u00e9t\u00e9s, l\u2019apprentissage des enfants se fait par leur participation \u00e0 la vie communautaire, et notamment\u00a0par le soin qu\u2019ils doivent prendre des anciens.<\/p>\n<p>Chez nous, les personnes \u00e2g\u00e9es sont consid\u00e9r\u00e9es comme une classe \u00e0 part avec, comme les enfants, qui ont leur propre nourriture, leurs s\u00e9ries t\u00e9l\u00e9, leurs amusements, ou leur niveau de langage qui nous am\u00e8ne souvent \u00e0 les infantiliser. Dans d&#8217;autres soci\u00e9t\u00e9s pourtant, l&#8217;ancien\u00a0est consid\u00e9r\u00e9(e) comme un tr\u00e9sor humain essentiel \u00e0 la transmission vers les nouvelles g\u00e9n\u00e9rations.<\/p>\n<p><em>Mais comment peut-on faire autrement\u00a0<\/em>?\u00a0Comment restituer la dignit\u00e9 et la place des personnes \u00e2g\u00e9es dans notre soci\u00e9t\u00e9 \u00a0? C&#8217;est que derri\u00e8re cette question, c&#8217;est un mod\u00e8le entier qui est remis en question. L&#8217;argument \u00e9non\u00e7ant que nous n&#8217;avons\u00a0<em>pas le temps<\/em> de nous occuper de nos parents\u00a0et pas d&#8217;argent\u00a0pour employer du personnel sp\u00e9cialis\u00e9, repose sur des rythmes de vie que nous nous ne remettons jamais en question. Impossible d&#8217;imaginer par exemple, qu&#8217;une partie d&#8217;un service civique obligatoire se ferait dans les maisons de retraite, d&#8217;imaginer pour chaque employ\u00e9 au sein d&#8217;une entreprise quelques jours de travail par mois dans une maison de retraite, ou encore d&#8217;\u00e9tablir des \u00e9changes de service\u00a0avec des \u00e9tudiants en qu\u00eate de logement.<\/p>\n<p>Dans nos soci\u00e9t\u00e9s o\u00f9 l\u2019unit\u00e9 de mesure est l\u2019individu \u00e9conomiquement productif, les personnes \u00e2g\u00e9es redeviennent des enfants, mais des enfants qui marchent \u00e0 reculons. Pass\u00e9 un certain \u00e2ge, nul besoin d\u2019avoir une maladie d\u00e9g\u00e9n\u00e9rative pour se faire infantiliser. D\u00e8s lors, c\u2019est \u00e0 nous qu\u2019incombe la responsabilit\u00e9 de mettre nos parents en maison de retraite. Bien s\u00fbr ils sont consentants, ils suivent nos conseils, puisqu\u2019il est entendu que nous savons mieux ce qui est bon pour eux. Nos d\u00e9cisions sont difficiles \u00e0 prendre, car nous sommes pi\u00e9g\u00e9s dans un syst\u00e8me o\u00f9 \u00e7a ne se fait pas de demander \u00e0 la voisine \u00ab\u00a0Je sors faire des courses, peux-tu t\u2019occuper de ma m\u00e8re pendant une heure\u00a0?\u00a0\u00bb, et la voisine de le faire, sans \u00eatre r\u00e9tribu\u00e9e, parce qu\u2019elle se sent concern\u00e9e par toute personne \u00e2g\u00e9e qui a contribu\u00e9 \u00e0 cr\u00e9er la soci\u00e9t\u00e9 o\u00f9 elle vit. \u00c7a ne se fait pas de dire \u00e0 son enfant de s\u2019occuper de son grand-p\u00e8re en rentrant de l\u2019\u00e9cole, un enfant \u00e7a doit rester dans son monde.<\/p>\n<p><strong>La mort est un verbe<\/strong><\/p>\n<p>Derri\u00e8re notre relation aux personnes \u00e2g\u00e9es, c&#8217;est aussi notre rapport \u00e0 la mort qui est en question.\u00a0Objet de spectacle\u00a0dans les films, les m\u00e9dias et les jeux vid\u00e9os, mais absente du r\u00e9el,\u00a0elle n&#8217;a plus d&#8217;odeur, plus de temp\u00e9rature, plus de rythme. Nous ne savons plus \u00e0 quoi ressemble la mort d&#8217;un animal que nous allons manger, nous n&#8217;assistons plus \u00e0 la mort de notre personnes \u00e2g\u00e9es Les personnes qui vont mourir sont mises \u00e0 l&#8217;\u00e9cart.<\/p>\n<p>Dans un monde o\u00f9 les fruits n\u2019ont plus de saison, o\u00f9 nous sommes enti\u00e8rement coup\u00e9s des cycles naturels, nous nous sommes aussi coup\u00e9s de la mort. Au point de ne pas pouvoir en prononcer le nom. Nous disons <em>partir, dispara\u00eetre, c&#8217;est fini.\u00a0<\/em>\u00a0\u00c0 l&#8217;\u00e9chelle des soci\u00e9t\u00e9s, nous vivons comme des immortels, dans une logique de croissance perp\u00e9tuelle. \u00c0 l&#8217;\u00e9chelle individuelle, quand la mort approche, nous ne savons plus comment l&#8217;accueillir. Pourtant la mort est un verbe,\u00a0le dernier de notre vie.<\/p>\n<p>Nous nous occupons plus de la mort que de mourir. Nous\u00a0la ritualisons \u00e0 l&#8217;enterrement,\u00a0une fois qu&#8217;elle est l\u00e0, pour ceux qui restent. Mais pas pour celui qui meurt. La mort n&#8217;est souvent \u00e9voqu\u00e9e que pour la repousser\u00a0<em>ne dites pas \u00e7a, arr\u00eatez de parler comme \u00e7a<\/em>, ou bien \u00e9lud\u00e9e dans les blagues lors des visites familiales.\u00a0Qui songerait \u00e0\u00a0organiser\u00a0des fun\u00e9railles\u00a0du vivant de la personne o\u00f9, pendant plusieurs jours, les proches viendraient lui dire ce qu&#8217;elle a \u00e9t\u00e9 pour eux, et lui liraient\u00a0ces mots qui se disent devant le cercueil ? Et permettre \u00e0 cette personne d&#8217;acqu\u00e9rir un statut de transmission, en se racontant ?<\/p>\n<p>La plupart des d\u00e9c\u00e8s en maison de retraite ont lieu la nuit ou t\u00f4t le matin, c\u2019est-\u00e0-dire au moment o\u00f9 les angoisses sont les plus pr\u00e9sentes. Par quel \u00e9trange proc\u00e9d\u00e9 sommes-nous convaincus que des personnes qui arrivent au bout du chemin souhaitent qu\u2019on les laisse tranquilles, baign\u00e9s d\u2019ennui, dans une chambre qui ressemble \u00e0 toutes les autres, avec une couche au cul et une sonnette au bras, et que la t\u00e9l\u00e9 est leur dernier plaisir ? Qui nous dit qu\u2019ils ne voudraient pas s\u2019\u00e9puiser encore un peu pour voir de nouveaux visages, des paysages apaisants, rire aux \u00e9clats, d\u00e9couvrir encore des choses qu\u2019ils n\u2019ont jamais vues ? Comment en est-on arriv\u00e9 \u00e0 emp\u00eacher les vieux de vivre sous pr\u00e9texte de vouloir les maintenir en vie\u00a0?\u00a0Il ne tenait qu\u2019\u00e0 nos parents de nous avoir mis en pension quand ils peinaient \u00e0 subvenir \u00e0 leurs besoins. Il serait peut-\u00eatre urgence de r\u00e9interroger la place pour ceux qui, pour le meilleur ou le pire, nous ont construits.<\/p>\n<p><a href=\"#_ftnref\" name=\"_ftn1\">[1]<\/a> http:\/\/www.infosuicide.org\/reperes\/epidemiologie\/<\/p>\n<p><a href=\"https:\/\/lanagedelourse.fr\/Sarah_Roubato01.html\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-2348 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg\" alt=\"couv Nage de l'ourse\" width=\"201\" height=\"310\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg 662w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-97x150.jpg 97w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-194x300.jpg 194w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-600x928.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse.jpg 779w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/p>\n<p><em>Trouve le verbe de ta vie\u00a0<\/em>ed La Nage de l&#8217;Ourse. Cliquez\u00a0<strong>ici\u00a0<\/strong>pour en savoir plus. Cliquez sur le livre pour le commander chez l&#8217;\u00e9diteur.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><a href=\"http:\/\/www.michel-lafon.fr\/livre\/1687-Lettres_a_ma_generation.html\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1091  alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-205x300.jpg\" alt=\"livre sarah\" width=\"158\" height=\"230\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-205x300.jpg 205w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-103x150.jpg 103w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah.jpg 341w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a>\u00a0 \u00a0Lettres \u00e0 ma g\u00e9n\u00e9ration\u00a0<\/em>ed Michel Lafon.\u00a0Cliquez\u00a0<strong><a href=\"https:\/\/mrmondialisation.org\/sarah-roubato-lettres-a-ma-generation\/\" target=\"_blank\" rel=\"noopener noreferrer\">ici\u00a0<\/a><\/strong>pour en savoir plus et lire des extraits. Cliquez sur le livre pour le commander chez l&#8217;\u00e9diteur.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 116px; left: 226px;\">Enregistrer<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer;\">Enregistrer<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Tiens Monsieur C.\u00a0! D\u00e9j\u00e0 r\u00e9veill\u00e9\u00a0?\u00a0\u00bb \u00c7a fait d\u00e9j\u00e0 plusieurs heures que Monsieur C. est r\u00e9veill\u00e9. La t\u00eate tourn\u00e9e vers la fen\u00eatre qui donne sur un mur. \u00c7a fait des heures qu\u2019il attend, assis au bord du lit. Il a r\u00e9ussi \u00e0\u00a0s&#8217;extirper\u00a0du matelas et \u00e0 pivoter pour s&#8217;asseoir.\u00a0Il n\u2019a pas trouv\u00e9 pas la manette pour redresser [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[27,477,485],"class_list":["post-305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive","tag-consommation","tag-generations","tag-original-29-oct-2014"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maisons de retraite : comment mourront nos parents demain ? - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maisons de retraite : comment mourront nos parents demain ? - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0Tiens Monsieur C.\u00a0! D\u00e9j\u00e0 r\u00e9veill\u00e9\u00a0?\u00a0\u00bb \u00c7a fait d\u00e9j\u00e0 plusieurs heures que Monsieur C. est r\u00e9veill\u00e9. La t\u00eate tourn\u00e9e vers la fen\u00eatre qui donne sur un mur. \u00c7a fait des heures qu\u2019il attend, assis au bord du lit. Il a r\u00e9ussi \u00e0\u00a0s&#8217;extirper\u00a0du matelas et \u00e0 pivoter pour s&#8217;asseoir.\u00a0Il n\u2019a pas trouv\u00e9 pas la manette pour redresser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-30T07:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-12T13:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2014\/10\/mains.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2014\/10\/mains.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2014\/10\/mains.jpg\",\"width\":300,\"height\":225},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/\",\"name\":\"Maisons de retraite : comment mourront nos parents demain ? - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#primaryimage\"},\"datePublished\":\"2018-01-30T07:33:00+00:00\",\"dateModified\":\"2021-04-12T13:30:18+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maisons de retraite : comment mourront nos parents demain ?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maisons de retraite : comment mourront nos parents demain ? - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/","og_locale":"en_US","og_type":"article","og_title":"Maisons de retraite : comment mourront nos parents demain ? - Sarah Roubato","og_description":"\u00ab\u00a0Tiens Monsieur C.\u00a0! D\u00e9j\u00e0 r\u00e9veill\u00e9\u00a0?\u00a0\u00bb \u00c7a fait d\u00e9j\u00e0 plusieurs heures que Monsieur C. est r\u00e9veill\u00e9. La t\u00eate tourn\u00e9e vers la fen\u00eatre qui donne sur un mur. \u00c7a fait des heures qu\u2019il attend, assis au bord du lit. Il a r\u00e9ussi \u00e0\u00a0s&#8217;extirper\u00a0du matelas et \u00e0 pivoter pour s&#8217;asseoir.\u00a0Il n\u2019a pas trouv\u00e9 pas la manette pour redresser [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2018-01-30T07:33:00+00:00","article_modified_time":"2021-04-12T13:30:18+00:00","og_image":[{"width":300,"height":225,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2014\/10\/mains.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Written by":"Sarah Roubato","Est. reading time":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#primaryimage","inLanguage":"en-US","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2014\/10\/mains.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2014\/10\/mains.jpg","width":300,"height":225},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/","name":"Maisons de retraite : comment mourront nos parents demain ? - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#primaryimage"},"datePublished":"2018-01-30T07:33:00+00:00","dateModified":"2021-04-12T13:30:18+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/maisons-de-retraite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Maisons de retraite : comment mourront nos parents demain ?"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":18,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/305\/revisions"}],"predecessor-version":[{"id":5200,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/305\/revisions\/5200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media\/1089"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media?parent=305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/categories?post=305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/tags?post=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}