
{"id":3269,"date":"2019-04-24T23:45:43","date_gmt":"2019-04-24T21:45:43","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=3269"},"modified":"2021-04-15T08:51:34","modified_gmt":"2021-04-15T06:51:34","slug":"amours","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/en\/cequinousarrive\/amours\/","title":{"rendered":"La monoculture de l&#8217;amour"},"content":{"rendered":"<p><em>J\u2019ai l\u2019\u00e2me lourde encore d\u2019amour inexprim\u00e9e.<\/em><\/p>\n<p><em>Cyrano de Bergerac<\/em>, Edmond Rostand<\/p>\n<p>&nbsp;<\/p>\n<p>C\u2019est le th\u00e8me \u00e9ternel des chansons et des films. Celui dont personne ne semble se lasser. Celui auquel tous les films biographiques ram\u00e8nent la vie des Ray Charles, Frida Kahlo, Edith Piaf, etc. Celui que les chansons de rue, les chansons de concert, les chansons de radio, les chansons \u00e0 la mode et les chansons mal vieillies, les clips des stars et les vid\u00e9os d\u2019inconnus dans leurs chambres, m\u00e2chent et rab\u00e2chent. L\u2019Amour. L\u2019amour du couple, l\u2019amour des amants, l\u2019amour des amoureux.<\/p>\n<p>Il serait mals\u00e9ant de s\u2019en plaindre. Malvenu de demander aux artistes\u00a0: n\u2019avez-vous donc rien d\u2019autre \u00e0 raconter\u00a0? Ne trouvez-vous pas que notre temps est assez riche en choses inexprim\u00e9es, pour que chacun, en creusant le sol, y trouve plus de tr\u00e9sors qu\u2019il ne pourra exprimer dans sa vie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3226 size-full alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/Capture-d&rsquo;e\u0301cran-2019-04-03-a\u0300-01.32.34.png\" alt=\"\" width=\"706\" height=\"334\" \/><\/p>\n<form action=\"https:\/\/www.paypal.com\/cgi-bin\/webscr\" method=\"post\" target=\"_top\"><input name=\"cmd\" type=\"hidden\" value=\"_s-xclick\" \/><br \/>\n<input name=\"hosted_button_id\" type=\"hidden\" value=\"EJQ4SMFNRV5JL\" \/><br \/>\n<input title=\"PayPal - The safer, easier way to pay online!\" alt=\"Donate with PayPal button\" name=\"submit\" src=\"https:\/\/www.paypalobjects.com\/fr_FR\/FR\/i\/btn\/btn_donateCC_LG.gif\" type=\"image\" \/><a href=\"https:\/\/fr.tipeee.com\/sarahroubato\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3465\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/06\/sarah-tipeee3-1024x737.png\" alt=\"\" width=\"304\" height=\"219\" \/><\/a><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.paypal.com\/fr_FR\/i\/scr\/pixel.gif\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/>La relation d\u2019un ma\u00eetre \u00e0 son \u00e9l\u00e8ve, d\u2019un coach \u00e0 son apprenti, n\u2019est-ce pas l\u00e0 de l\u2019amour ? Quand <em>celui qui est au-devant<\/em> \u2013 c\u2019est ainsi que se dit <em>professeur <\/em>en japonais et qu\u2019il se pratique dans les arts martiaux \u2013 voit les potentiels de l\u2019apprenti, tout ce qui est encore vert, maladroit, et qu\u2019il va canaliser, orienter, aider \u00e0 s\u2019\u00e9panouir. L\u2019\u00e9l\u00e8ve qui se cherche, se livre, r\u00e9siste et explose devant celui en qui il a une totale confiance. Gr\u00e2ce \u00e0 lui, le ma\u00eetre int\u00e8gre la cha\u00eene de ceux qui passent. N\u2019est-ce pas l\u00e0 de l\u2019amour ?<\/p>\n<figure id=\"attachment_3280\" aria-describedby=\"caption-attachment-3280\" style=\"width: 390px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3280\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/Capture-d&rsquo;e\u0301cran-2019-04-24-a\u0300-23.41.40-1024x640.png\" alt=\"\" width=\"390\" height=\"244\" \/><figcaption id=\"caption-attachment-3280\" class=\"wp-caption-text\">Le ma\u00eetre et son \u00e9l\u00e8ve, &#8220;Entr\u00e9e des artistes&#8221;, 1938<\/figcaption><\/figure>\n<p>Quand une jeune fille aide une vieille femme \u00e0 monter ses paquets, \u00e0 atteindre le haut du placard, quand elle s\u2019assoit pr\u00e8s d\u2019elle et l\u2019\u00e9coute parler d\u2019un autre temps, quand elle accueille l\u2019enfant qui rit au fond des yeux rid\u00e9s. Quand l\u2019a\u00een\u00e9e retrouve quelque chose de la femme qu\u2019elle a \u00e9t\u00e9 dans la fra\u00eecheur de la jeune fille. Quand, entre ces deux l\u00e0 qui ne sont ni petite-fille ni grand-m\u00e8re, le temps devient une caresse qui berce deux \u00e2mes soudainement s\u0153urs. N\u2019est-ce pas l\u00e0 de l\u2019amour ?<\/p>\n<p>Quand un commer\u00e7ant du coin devient le port o\u00f9 l\u2019on fait halte, quand on s\u2019attarde \u00e0 son comptoir pour entendre des bribes de sa vie. Qu\u2019on y boit le r\u00e9cit de la ville qui change, des temps difficiles o\u00f9 il faut tenir. Quand le commer\u00e7ant guette le passage de ce plus-que-client fid\u00e8le comme un rayon de soleil dans sa journ\u00e9e embrum\u00e9e. Quand il prend sa retraite et que soudain, on se rend compte qu\u2019il manquera quelque chose sans lui, car il faisait partie de notre paysage, comme le vieux ch\u00eane \u00e0 la fen\u00eatre, comme la tour de Notre-Dame derri\u00e8re la baie vitr\u00e9e de certains caf\u00e9s. N\u2019est-ce pas quand m\u00eame de l\u2019amour ?<\/p>\n<figure id=\"attachment_3270\" aria-describedby=\"caption-attachment-3270\" style=\"width: 439px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3270\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/le-vieil-homme-et-lenfant.jpg\" alt=\"\" width=\"439\" height=\"339\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/le-vieil-homme-et-lenfant.jpg 799w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/le-vieil-homme-et-lenfant-150x116.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/le-vieil-homme-et-lenfant-300x232.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/le-vieil-homme-et-lenfant-768x593.jpg 768w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/le-vieil-homme-et-lenfant-600x463.jpg 600w\" sizes=\"auto, (max-width: 439px) 100vw, 439px\" \/><figcaption id=\"caption-attachment-3270\" class=\"wp-caption-text\">&#8220;Le vieil homme et l&#8217;enfant&#8221; 1966<\/figcaption><\/figure>\n<p>Quand on voit un enfant grandir sans \u00eatre de sa famille, que l\u2019on devient un pilier dans sa vie. Un complice, un cadre, un r\u00e9f\u00e9rent. Recueillir ses petits pas incertains quand il est encore b\u00e9b\u00e9, ses rires impudiques quand il est petit enfant, ses r\u00e9voltes quand il est adolescent. Broder avec lui un bout d\u2019imaginaire, s\u2019autoriser le d\u00e9lire, r\u00e9apprendre \u00e0 s\u2019\u00e9merveiller, se r\u00e9volter de la connerie des adultes. N\u2019est-ce pas l\u00e0 aussi de l\u2019amour ?<\/p>\n<p>Avoir un voisin chez qui l\u2019on entre sans frapper, pour emprunter un outil ou prendre un conseil. Quelqu\u2019un avec qui partager la connaissance d\u2019un flanc de montagne, d\u2019un coteau, d\u2019un quartier. Qui nous permet de sortir la deuxi\u00e8me assiette et d\u2019oser cuisiner ces plats qui ne se mangent jamais seuls. Celui \u00e0 qui l\u2019on pense quand on voyage et qu\u2019on se dit qu\u2019on ram\u00e8nera une bouteille. Qui nous laisse tranquille quand on a besoin d\u2019\u00eatre seul et qui est l\u00e0 quand on a besoin de ne pas se sentir seul. N\u2019est-ce pas l\u00e0 de l\u2019amour ?<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3275\" aria-describedby=\"caption-attachment-3275\" style=\"width: 356px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3275\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1.jpg\" alt=\"\" width=\"356\" height=\"237\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1.jpg 900w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-150x100.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-300x200.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-768x512.jpg 768w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-600x400.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-440x293.jpg 440w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-650x433.jpg 650w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillesurlepont1-886x590.jpg 886w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><figcaption id=\"caption-attachment-3275\" class=\"wp-caption-text\">&#8220;La fille sur le pont&#8221;, 1999<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Et le complice de sc\u00e8ne ou d\u2019aventure, celui avec qui on a fr\u00f4l\u00e9 l\u2019\u00e9ternit\u00e9, compagnon de plong\u00e9e, de vol, d\u2019escalade, de spectacle. Celui qui nous comprend sans mot, que l\u2019on d\u00e9sire sans sexe, qu\u2019on entend d\u2019un geste et qu\u2019on touche du bout des yeux. Celui qui n\u2019a pas eu besoin de cl\u00e9 pour visiter notre \u00e2me. Si cela n\u2019est pas de l\u2019amour\u2026<\/p>\n<p>Et ceux dont on fait des monuments culturels, dont les mots, les musiques et les \u0153uvres dialoguent avec nous dans les moments les plus intenses de nos vie, et qui bien souvent, nous la sauvent. Eux qui vivent \u00e0 travers nous en nous et tout autour de nous. Ne les aimons-nous pas\u00a0?<\/p>\n<p>Mais alors je devrais aussi parler de l\u2019amour pour son pays, pour un coin de terre, pour un quartier, pour un arbre, pour un animal. L\u2019amour pour son instrument de musique ou pour une vieille maison qui nous a vu grandir.<\/p>\n<figure id=\"attachment_3271\" aria-describedby=\"caption-attachment-3271\" style=\"width: 436px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3271\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/belle-equipe.jpg\" alt=\"\" width=\"436\" height=\"269\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/belle-equipe.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/belle-equipe-150x93.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/belle-equipe-300x185.jpg 300w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/><figcaption id=\"caption-attachment-3271\" class=\"wp-caption-text\">&#8220;La belle \u00e9quipe&#8221; 1936<\/figcaption><\/figure>\n<p>Et si je devais parler ici de l\u2019amiti\u00e9 je dirais qu\u2019elle est une des plus belles formes de l\u2019amour, et qu\u2019elle m\u00e9riterait bien aussi qu\u2019on red\u00e9couvre sa richesse. Car elle sait exister bien au-del\u00e0 de ceux qui partagent sorties activit\u00e9s et voyages, bien au-del\u00e0 de ceux qui se ressemblent socialement, qui fr\u00e9quent les m\u00eames lieux et aiment aller voir les m\u00eames films. Bien au-del\u00e0 aussi de ceux qui ont des photos en commun. Ne pourrions-nous entretenir une magnifique amiti\u00e9 avec quelqu\u2019un qui pourrait \u00eatre notre grand-p\u00e8re, avec un enfant qui pourrait \u00eatre notre petit fr\u00e8re, avec quelqu\u2019un qui soit \u00e9loign\u00e9 de tout ce que nous connaissons\u00a0? Pourrions-nous enfin passer des soir\u00e9es enti\u00e8res avec un homme si on est une femme, avec une femme si on est un homme, sans se demander si cela ne sera pas \u00ab\u00a0mal interpr\u00e9t\u00e9\u00a0\u00bb, surtout si l&#8217;autre est en couple.\u00a0<em>Mal interpr\u00e9t\u00e9\u2026 <\/em>quelle bien triste formule pour l\u2019envie d\u2019une \u00e9paule o\u00f9 se blottir, d\u2019un rire o\u00f9 se r\u00e9chauffer, d\u2019une paroi o\u00f9 l\u2019on puisse entendre son propre cri. Quelqu\u2019un qui nous comprend sans avoir rien \u00e0 prouver.<\/p>\n<p>Les temps sont bien durs pour qui cherche ces formes d\u2019amour. Comme des vari\u00e9t\u00e9s anciennes de l\u00e9gumes et de fruits, ou comme des coupes de pantalon qui d\u00e9cid\u00e9ment ne se font plus. Pour qui n\u2019est ni de la famille, ni du cercle d\u2019amis du quotidien, ni l\u2019amoureux, il n\u2019y a pas de place. \u00c0 croire que nous avons m\u00eame r\u00e9ussi \u00e0 cultiver la monoculture de l\u2019amour.<\/p>\n<p><input title=\"PayPal - The safer, easier way to pay online!\" alt=\"Donate with PayPal button\" name=\"submit\" src=\"https:\/\/www.paypalobjects.com\/fr_FR\/FR\/i\/btn\/btn_donateCC_LG.gif\" type=\"image\" \/><\/p>\n<p>Sarah Roubato a publi\u00e9 :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3000 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-617x1024.jpg\" alt=\"\" width=\"162\" height=\"269\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-617x1024.jpg 617w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-90x150.jpg 90w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-181x300.jpg 181w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-768x1275.jpg 768w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-600x996.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd.jpg 1309w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/p>\n<p><em style=\"line-height: 1.5;\">\u00a0Partout en France et ailleurs, ils sont sur le point d\u2019avoir trente ans. Une foule d\u2019anonymes qui cherchent \u00e0 habiter le monde ou \u00e0 le fuir, \u00e0 dessiner leurs r\u00eaves ou \u00e0 s\u2019en d\u00e9tourner. Au c\u0153ur du tumulte, ils s\u2019interrogent, se font violence et ce sont leurs voix que l\u2019on entend se d\u00e9ployer\u00a0<\/em><\/p>\n<p>Cliquez<a href=\"http:\/\/publie.net\/livre\/30-ans-heure-sarah-roubato\/\"><strong> ici<\/strong><\/a> pour le commander chez l&#8217;\u00e9diteur<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/oeuvres\/trouveleverbesonore\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2348 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg\" alt=\"\" width=\"166\" height=\"257\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg 662w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-97x150.jpg 97w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-194x300.jpg 194w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-600x928.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse.jpg 779w\" sizes=\"auto, (max-width: 166px) 100vw, 166px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p class=\"small\"><em>Une jeune femme \u00e9crit \u00e0 un adolescent et lui propose d\u2019envisager son avenir avec un autre regard que celui qu\u2019on lui a appris, pour faire face \u00e0 un monde qui change et qu\u2019il va devoir r\u00e9inventer. Une lettre qui r\u00e9sonne \u00e0 tout \u00e2ge pour ceux qui ont eu envie de quitter les chemins tout trac\u00e9s et \u00e0 qui on a dit que c\u2019\u00e9tait impossible.<\/em><\/p>\n<p>Cliquez\u00a0<strong><a href=\"https:\/\/dev.sarahroubato.com\/acheter\/trouveleverbe\/\">ici\u00a0<\/a><\/strong>pour commander le livre \u00a0ou commandez-le dans n&#8217;importe quelle librairie.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.michel-lafon.fr\/livre\/1687-Lettres_a_ma_generation.html\"><em><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1091 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-103x150.jpg\" alt=\"livre sarah\" width=\"129\" height=\"188\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-103x150.jpg 103w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-205x300.jpg 205w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah.jpg 341w\" sizes=\"auto, (max-width: 129px) 100vw, 129px\" \/><\/em><\/a><\/p>\n<p><em>Un recueil de lettres adress\u00e9es \u00e0 toutes celles et ceux, m\u00eame s&#8217;ils ne peuvent pas r\u00e9pondre, qui peuplent la solitude d&#8217;une jeune femme \u00e9prise de la beaut\u00e9 du monde. Comment la dire, comment la pr\u00e9server, comment y participer, alors que des forces contraires \u2013 l&#8217;hyperconsommation, les renoncements politiques, l&#8217;ambivalence du progr\u00e8s technologique \u2013 nous isolent toujours plus les uns des autres ?<\/em><\/p>\n<p>Cliquez <strong><a href=\"https:\/\/mrmondialisation.org\/sarah-roubato-lettres-a-ma-generation\/\" target=\"_blank\" rel=\"noopener noreferrer\">ici\u00a0<\/a><\/strong>pour en savoir plus et lire des extraits. Cliquez sur le livre pour le commander directement chez l&#8217;\u00e9diteur ou commandez-le dans n&#8217;importe quelle librairie<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3000 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-617x1024.jpg\" alt=\"\" width=\"223\" height=\"370\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-617x1024.jpg 617w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-90x150.jpg 90w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-181x300.jpg 181w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-768x1275.jpg 768w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd-600x996.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/12\/9782371775497_COV-1e-sd.jpg 1309w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/><\/p>\n<div style=\"position: relative; height: 0; padding-bottom: 56.25%;\"><iframe loading=\"lazy\" style=\"position: absolute; width: 100%; height: 100%; left: 0;\" src=\"https:\/\/www.youtube.com\/embed\/GhbnrEuAcA0?ecver=2\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<\/form>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>J\u2019ai l\u2019\u00e2me lourde encore d\u2019amour inexprim\u00e9e. Cyrano de Bergerac, Edmond Rostand &nbsp; C\u2019est le th\u00e8me \u00e9ternel des chansons et des films. Celui dont personne ne semble se lasser. Celui auquel tous les films biographiques ram\u00e8nent la vie des Ray Charles, Frida Kahlo, Edith Piaf, etc. Celui que les chansons de rue, les chansons de concert, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-3269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La monoculture de l&#039;amour - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La monoculture de l&#039;amour - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"J\u2019ai l\u2019\u00e2me lourde encore d\u2019amour inexprim\u00e9e. Cyrano de Bergerac, Edmond Rostand &nbsp; C\u2019est le th\u00e8me \u00e9ternel des chansons et des films. Celui dont personne ne semble se lasser. Celui auquel tous les films biographiques ram\u00e8nent la vie des Ray Charles, Frida Kahlo, Edith Piaf, etc. Celui que les chansons de rue, les chansons de concert, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-24T21:45:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T06:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillepont024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"459\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillepont024.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillepont024.jpg\",\"width\":459,\"height\":486},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/\",\"name\":\"La monoculture de l'amour - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#primaryimage\"},\"datePublished\":\"2019-04-24T21:45:43+00:00\",\"dateModified\":\"2021-04-15T06:51:34+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La monoculture de l&#8217;amour\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La monoculture de l'amour - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/","og_locale":"en_US","og_type":"article","og_title":"La monoculture de l'amour - Sarah Roubato","og_description":"J\u2019ai l\u2019\u00e2me lourde encore d\u2019amour inexprim\u00e9e. Cyrano de Bergerac, Edmond Rostand &nbsp; C\u2019est le th\u00e8me \u00e9ternel des chansons et des films. Celui dont personne ne semble se lasser. Celui auquel tous les films biographiques ram\u00e8nent la vie des Ray Charles, Frida Kahlo, Edith Piaf, etc. Celui que les chansons de rue, les chansons de concert, [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2019-04-24T21:45:43+00:00","article_modified_time":"2021-04-15T06:51:34+00:00","og_image":[{"width":459,"height":486,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillepont024.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Written by":"Sarah Roubato","Est. reading time":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#primaryimage","inLanguage":"en-US","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillepont024.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2019\/04\/fillepont024.jpg","width":459,"height":486},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/","name":"La monoculture de l'amour - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#primaryimage"},"datePublished":"2019-04-24T21:45:43+00:00","dateModified":"2021-04-15T06:51:34+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/amours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"La monoculture de l&#8217;amour"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/3269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/comments?post=3269"}],"version-history":[{"count":21,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/3269\/revisions"}],"predecessor-version":[{"id":5270,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/3269\/revisions\/5270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media\/3278"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media?parent=3269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/categories?post=3269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/tags?post=3269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}