
{"id":349,"date":"2014-11-01T23:27:47","date_gmt":"2014-11-01T23:27:47","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=349"},"modified":"2020-05-18T17:17:49","modified_gmt":"2020-05-18T15:17:49","slug":"ayrad-ou-les-necessaires-choix","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/","title":{"rendered":"Ayrad ou les n\u00e9cessaires choix"},"content":{"rendered":"<p><a href=\"https:\/\/www.paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1026 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg\" alt=\"mafalda9\" width=\"300\" height=\"214\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-150x107.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9.jpg 378w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Mardi dernier le groupe Ayrad pr\u00e9sentait son premier album au Cabaret du Mile End, dans le cadre du Festival du Monde Arabe. L\u2019\u00e9motion et l\u2019enthousiasme \u00e9taient au rendez-vous autour de ce groupe qui puise dans diff\u00e9rents styles musicaux d\u2019Afrique du nord avec de l\u00e9g\u00e8res influences andalouses et des instruments modernes (clavier, basse). Autour de Ayrad Hamza Abouabdelmajid, cinq musiciens\u00a0: Annick Beauvais au hautbois, Gabou Lajoie \u00e0 la basse, Bettil \u00e0 la batterie, Anit Ghosh au violon et Kattam aux percussions.<\/p>\n<p>Les musiciens ont tour \u00e0 tour pris la parole pour remercier les contributeurs de cette aventure qu\u2019est la cr\u00e9ation d\u2019un album. Un album, c\u2019est une succession de choix que l\u2019on fait\u00a0: choix des chansons, de l\u2019ordre, du lieu o\u00f9 enregistrer, choix du son. Sur sc\u00e8ne, ce sont aussi des choix esth\u00e9tiques, linguistiques qui vont tracer l\u2019avenir d\u2019un groupe et lui permettre de se distinguer et de durer.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Le choix sc\u00e9nique\u00a0: d\u00e9calages<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Le groupe a commenc\u00e9 par envoyer du fort. Solos du hautbois puis r\u00e9ponse du violon, chacun \u00e9clair\u00e9 tour \u00e0 tour, puis d\u00e9collage et encha\u00eenement de pi\u00e8ces bien rythm\u00e9es. Pourtant, d\u00e8s le d\u00e9part, l\u2019\u0153il du spectateur ne per\u00e7oit pas un ensemble. C\u00f4t\u00e9 jardin, Anit Ghosh et Kattam sont physiquement enti\u00e8rement pr\u00e9sents. Ces musiciens qui ram\u00e8nent sur sc\u00e8ne quelque chose des traditions musicales d\u2019o\u00f9 ils viennent (Europe de l\u2019est et Afrique du nord)\u00a0: le fait que ces musiques se dansent et sont souvent des musiques de transe. Le corps de Anit est totalement investi de la musique qu\u2019il joue, et Kattam, bien qu\u2019\u00e0 l\u2019arri\u00e8re avec son arsenal de percussions devant lui, ne se fait pas du tout oublier, tant il est tellement pr\u00e9sent, secoue la t\u00eate, l\u00e8ve les yeux au ciel, s\u2019engage dans chaque mouvement, danse debout. Plus tard il s\u2019avance au-devant de la sc\u00e8ne pour jouer des pieds sur une \u00e9norme percussion. \u00c0 la fin il anime une s\u00e9ance de percussions des mains o\u00f9 le public forme deux groupes et d\u00e9couvre la polyrythmie. En Afrique, nombre de ma\u00eetres disent que pour \u00eatre un vrai musicien il faut \u00eatre capable de danser ce qu\u2019on joue.<\/p>\n<p>C\u00f4t\u00e9 cour de la sc\u00e8ne, les deux musiciens leaders du groupe font contraste. Ce n\u2019est qu\u2019\u00e0 la fin du spectacle qu\u2019ils se sont laiss\u00e9s emporter par l\u2019\u00e9nergie du violoniste et du percussionniste, celui-ci entamant des pas de danse pr\u00e8s de Hamza qui s\u2019y est mis. On aurait voulu que cette \u00e9nergie soit pr\u00e9sente d\u00e8s le d\u00e9part, que tout le groupe sur sc\u00e8ne forme quelque chose qui nous restitue l\u2019esprit des musiques maghr\u00e9bines\u00a0: la f\u00eate du groupe. On avait l\u00e0 quelque chose qui semblait h\u00e9siter entre le band \u00e0 l\u2019occidentale o\u00f9 les corps sont presque l\u00e0 par hasard, et l\u2019investissement des corps des traditions maghr\u00e9bines et tziganes. Le batteur bien s\u00fbr ne pouvait pas faire grand chose. Quoique\u2026<\/p>\n<p><strong>Le choix des instruments\u00a0: batterie rock et percussions<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Le batteur aurait pu faire quelque chose\u00a0: jouer moins fort. On aurait appr\u00e9ci\u00e9 davantage une batterie style jazz qu\u2019une grosse batterie rock qui n\u2019a pas sa place dans une formation o\u00f9 chaque instrument est \u00e9galement important et m\u00e9rite d\u2019\u00eatre entendu. Ce n\u2019est que dans la pi\u00e8ce sans batterie qu\u2019on a vraiment pu entendre la virtuosit\u00e9 de Kattam aux percussions. L\u2019alignement batterie-percussions, utilis\u00e9e aussi dans de nombreux groupes latins \u00e0 Montr\u00e9al, est tr\u00e8s difficile \u00e0 ma\u00eetriser et m\u00e9rite qu\u2019on s\u2019y arr\u00eate, car la batterie peut rapidement effacer les congas, djemb\u00e9s et autres instruments percussifs qui donnent toute sa couleur \u00e0 la musique.<\/p>\n<p>Le public ne s\u2019y est pas tromp\u00e9\u00a0: j\u2019ai pu entendre plusieurs personnes dans le public dire que la batterie \u00e9tait vraiment trop forte. Il est vrai qu\u2019il n\u2019y a pas de rapport entre l\u2019agression du tympan et le soul\u00e8vement euphorique qui nous conduira \u00e0 danser. Une guitare flamenca est bien capable de nous soulever une salle enti\u00e8re, car le sens du rythme n\u2019est pas en rapport avec l\u2019intensit\u00e9 du son.<strong><br \/>\n<\/strong><\/p>\n<p><strong>Le choix communautaire\u00a0: qui ne parle pas arabe dans la salle\u00a0?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ayrad a jou\u00e9 les onze chansons de l\u2019album, ainsi que deux reprises c\u00e9l\u00e8bres du r\u00e9pertoire maghr\u00e9bin, pour le plus grand bonheur de tous. Ayrad a voulu embarquer le public dans un \u00e9change. \u00c0 ceci pr\u00e8s qu\u2019il nous a demand\u00e9 de r\u00e9p\u00e9ter, sans se soucier que peut-\u00eatre certains dans la salle ne parlaient pas arabe. Ce petit d\u00e9tail est d\u2019une tr\u00e8s grande importance, car il signifie que le choix est fait, et que le groupe cherche \u00e0 atteindre un public communautaire. Ayrad parlait en fran\u00e7ais bien s\u00fbr, mais pourquoi ne pas nous avoir dit lentement les mots en arabe, quitte \u00e0 prendre deux minutes pour nous traduire la partie \u00e0 r\u00e9p\u00e9ter\u00a0? J\u2019ai pu voir des jeunes filles qu\u00e9b\u00e9coises enthousiastes qui d\u2019un coup ont fait des signes d\u2019ignorance en voulant r\u00e9p\u00e9ter, noy\u00e9es dans une foule arabophone heureuse de retrouver sa langue et sa musique.<\/p>\n<p>Qu\u2019un groupe de musique permette \u00e0 des immigrants de retrouver un lien avec leurs origines, c\u2019est absolument n\u00e9cessaire dans une ville comme Montr\u00e9al. Mais ne pas inclure les autres, qui sont l\u00e0 pour d\u00e9couvrir et appr\u00e9cier \u00ab\u00a0l\u2019autre\u00a0\u00bb, limitera la port\u00e9e du groupe. Et c\u2019est souvent cela qui, au Qu\u00e9bec, diff\u00e9rencie les artistes dits \u00ab\u00a0du monde\u00a0\u00bb qui resteront confin\u00e9s \u00e0 un public communautaire, et ceux qui feront des salles plus grandes, plus nombreuses et plus vari\u00e9es. Le choix d\u2019int\u00e9grer sur sc\u00e8ne des artistes venus du Qu\u00e9bec et d\u2019ailleurs inviterait donc \u00e0 int\u00e9grer aussi le public non arabophone \u00e0 cette musique qui parle \u00e0 tous.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Le choix des th\u00e8mes\u00a0: originalit\u00e9\u00a0?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00a0 <\/strong>Ayrad chante le pays, sa m\u00e8re, l\u2019amour. Des th\u00e8mes, il faut le dire, largement balis\u00e9s par les artistes immigrants. Il y a des th\u00e8mes qui collent \u00e0 la peau de certains artistes venus d\u2019un certain milieu culturel\u00a0: les latinos parlent de danser, les arabes parlent de leur m\u00e8re, les africains parlent de la pauvret\u00e9. Pouvons-nous sortir de ces clich\u00e9s pour que nos artistes venus d\u2019ailleurs, mais bien ici, nous parlent aussi de notre r\u00e9alit\u00e9 partag\u00e9e\u00a0?<\/p>\n<p><strong>Comment sortir du lot\u00a0? <\/strong><\/p>\n<p>Montr\u00e9al est un v\u00e9ritable \u00e9crin o\u00f9 des bijoux de musiciens formant une diversit\u00e9 unique au monde, sont pr\u00eats \u00e0 nous donner le meilleur. De nombreux groupes remplissent chaque semaine les m\u00eames salles de Montr\u00e9al, o\u00f9 le public se rend aux soir\u00e9es \u00ab\u00a0arabes\u00a0\u00bb, \u00ab\u00a0salsa\u00a0\u00bb, \u00ab\u00a0africaines\u00a0\u00bb. Le multiculturalisme op\u00e8re en \u00e9tiquetant les artistes pour remplir une case carte postale et communautaire. Les groupes se cr\u00e9ent, s\u2019agrandissent, s\u2019\u00e9vanouissent, se recomposent.<\/p>\n<p>Les choix de mise en sc\u00e8ne, du public cibl\u00e9 et des th\u00e8mes des chansons sont les \u00e9l\u00e9ments qui feront l\u2019originalit\u00e9 d\u2019un groupe dans une ville o\u00f9 m\u00e9langer le traditionnel et le moderne, et m\u00e9langer diff\u00e9rents styles de musiques du monde, devient banal. Il faudra aussi des \u00e9v\u00e9nements et des salles qui encouragent autre chose que la vente de cartes postales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mardi dernier le groupe Ayrad pr\u00e9sentait son premier album au Cabaret du Mile End, dans le cadre du Festival du Monde Arabe. L\u2019\u00e9motion et l\u2019enthousiasme \u00e9taient au rendez-vous autour de ce groupe qui puise dans diff\u00e9rents styles musicaux d\u2019Afrique du nord avec de l\u00e9g\u00e8res influences andalouses et des instruments modernes (clavier, basse). Autour de Ayrad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[120,122,39,121,44],"class_list":["post-349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequilsnousracontent","tag-communautarisme","tag-montreal","tag-multiculturalisme","tag-musique-arabe","tag-musique-du-monde"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ayrad ou les n\u00e9cessaires choix - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ayrad ou les n\u00e9cessaires choix - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Mardi dernier le groupe Ayrad pr\u00e9sentait son premier album au Cabaret du Mile End, dans le cadre du Festival du Monde Arabe. L\u2019\u00e9motion et l\u2019enthousiasme \u00e9taient au rendez-vous autour de ce groupe qui puise dans diff\u00e9rents styles musicaux d\u2019Afrique du nord avec de l\u00e9g\u00e8res influences andalouses et des instruments modernes (clavier, basse). Autour de Ayrad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-01T23:27:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-18T15:17:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.20.40.png\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.20.40.png\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.20.40.png\",\"width\":590,\"height\":411},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/\",\"name\":\"Ayrad ou les n\u00e9cessaires choix - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#primaryimage\"},\"datePublished\":\"2014-11-01T23:27:47+00:00\",\"dateModified\":\"2020-05-18T15:17:49+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayrad ou les n\u00e9cessaires choix\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayrad ou les n\u00e9cessaires choix - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/","og_locale":"en_US","og_type":"article","og_title":"Ayrad ou les n\u00e9cessaires choix - Sarah Roubato","og_description":"Mardi dernier le groupe Ayrad pr\u00e9sentait son premier album au Cabaret du Mile End, dans le cadre du Festival du Monde Arabe. L\u2019\u00e9motion et l\u2019enthousiasme \u00e9taient au rendez-vous autour de ce groupe qui puise dans diff\u00e9rents styles musicaux d\u2019Afrique du nord avec de l\u00e9g\u00e8res influences andalouses et des instruments modernes (clavier, basse). Autour de Ayrad [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2014-11-01T23:27:47+00:00","article_modified_time":"2020-05-18T15:17:49+00:00","og_image":[{"width":590,"height":411,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.20.40.png","type":"image\/png"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Written by":"Sarah Roubato","Est. reading time":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#primaryimage","inLanguage":"en-US","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.20.40.png","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.20.40.png","width":590,"height":411},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/","name":"Ayrad ou les n\u00e9cessaires choix - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#primaryimage"},"datePublished":"2014-11-01T23:27:47+00:00","dateModified":"2020-05-18T15:17:49+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/ayrad-ou-les-necessaires-choix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Ayrad ou les n\u00e9cessaires choix"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":4,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/349\/revisions"}],"predecessor-version":[{"id":4486,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/349\/revisions\/4486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media\/327"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media?parent=349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/categories?post=349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/tags?post=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}