
{"id":595,"date":"2015-07-01T21:51:44","date_gmt":"2015-07-02T03:51:44","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=595"},"modified":"2020-05-17T17:48:00","modified_gmt":"2020-05-17T15:48:00","slug":"lettre-en-morceaux-a-emile-zola2","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/","title":{"rendered":"Lettre en morceaux \u00e0 \u00c9mile Zola 2"},"content":{"rendered":"<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg\" alt=\"Lettre Zola2\" width=\"400\" height=\"310\" class=\"alignnone size-full wp-image-598\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg 400w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2-150x116.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2-300x233.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Le 7 juillet 2015<\/p>\n<\/p>\n<p>Monsieur Zola,<\/p>\n<\/p>\n<p>Vous avez \u00e9crit :<\/p>\n<\/p>\n<p>\u00ab Chaque fois qu\u2019un jeune homme de province tombe chez moi pour me demander conseil, je l\u2019engage \u00e0 se jeter en plein dans la bataille, dans le journalisme&#8230; Combien je le pr\u00e9f\u00e8re dans la lutte quotidienne qui seule fait conna\u00eetre les choses et les hommes ! &#8230; On dit que la presse en vide beaucoup de ces jeunes gens : sans doute, mais elle ne vide jamais que ceux qui n\u2019ont rien dans le ventre. \u00bb<\/p>\n<\/p>\n<p>Que pensez-vous de la presse d\u2019aujourd\u2019hui ? Vous aviez per\u00e7u la force naissante de l\u2019opinion publique au moment de votre combat pour Dreyfus. Les d\u00e9bats se faisaient alors dans les journaux. Les \u00e9crivains y avaient des colonnes enti\u00e8res pour parler de la soci\u00e9t\u00e9, hors des rubriques litt\u00e9raires. M\u00eame les futurs dirigeants politiques \u00e9crivaient. Aujourd\u2019hui ceux-l\u00e0 qui pr\u00e9tendent repr\u00e9senter le peuple et s\u2019adresser \u00e0 lui n\u2019\u00e9crivent plus leurs propres discours. Aujourd\u2019hui c\u2019est ceux qui n\u2019ont rien dans le ventre qui publient. De l\u2019information, des r\u00e9sum\u00e9s, des compte-rendus. Et ceux qui ont quelques chose dans le ventre ont\u2026 les cheveux blancs.<\/p>\n<\/p>\n<p>Et certains d\u2019entre eux daignent me rencontrer, c\u2019est pour me dire \u00ab Ah il y a dix ans, c\u2019est s\u00fbr que vous auriez eu votre chance\u2026 \u00bb, \u00ab Merci pour votre article mais nous ne prenons pas de pigistes \u00bb, \u00ab Votre message a bien \u00e9t\u00e9 re\u00e7u. Si nous ne donnons pas suite\u2026 \u00bb. La plupart du temps, on ne lui dit rien. Les journaux ind\u00e9pendants sont \u00e0 l\u2019agonie. Restent les blogs et les journaux en ligne qui prennent son travail sans le r\u00e9mun\u00e9rer, contre une \u00ab visibilit\u00e9 \u00bb. Quand \u00e9crire n\u2019est pas un passe-temps mais une raison d\u2019\u00eatre et un m\u00e9tier, doit-on accepter de se retrouver dans les blogs des lecteurs ? Figurez-vous, il y a un an, un jury d\u2019une radio communautaire m\u2019a dit que mon \u00e9mission \u00e9tait refus\u00e9e car \u00ab faire r\u00e9fl\u00e9chir un artiste \u00e0 sa d\u00e9marche, \u00e7a le mettrait mal \u00e0 l\u2019aise. \u00bb Il faut rester dans l\u2019information et la promotion. Vous l\u2019aviez d\u2019ailleurs pressenti :<\/p>\n<\/p>\n<p>\u00ab L\u00e0 est la formule nouvelle : l\u2019information. C\u2019est l\u2019information qui, peu \u00e0 peu, en s\u2019\u00e9talant, a transform\u00e9 le journalisme, tu\u00e9 les grands articles de discussion, tu\u00e9 la critique litt\u00e9raire, donn\u00e9 chaque jour plus de place aux d\u00e9p\u00eaches, aux nouvelles grandes et petites, aux proc\u00e8s-verbaux des reporters et des interviewers. Il s\u2019agit d\u2019\u00eatre renseign\u00e9 tout de suite. \u00bb<\/p>\n<\/p>\n<p>Tout de suite, voil\u00e0 le mot d\u2019ordre.  Court article visible sur le iphone, \u00e0 la pause d\u00e9jeuner. C\u2019est que les gens, Monsieur Zola, ne lisent plus de longs articles. Voyez, je suis oblig\u00e9e de couper cette lettre en morceaux pour \u00eatre s\u00fbre qu\u2019elle soit lue en entier.<\/p>\n<\/p>\n<p>\u00c0 demain donc<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-1.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-1-300x145.png\" alt=\"signature Sarah 1\" width=\"300\" height=\"145\" class=\"alignnone size-medium wp-image-621\" \/><\/a><br \/>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 7 juillet 2015 Monsieur Zola, Vous avez \u00e9crit : \u00ab Chaque fois qu\u2019un jeune homme de province tombe chez moi pour me demander conseil, je l\u2019engage \u00e0 se jeter en plein dans la bataille, dans le journalisme&#8230; Combien je le pr\u00e9f\u00e8re dans la lutte quotidienne qui seule fait conna\u00eetre les choses et les hommes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-595","post","type-post","status-publish","format-standard","hentry","category-lettres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lettre en morceaux \u00e0 \u00c9mile Zola 2 - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettre en morceaux \u00e0 \u00c9mile Zola 2 - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Le 7 juillet 2015 Monsieur Zola, Vous avez \u00e9crit : \u00ab Chaque fois qu\u2019un jeune homme de province tombe chez moi pour me demander conseil, je l\u2019engage \u00e0 se jeter en plein dans la bataille, dans le journalisme&#8230; Combien je le pr\u00e9f\u00e8re dans la lutte quotidienne qui seule fait conna\u00eetre les choses et les hommes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-02T03:51:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-17T15:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg\",\"width\":400,\"height\":310},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/\",\"name\":\"Lettre en morceaux \u00e0 \u00c9mile Zola 2 - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#primaryimage\"},\"datePublished\":\"2015-07-02T03:51:44+00:00\",\"dateModified\":\"2020-05-17T15:48:00+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettre en morceaux \u00e0 \u00c9mile Zola 2\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettre en morceaux \u00e0 \u00c9mile Zola 2 - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/","og_locale":"en_US","og_type":"article","og_title":"Lettre en morceaux \u00e0 \u00c9mile Zola 2 - Sarah Roubato","og_description":"Le 7 juillet 2015 Monsieur Zola, Vous avez \u00e9crit : \u00ab Chaque fois qu\u2019un jeune homme de province tombe chez moi pour me demander conseil, je l\u2019engage \u00e0 se jeter en plein dans la bataille, dans le journalisme&#8230; Combien je le pr\u00e9f\u00e8re dans la lutte quotidienne qui seule fait conna\u00eetre les choses et les hommes [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-07-02T03:51:44+00:00","article_modified_time":"2020-05-17T15:48:00+00:00","og_image":[{"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Written by":"Sarah Roubato","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#primaryimage","inLanguage":"en-US","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola2.jpg","width":400,"height":310},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/","name":"Lettre en morceaux \u00e0 \u00c9mile Zola 2 - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#primaryimage"},"datePublished":"2015-07-02T03:51:44+00:00","dateModified":"2020-05-17T15:48:00+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Lettre en morceaux \u00e0 \u00c9mile Zola 2"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/comments?post=595"}],"version-history":[{"count":9,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/595\/revisions"}],"predecessor-version":[{"id":4439,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/595\/revisions\/4439"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media?parent=595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/categories?post=595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/tags?post=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}