
{"id":863,"date":"2015-10-08T08:49:13","date_gmt":"2015-10-08T14:49:13","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=863"},"modified":"2020-05-17T14:25:01","modified_gmt":"2020-05-17T12:25:01","slug":"lettre-aux-refugies-4","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/","title":{"rendered":"Lettre aux r\u00e9fugi\u00e9s 4"},"content":{"rendered":"<p>Si c\u2019est vrai. Vous y \u00eates. Tout vous para\u00eet beau. Il fait froid, je sais. Les vaches ont l\u2019air \u00e9norme. Vous pleurez vous riez. Dormez. Dormez enfin. Vous \u00eates l\u00e0, vous y restez. Mais attendez\u2026<\/p>\n<p> Vous voil\u00e0 arriv\u00e9s. Bien ou mal, accueillis ou tol\u00e9r\u00e9s, install\u00e9s ou parqu\u00e9s, ici ou l\u00e0, parce que vos proches y sont ou parce que c\u2019\u00e9tait plus facile d\u2019y entrer. La France, la Su\u00e8de, l\u2019Allemagne, vous les avez \u00e0 peine choisi. Quand on fuit, est-ce qu\u2019on choisit ? Un autre p\u00e9riple plus long encore commence : celui qui vous m\u00e8nera \u00e0 vous sentir \u2013 comment doit-on dire ? \u2013 int\u00e9gr\u00e9s, assimil\u00e9s, adopt\u00e9s. On d\u00e9bat d\u00e9j\u00e0 sur votre capacit\u00e9 \u00e0 vous int\u00e9grer. Et chaque pays de cette soi-disant Union Europ\u00e9enne a sa propre conception de l\u2019int\u00e9gration. <\/p>\n<p><strong>&#8220;You leave home when home won&#8217;t let you stay&#8221;<br \/>\nWarsan Shire<\/strong><\/p>\n<p> En ce moment les m\u00e9dias font la course au portrait d\u2019immigr\u00e9s int\u00e9gr\u00e9s \u00e0 la soci\u00e9t\u00e9 qui font rayonner sa culture. Comme pour montrer l\u2019\u00e9vidence : une soci\u00e9t\u00e9 s\u2019enrichit toujours des apports des immigrants. Une soci\u00e9t\u00e9 saine est une soci\u00e9t\u00e9 qui bouge. On expose des migrants mod\u00e8les. Bien s\u00fbr on ne parlera pas de ceux qui sont rest\u00e9s vingt ans ici et parlent \u00e0 peine la langue. Pourtant ils existent, autant que les autres qui font pleinement partie de notre soci\u00e9t\u00e9. Certains viennent avec un tel d\u00e9sir d\u2019int\u00e9gration qu\u2019ils parleront mieux la langue que beaucoup de natifs. D\u2019autres se retrouvent dans des quartiers isol\u00e9s et se replient en communaut\u00e9. C\u2019est qu\u2019une personne en exil devient simultan\u00e9ment plus fragile et plus puissante qu\u2019elle ne l\u2019a jamais \u00e9t\u00e9.<\/p>\n<p> Plus fragile parce que te voil\u00e0 en territoire inconnu, avec des codes, une langue et des normes \u00e9trangers. Tu attiseras les peurs des locaux et les convoitises des communautaristes. Les primates sont port\u00e9s \u00e0 se rapprocher de ceux qui leur ressemblent. Tu iras d\u2019abord voir tes proches, les gens qui partagent la m\u00eame langue et la m\u00eame religion que toi. <\/p>\n<p> Mais une personne en exil a aussi une force extraordinaire. Celle de rena\u00eetre. De se r\u00e9inventer. Ici, tu peux te distancer de certaines normes de ton pays. Tu perds tes rep\u00e8res, pour t\u2019en fabriquer d\u2019autres. Si on te donne les outils pour le faire, et si tu es pr\u00eat \u00e0 t\u2019en servir. <\/p>\n<p> Tu auras toujours comme un petit mal de mer, comme un fil qui tirera vers l\u00e0 d\u2019o\u00f9 tu es parti. Mais tu rencontreras la partie de toi qui y survis. Oui je sais, \u00e7a fait peur. Et \u00e7a fait mal. Comme toutes les naissances. <\/p>\n<p> Tes enfants, eux, joueront dans la cour avec les autres avant m\u00eame de pouvoir leur parler. Bient\u00f4t c\u2019est eux qui te traduiront les papiers administratifs dans la nouvelle langue. Elle leur glissera dans le gosier comme du sirop. <\/p>\n<p> L\u2019adaptation\u2026 principe qui m\u00e8ne un animal \u00e0 survivre ou non dans un milieu donn\u00e9. \u00c7a y est vous vous r\u00e9veillez ? Non, ce matin, plus besoin de marcher. Vous \u00eates l\u00e0, et vous y restez. Et aujourd\u2019hui commence pour vous le plus long p\u00e9riple.   <\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-NB.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-NB-300x145.png\" alt=\"signature Sarah NB\" width=\"300\" height=\"145\" class=\"alignright size-medium wp-image-696\" \/><\/a><br \/>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Si c\u2019est vrai. Vous y \u00eates. Tout vous para\u00eet beau. Il fait froid, je sais. Les vaches ont l\u2019air \u00e9norme. Vous pleurez vous riez. Dormez. Dormez enfin. Vous \u00eates l\u00e0, vous y restez. Mais attendez\u2026 Vous voil\u00e0 arriv\u00e9s. Bien ou mal, accueillis ou tol\u00e9r\u00e9s, install\u00e9s ou parqu\u00e9s, ici ou l\u00e0, parce que vos proches y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[203,221,240,244,220,190,223,243],"class_list":["post-863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lettres","tag-europe","tag-exil","tag-immigration","tag-integration","tag-migrants","tag-sarah-roubato","tag-syrie","tag-warsan-shire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lettre aux r\u00e9fugi\u00e9s 4 - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettre aux r\u00e9fugi\u00e9s 4 - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Si c\u2019est vrai. Vous y \u00eates. Tout vous para\u00eet beau. Il fait froid, je sais. Les vaches ont l\u2019air \u00e9norme. Vous pleurez vous riez. Dormez. Dormez enfin. Vous \u00eates l\u00e0, vous y restez. Mais attendez\u2026 Vous voil\u00e0 arriv\u00e9s. Bien ou mal, accueillis ou tol\u00e9r\u00e9s, install\u00e9s ou parqu\u00e9s, ici ou l\u00e0, parce que vos proches y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-08T14:49:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-17T12:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/re\u0301fugie\u0301s4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/re\u0301fugie\u0301s4.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/re\u0301fugie\u0301s4.jpg\",\"width\":400,\"height\":310},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/\",\"name\":\"Lettre aux r\u00e9fugi\u00e9s 4 - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#primaryimage\"},\"datePublished\":\"2015-10-08T14:49:13+00:00\",\"dateModified\":\"2020-05-17T12:25:01+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettre aux r\u00e9fugi\u00e9s 4\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettre aux r\u00e9fugi\u00e9s 4 - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/","og_locale":"en_US","og_type":"article","og_title":"Lettre aux r\u00e9fugi\u00e9s 4 - Sarah Roubato","og_description":"Si c\u2019est vrai. Vous y \u00eates. Tout vous para\u00eet beau. Il fait froid, je sais. Les vaches ont l\u2019air \u00e9norme. Vous pleurez vous riez. Dormez. Dormez enfin. Vous \u00eates l\u00e0, vous y restez. Mais attendez\u2026 Vous voil\u00e0 arriv\u00e9s. Bien ou mal, accueillis ou tol\u00e9r\u00e9s, install\u00e9s ou parqu\u00e9s, ici ou l\u00e0, parce que vos proches y [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-10-08T14:49:13+00:00","article_modified_time":"2020-05-17T12:25:01+00:00","og_image":[{"width":400,"height":310,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/re\u0301fugie\u0301s4.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Written by":"Sarah Roubato","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#primaryimage","inLanguage":"en-US","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/re\u0301fugie\u0301s4.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/re\u0301fugie\u0301s4.jpg","width":400,"height":310},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/","name":"Lettre aux r\u00e9fugi\u00e9s 4 - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#primaryimage"},"datePublished":"2015-10-08T14:49:13+00:00","dateModified":"2020-05-17T12:25:01+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-aux-refugies-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Lettre aux r\u00e9fugi\u00e9s 4"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/en\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":2,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/863\/revisions"}],"predecessor-version":[{"id":4421,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/posts\/863\/revisions\/4421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media\/852"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/en\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}