
{"id":1414,"date":"2017-03-12T06:39:09","date_gmt":"2017-03-12T05:39:09","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=1414"},"modified":"2021-04-15T08:54:31","modified_gmt":"2021-04-15T06:54:31","slug":"aulecteur","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/lettres\/aulecteur\/","title":{"rendered":"Lettre aux yeux derri\u00e8re cet \u00e9cran"},"content":{"rendered":"<p>Cher lecteur,<\/p>\n<p>Si nous te disons <em>tu<\/em>, c\u2019est parce que c\u2019est \u00e0 toi, petite individualit\u00e9 sur deux pattes, que notre travail s\u2019adresse. C\u2019est en toi qu\u2019il r\u00e9sonne et c\u2019est pour toi que nous le faisons. Si je dis <em>nous<\/em>, c\u2019est parce que je ne suis qu\u2019un parmi tant d\u2019autres, jeunes cr\u00e9ateurs, diseurs, faiseurs, qui cherchons une autre mani\u00e8re de travailler, de cr\u00e9er, d\u2019exprimer le monde et d\u2019y agir.<\/p>\n<p>Nous t\u2019\u00e9crivons de la terrasse d\u2019un caf\u00e9, sur la petite place d\u2019un de ces vieux centre villes qui finissent par tous se ressembler, entre les boutiques d\u2019artisanat local fabriqu\u00e9 \u00e0 trois cents kilom\u00e8tres, celles des grandes enseignes, et les petits restaurants locaux dont les prix ne sont accessibles qu\u2019aux touristes.<\/p>\n<p>C\u2019est samedi. L\u2019art\u00e8re principale ne d\u00e9semplit pas. Deux adolescentes flashent sur un vernis \u00e0 ongle dans une boutique de maquillage \u2013 3.90\u20ac. Un petit gar\u00e7on tend la main vers le paquet de bonbons multicolores expos\u00e9 dans la vitrine d\u2019une boulangerie \u2013 1.50\u20ac. Un couple regarde des coussins de d\u00e9coration \u2013 15.99\u20ac, un autre le prix d\u2019un balayage de m\u00e8ches chez le coiffeur &#8211; 80\u20ac . Un panini co\u00fbte 3\u20ac, un caf\u00e9 \u00e0 2\u20ac, une cr\u00eape appel\u00e9e <em>La Proven\u00e7ale<\/em> 12\u20ac.<\/p>\n<p>En face d\u2019un chocolatier, un jeune homme est assis en tailleur sur le trottoir. Il tient un bout de carton avec marqu\u00e9 <em>J\u2019ai faim<\/em>. \u00c7a doit \u00eatre son premier jour. L\u2019indiff\u00e9rence n&#8217;a pas encore terni son regard. Ses yeux cherchent encore une voie de sortie. Sa barbe blonde est bien taill\u00e9e. Il n\u2019y a pas grand chose qui nous s\u00e9pare. Un pas. Un pas de c\u00f4t\u00e9. Aujourd\u2019hui, je dois tenir avec deux euros vingt pour travailler jusqu\u2019au soir dans un caf\u00e9. Travailler, c\u2019est \u00e0 dire avancer un manuscrit qui s\u2019ajoutera \u00e0 ceux perdus dans une pile chez des \u00e9diteurs. \u00c7a, c&#8217;est le vrai travail. Mais il ne pourra pas prendre tout mon temps. Car il faut encore r\u00e9aliser un montage de trois minutes pour le prochain portrait sonore, pour vous donner envie de l\u2019acheter. V\u00e9rifier la liste des <em>sans r\u00e9ponse<\/em> de ce dernier mois, et pr\u00e9parer les mails pour les relancer. Chercher de nouveaux m\u00e9dias \u00e0 qui proposer des articles, chercher des radios pour diffuser des textes sonores. Prospecter, relancer, proposer, pr\u00e9senter, faire savoir&#8230;<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-1427 alignright\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/terrcaf-300x199.jpg\" alt=\"terrcaf\" width=\"317\" height=\"210\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/terrcaf-300x199.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/terrcaf-150x100.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/terrcaf-600x399.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/terrcaf-440x293.jpg 440w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/terrcaf.jpg 650w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/>Voil\u00e0 quelques temps d\u00e9j\u00e0 que tu nous connais. Il y a un peu plus d\u2019un an, tu fus un million et demi en trois jours \u00e0 lire une lettre post\u00e9e sur Mediapart. Depuis, tu es des centaines \u00e0 \u00e9crire \u00e0 Sarah. Tes messages lui rappellent que oui, il faut continuer, s\u2019accrocher, que \u00e7a a du sens, que quelque chose bouillonne. Parfois, ces conversations par \u00e9crans interpos\u00e9s sont le pr\u00e9lude de rencontres, et nous nous retrouvons quelques semaines plus tard dans un caf\u00e9, une biblioth\u00e8que, un th\u00e9\u00e2tre d\u2019un coin de France, \u00e0 parler de la soci\u00e9t\u00e9 que nous voulons construire, de nos peurs, de nos d\u00e9fis, de nos envies. \u00c0 tous les passeurs qui permettent ces rencontres, merci.<\/p>\n<p>Chaque jour Sarah re\u00e7oit des dizaines de messages de toi. Tu lui dis que ses mots ont chang\u00e9 quelque chose dans ta vie, que tu y retrouves ce que tu as toujours ressenti, tu lui parles de ta situation, de tes questionnements. Elle r\u00e9pond \u00e0 chacun. Elle sourit quand tu t\u2019excuses de la d\u00e9ranger, quand tu lui \u00e9cris qu\u2019elle n\u2019aura s\u00fbrement pas le temps de r\u00e9pondre. Elle se demande quelle image tu te fais de sa vie.\u00a0 Internet est une vitrine. Tout y est affichage : affichage d\u2019humeur, de statut, d\u2019information. Sur internet, il faut toujours dire que tout va bien. Mettre des points d\u2019exclamation. Montrer aux gens que \u00e7a marche, pour qu\u2019ils viennent. C\u2019est la r\u00e8gle : on ach\u00e8te les livres qui se vendent bien et sont aux premiers rayons des libraires, on va voir les spectacles qui remplissent d\u00e9j\u00e0 les salles, on clique sur les publications les plus partag\u00e9es.<\/p>\n<p>Quand tu \u00e9cris \u00e0 Sarah, tu ne te contentes pas de flatteries. Tu livres tes fragilit\u00e9s et tes doutes. Tu l\u2019invites \u00e0 une intimit\u00e9.\u00a0 Alors aujourd\u2019hui, nous allons r\u00e9pondre \u00e0 ton invitation. On va te parler de ce travail qui est le n\u00f4tre, de cette vie \u00e9trange de cr\u00e9ateur sur internet. On te parlera sans d\u00e9tour et sans pr\u00e9caution, honn\u00eatement et directement.<\/p>\n<p><strong>\u201cAvec internet, tu peux atteindre plus de monde !\u201d<\/strong><\/p>\n<p>On nous dit souvent que nous avons la chance de vivre dans un monde o\u00f9, gr\u00e2ce \u00e0 internet, nous pouvons partager nos cr\u00e9ations directement avec les gens, et toucher un public tr\u00e8s large. <em>Partager<\/em>, c\u2019est l\u00e0 le mot utilis\u00e9. Mais dans <em>partage<\/em>, il y a \u00e9change. Or, quand un cr\u00e9ateur met en ligne ses cr\u00e9ations gratuitement, sache qu\u2019il ne partage pas. Il ne te les offre m\u00eame pas, car dans <em>offrir<\/em>, il y a encore de l\u2019\u00e9change : le sourire de la personne \u00e0 qui tu offres, le plaisir de voir l\u2019effet produit. Derri\u00e8re l\u2019\u00e9cran, rien de tout \u00e7a. Nous balan\u00e7ons nos cr\u00e9ations dans cet espace intersid\u00e9ral, et c\u2019est tout. C\u2019est un courrier qui n&#8217;attend aucune r\u00e9ponse.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.17.46.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1421\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.17.46-300x225.png\" alt=\"Capture d\u2019e\u0301cran 2017-03-12 a\u0300 13.17.46\" width=\"300\" height=\"225\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.17.46-300x225.png 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.17.46-150x113.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.17.46-600x451.png 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.17.46.png 775w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Le cr\u00e9ateur qui met son travail en ligne a tout de l&#8217;artiste ambulant. Il a travaill\u00e9 pendant des semaines, des mois, des ann\u00e9es, sur sa cr\u00e9ation. Comme il veut te pr\u00e9senter le meilleur travail possible, il a cass\u00e9 sa tirelire pour acheter du bon mat\u00e9riel : un micro, une carte son, une cam\u00e9ra, un logiciel. Il passe quelques semaines \u00e0 se tailler un beau site internet, comme l&#8217;artiste ambulant d\u00e9pensera ce qui lui reste pour s&#8217;acheter un beau costume. Quand il poste un contenu sur internet, il met ses mains en porte-voix, et te crie : \u201cRegarde mon travail, regarde ce que je sais faire ! \u201d Toute la difficult\u00e9 consiste \u00e0 attirer ton attention, pour que tu t&#8217;arr\u00eates quelques secondes devant sa publication. Il r\u00e9\u00e9crit plusieurs fois le chapeau de son article, r\u00e9fl\u00e9chit bien aux mots cl\u00e9s, cr\u00e9e des teasers, des B.O, des montages courts, des formules, des posts sur Facebook. L&#8217;artiste ambulant ne choisit pas son heure au hasard. Il sait qu&#8217;il faut t&#8217;attraper quand tu auras l&#8217;esprit libre, dans le m\u00e9tro en revenant du boulot, ou le dimanche matin. Le meilleur article peut passer \u00e0 la trappe s&#8217;il n&#8217;est pas post\u00e9 \u00e0 la bonne heure.<\/p>\n<p><strong>Le mythe : \u201cSi tu as du talent, tu vas y arriver\u201d<\/strong><\/p>\n<p>Ce jeune cr\u00e9ateur dont nous te parlons a grandi dans une soci\u00e9t\u00e9 o\u00f9 on lui dit que si on fait du bon travail, si on a du talent, si on s\u2019accroche, on est r\u00e9compens\u00e9. Bel id\u00e9al qui suppose que les gens ne s\u2019y trompent pas. Alors il se dit que si tu aimes ce qu\u2019il te donne gratuitement, tu ach\u00e8teras le reste. On lui a dit qu\u2019il fallait d\u2019abord se faire conna\u00eetre, et ensuite esp\u00e9rer vendre. D\u2019abord travailler, ensuite proposer son article, son film, ses photos, son reportage. Comme des salles proposent aux musiciens de venir jouer gratuitement, de nombreux sites proposent aux cr\u00e9ateurs de publier <em>contre de la visibilit\u00e9<\/em>. C&#8217;est le nouveau graal : la visibilit\u00e9.<\/p>\n<p>Quand il est encore dans son antre \u00e0 cr\u00e9er, et qu\u2019il voit le bout d\u2019une oeuvre, les murs de sa chambre font un dr\u00f4le de bruit. C\u2019est que ses r\u00eaves sont trop grands, ils les font craquer. Il se dit que \u00e7a y est, cette fois \u00e7a va marcher. Non, ne t\u2019inqui\u00e8te pas, il n\u2019est pas de ceux qui r\u00eavent de succ\u00e8s facile et de gloire. Sa seule pr\u00e9tention est de pouvoir sculpter, dans la mati\u00e8re qu&#8217;il a choisie, quelque chose qui lui permettra de manger, de se loger, assez pour que son travail occupe le centre de sa vie et qu\u2019il ne soit jamais rel\u00e9gu\u00e9 en p\u00e9riph\u00e9rie, dans les miettes du temps que lui laissera son boulot de survie.<\/p>\n<figure id=\"attachment_1422\" aria-describedby=\"caption-attachment-1422\" style=\"width: 209px\" class=\"wp-caption alignright\"><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/angel-boligan-ordinateur.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1422 size-medium\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/angel-boligan-ordinateur-209x300.jpg\" alt=\"angel boligan ordinateur\" width=\"209\" height=\"300\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/angel-boligan-ordinateur-209x300.jpg 209w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/angel-boligan-ordinateur-104x150.jpg 104w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/angel-boligan-ordinateur.jpg 348w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/><\/a><figcaption id=\"caption-attachment-1422\" class=\"wp-caption-text\">Angel Boligan<\/figcaption><\/figure>\n<p>Et puis avec le temps, de coup d\u2019essai en tentative, de projet en projet, les murs de sa chambre finissent par se taire. Le jeune cr\u00e9ateur a appris \u00e0 rabaisser ses attentes. S\u2019il pouvait d\u00e9j\u00e0 se rembourser ses frais, il serait satisfait. Imagine, dans ton travail, n&#8217;avoir d&#8217;autre esp\u00e9rance que celle de te rembourser tes frais de d\u00e9placement, de t\u00e9l\u00e9phone ou de pap\u00e8terie.<\/p>\n<p>Il passe plus de temps \u00e0 agiter les bras pour attirer ton attention qu\u2019\u00e0 cr\u00e9er. Imagine un circassien qui passerait plus de temps \u00e0 te crier de venir voir son spectacle qu\u2019\u00e0 r\u00e9p\u00e9ter son num\u00e9ro. Toute cette gesticulation devant l\u2019\u00e9cran l\u2019\u00e9puise, ass\u00e8che ses instincts, coupe sa r\u00e9flexion. Il perd ce rythme de la cr\u00e9ation qui fait qu&#8217;un musicien devient bon en jouant, chaque jour. Il sait qu\u2019il pourrait aller beaucoup plus loin s\u2019il \u00e9tait libre.\u00a0 Il se sent la taille d\u2019une com\u00e8te \u00e0 qui on offrirait l\u2019\u00e9tendue d\u2019un bac \u00e0 sable.<\/p>\n<p>Il se sent pris dans l\u2019obligation de poster r\u00e9guli\u00e8rement, pour ne pas te perdre, pour que tu vois qu\u2019il est <em>actif<\/em>. Le vois-tu, certains soirs, les yeux rougis par l\u2019\u00e9cran, le rond brun de la tasse qui se superpose aux autres sur son bureau, faire craquer son cou, dans le silence de sa chambre, apr\u00e8s avoir pass\u00e9 cinq heures \u00e0 bien arranger un extrait de son travail pour te donner l\u2019envie de lire, de regarder ou d\u2019\u00e9couter ce qu\u2019il fait ?<\/p>\n<p>Bien s\u00fbr cette vie, il l&#8217;a choisie. En fait, il a choisi de ne jamais donner priorit\u00e9 \u00e0 autre chose qu&#8217;\u00e0 son vrai travail. Mais il n&#8217;a pas choisi le reste. Passer une heure \u00e0 choisir une police pour que le visuel soit beau et attire l&#8217;attention de l&#8217;internaute, \u00e7a il ne l&#8217;a pas choisi. Il sait bien qu&#8217;il ne sera jamais pay\u00e9 \u00e0 l&#8217;heure, ni m\u00eame \u00e0 la valeur r\u00e9elle de son travail. Soit. Il ne demande qu&#8217;une chose : pouvoir gagner assez pour se nourrir, se loger, se chauffer, et pour avoir le temps de continuer \u00e0 cr\u00e9er. Parfois il s&#8217;imagine qu&#8217;un de ses pairs qui aurait d\u00e9j\u00e0 fait ses preuves, lui propose une chambre dans sa maison, qu&#8217;il puisse venir y travailler le temps qu&#8217;il a besoin. Il souffre du manque de lien interg\u00e9n\u00e9rationnel entre les cr\u00e9ateurs. Les anciens sont bien trop occup\u00e9s pour daigner r\u00e9pondre aux petits jeunes. La transmission qui a pu exister entre le ma\u00eetre et l&#8217;apprenti, le simple lien de confiance qui autoriserait un jeune \u00e0 se confier \u00e0 un grand fr\u00e8re, une \u00e9paule pour se reposer, une oreille pour accueillir les d\u00e9couragements comme les excitations, ou bien simplement, un moment qui ne soit pas d\u00e9rob\u00e9 \u00e0 l&#8217;urgence, une soir\u00e9e o\u00f9 quelque chose se d\u00e9pose, tout cela semble avoir \u00e9t\u00e9 balay\u00e9.<\/p>\n<p>Pourtant, au milieu de cet isolement des individus et des g\u00e9n\u00e9rations, certains tentent autre chose. On s&#8217;invente d&#8217;autres mani\u00e8res de faire, soi-m\u00eame, sans interm\u00e9diaire, dans l&#8217;entraide, le troc, l&#8217;\u00e9change. Pour la nourriture, le transport, les services. Mais pas encore pour l&#8217;immat\u00e9riel. Il ne viendrait \u00e0 l&#8217;esprit\u00a0 de personne de ne pas payer son caf\u00e9. Mais payer un enregistrement, une chanson, de la musique, une photo&#8230;<\/p>\n<p><strong>Les nouveaux m\u00e9tiers \u00e0 inventer<\/strong><\/p>\n<p>Le 10 janvier 2017 en rallumant son ordinateur, Sarah trouve quatre-vingt seize messages dat\u00e9s du jour-m\u00eame. Elle comprend que c\u2019est aujourd\u2019hui qu\u2019a \u00e9t\u00e9 post\u00e9e la lettre <strong><em><a href=\"http:\/\/lareleveetlapeste.fr\/trouve-verbe-de-vie-metier-verbe-lettre-bouleversante\/\">Trouve le verbe de ta vie<\/a><\/em><\/strong> sur le site de la <a href=\"http:\/\/lareleveetlapeste.fr\/\"><strong>Rel\u00e8ve et la Peste<\/strong>,<\/a>\u00a0 un de ces nouveaux m\u00e9dias qui te propose de te faire voir le monde autrement. Elle apprend qu\u2019en vingt-quatre heures, cette lettre a \u00e9t\u00e9 partag\u00e9e 50 000 fois. Donc lue par quelques centaines de milliers de personnes.<\/p>\n<p>Entre le 1er janvier 2016 <a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.19.12.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1419\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.19.12-300x250.png\" alt=\"Capture d\u2019e\u0301cran 2017-03-12 a\u0300 13.19.12\" width=\"300\" height=\"250\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.19.12-300x250.png 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.19.12-150x125.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Capture-d\u2019e\u0301cran-2017-03-12-a\u0300-13.19.12.png 568w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>et le 9 mars 2017, les portraits sonores <a href=\"https:\/\/dev.sarahroubato.com\/extraquotidien\"><em><strong>L\u2019extraordinaire au quotidien<\/strong> (en cliquant ici tu arriveras sur la page) <\/em><\/a>ont r\u00e9colt\u00e9 256,50\u20ac, gr\u00e2ce \u00e0 23 acheteurs. Soit 85\u20ac par mois. Dans ce m\u00eame laps de temps, quelques dizaines de milliers lecteurs sont venus sur les pages de ces portraits. Voil\u00e0 plus de six mois que le mat\u00e9riel d\u2019enregistrement \u00e0 2000\u20ac n\u2019est pas sorti de son sac, qu&#8217;aucun nouveau portrait n&#8217;a \u00e9t\u00e9 enregistr\u00e9. Parce qu\u2019il faut d\u2019abord essayer de diffuser ce qui a \u00e9t\u00e9 fait. Chaque portrait prend environ un mois de travail \u00e0 temps plein. Ils sont vendus \u00e0 prix ouvert \u2013 tu peux y mettre entre 50 centimes et 20 euros. L\u2019\u00e9quivalent d\u2019un caf\u00e9, d\u2019un ticket de m\u00e9tro, d\u2019un sandwich. Tiens, la ville change de costume, c\u2019est la fin de l\u2019apr\u00e8s-midi. L\u2019heure de l\u2019ap\u00e9ro, le Vittel menthe \u00e0 3.20\u20ac. Un fond de sirop sucr\u00e9 et de l\u2019eau. Si 10% des 50.000 personnes qui ont partag\u00e9 la lettre donnait 1\u20ac pour \u00e9couter un portrait de 30 minutes\u2026 1 mois de travail\u2026 1\u20ac\u2026 10% de 50.000\u2026 5000\u20ac, de quoi vivre largement pendant un an.<\/p>\n<p>Qu&#8217;est-ce que j&#8217;ai mal fait, mal pens\u00e9, mal \u00e9valu\u00e9\u00a0? Le m\u00e9tier d\u2019agitateur sur internet n\u2019est pas inn\u00e9, ce n\u2019est pas le n\u00f4tre, et ce n\u2019est pas lui que nous avons choisi. Internet est un outil et non une fin. Il faut se remettre en question. Mais le travail de cr\u00e9ateur ne d\u00e9pend pas que de soi. Alors nous nous interrogeons sur toi, lecteur. Incompr\u00e9hension, stupeur. Et oui, col\u00e8re (On t\u2019a promis que cette lettre sera honn\u00eate) Bien s\u00fbr, tu es sans cesse sollicit\u00e9. Les num\u00e9ros inconnus qui t\u2019appellent apr\u00e8s le travail pour te proposer des produits, les campagnes de don des associations, et puis nous sommes des centaines, des milliers d\u2019artistes sur internet \u00e0 te demander d\u2019encourager notre travail. Tu ne peux pas donner de partout. Bien s\u00fbr. Et le Vittel menthe \u00e0 3.20\u20ac, et le coussin de d\u00e9coration, et le sandwich. Bien s\u00fbr nous ne sommes qu\u2019une fraction de secondes dans ta vie sur internet, et nous devrions nous estimer heureux que tu t\u2019arr\u00eates pour cliquer, pour liker, pour partager. <em>Bien s\u00fbr il y a les guerres d\u2019Irlande\u2026<\/em><\/p>\n<p>On nous conseille parfois de faire des lev\u00e9es de fond sur des sites participatifs. Mais c\u2019est encore de l\u2019aum\u00f4ne. Nous voudrions autre chose. Nous pr\u00e9tendons que nous faisons un travail qui m\u00e9rite r\u00e9mun\u00e9ration. Comme le Vittel, comme le sandwich, comme le vernis \u00e0 ongle.<\/p>\n<p><strong>Cette autre soci\u00e9t\u00e9 dont nous r\u00eavons<\/strong><\/p>\n<p>\u00c0 l\u2019heure o\u00f9 la France s\u2019inqui\u00e8te de son avenir, tu dois te dire qu&#8217;il y a d&#8217;autres priorit\u00e9s. Mais c&#8217;est au contraire le meilleur moment, pour te parler de ces jeunes qui essayent de se r\u00e9inventer leur m\u00e9tier, qui cherchent d\u2019autres mod\u00e8les \u00e9conomiques. Et qui n&#8217;y arriverons pas sans toi. Comme aucun artiste, aussi g\u00e9nial, talentueux et travailleur fut-il, n&#8217;a r\u00e9ussi sans l&#8217;aide, l&#8217;\u00e9coute et la disponibilit\u00e9s de ses pairs.<a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1160 alignright\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-300x200.jpg\" alt=\"photo : Francis Azevedo\" width=\"300\" height=\"200\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-300x200.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-150x100.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-600x400.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-440x293.jpg 440w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-650x433.jpg 650w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11-886x590.jpg 886w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/04\/Nuit-debout11.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Alors, nous diras-tu, quel est le but de cette lettre ? Te faire culpabiliser ? S\u00fbrement pas. Simplement te rappeler \u00e0 ton pouvoir de consommateur, toi la paire d\u2019yeux qui es en train de lire ces lignes entre deux urgences. Toi qui lis, qui commentes, qui partages derri\u00e8re ton \u00e9cran, sache que chacun de tes clics est un geste que tu poses dans le circuit de la cr\u00e9ation et des m\u00e9dias. Toi qui te plains peut-\u00eatre d\u2019entendre toujours la m\u00eame chose dans les m\u00e9dias, toi qui voudrais autre chose. Tu n\u2019es pas invisible, tu n\u2019es pas anodin. La soci\u00e9t\u00e9 est comme la peau d&#8217;un tambour : chaque geste que tu fais et que tu ne fais pas, r\u00e9sonne \u00e0 l&#8217;autre bout. Chaque fois que tu ach\u00e8tes, et chaque fois que tu n\u2019ach\u00e8tes pas, tu choisis le monde auquel tu participes. Celui de demain, celui de tes enfants. Le n\u00f4tre, le mien. Celui qui me fera continuer ou celui qui me fera un jour tout poser par terre, et m\u2019assoir en tailleur sur le trottoir avec une petite pancarte.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Pour acheter un portrait, il suffit d&#8217;aller sur cette page (<strong><a href=\"https:\/\/dev.sarahroubato.com\/extraquotidien\">cliquez ici)<\/a><\/strong>, de choisir le portrait qui t&#8217;int\u00e9resse (extraits en \u00e9coute libre) et de cliquer sur le bouton <em>Acheter<\/em> en s\u00e9lectionnant le prix que tu souhaites mettre. Tu seras redirig\u00e9 sur une page Paypal, en descendant tu cliques sur \u00abPayer sans ouvrir de compte\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cher lecteur, Si nous te disons tu, c\u2019est parce que c\u2019est \u00e0 toi, petite individualit\u00e9 sur deux pattes, que notre travail s\u2019adresse. C\u2019est en toi qu\u2019il r\u00e9sonne et c\u2019est pour toi que nous le faisons. Si je dis nous, c\u2019est parce que je ne suis qu\u2019un parmi tant d\u2019autres, jeunes cr\u00e9ateurs, diseurs, faiseurs, qui cherchons [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1425,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[185,27,413,412,190],"class_list":["post-1414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lettres","tag-artiste","tag-consommation","tag-lecteur","tag-lettre","tag-sarah-roubato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lettre aux yeux derri\u00e8re cet \u00e9cran - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettre aux yeux derri\u00e8re cet \u00e9cran - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Cher lecteur, Si nous te disons tu, c\u2019est parce que c\u2019est \u00e0 toi, petite individualit\u00e9 sur deux pattes, que notre travail s\u2019adresse. C\u2019est en toi qu\u2019il r\u00e9sonne et c\u2019est pour toi que nous le faisons. Si je dis nous, c\u2019est parce que je ne suis qu\u2019un parmi tant d\u2019autres, jeunes cr\u00e9ateurs, diseurs, faiseurs, qui cherchons [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-12T05:39:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T06:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Sans-titre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2402\" \/>\n\t<meta property=\"og:image:height\" content=\"2407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"42 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Sans-titre.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Sans-titre.jpg\",\"width\":2402,\"height\":2407},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/\",\"name\":\"Lettre aux yeux derri\u00e8re cet \u00e9cran - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#primaryimage\"},\"datePublished\":\"2017-03-12T05:39:09+00:00\",\"dateModified\":\"2021-04-15T06:54:31+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettre aux yeux derri\u00e8re cet \u00e9cran\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettre aux yeux derri\u00e8re cet \u00e9cran - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/","og_locale":"es_ES","og_type":"article","og_title":"Lettre aux yeux derri\u00e8re cet \u00e9cran - Sarah Roubato","og_description":"Cher lecteur, Si nous te disons tu, c\u2019est parce que c\u2019est \u00e0 toi, petite individualit\u00e9 sur deux pattes, que notre travail s\u2019adresse. C\u2019est en toi qu\u2019il r\u00e9sonne et c\u2019est pour toi que nous le faisons. Si je dis nous, c\u2019est parce que je ne suis qu\u2019un parmi tant d\u2019autres, jeunes cr\u00e9ateurs, diseurs, faiseurs, qui cherchons [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2017-03-12T05:39:09+00:00","article_modified_time":"2021-04-15T06:54:31+00:00","og_image":[{"width":2402,"height":2407,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Sans-titre.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"42 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Sans-titre.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/03\/Sans-titre.jpg","width":2402,"height":2407},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/","name":"Lettre aux yeux derri\u00e8re cet \u00e9cran - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#primaryimage"},"datePublished":"2017-03-12T05:39:09+00:00","dateModified":"2021-04-15T06:54:31+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/aulecteur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Lettre aux yeux derri\u00e8re cet \u00e9cran"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=1414"}],"version-history":[{"count":15,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1414\/revisions"}],"predecessor-version":[{"id":5277,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1414\/revisions\/5277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/1425"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=1414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=1414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=1414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}