
{"id":1680,"date":"2017-09-09T08:30:51","date_gmt":"2017-09-09T14:30:51","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=1680"},"modified":"2021-08-19T07:51:55","modified_gmt":"2021-08-19T05:51:55","slug":"fruits","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/","title":{"rendered":"Le go\u00fbt des fruits qu&#8217;on trouve sur le chemin"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: left;\">J\u2019ai le souvenir d\u2019exp\u00e9riences jouissives avec les fruits. Ce ne sont pas ceux que j\u2019aurais pu trouver sur le march\u00e9, ou qu\u2019on m\u2019aurait fait go\u00fbter. Ce sont les fruits que j\u2019ai pu trouver en me promenant, par hasard. Les prunes au bord d\u2019un verger entre deux villages du Gers, sur une route \u00e9cras\u00e9e de chaleur. Les figues de barbarie dans une ruelle d\u2019une petite ville des Causses du Quercy, que j\u2019ai h\u00e9sit\u00e9 \u00e0 prendre, les pommes d\u2019un hameau de la montagne noire.<\/p>\n<p style=\"text-align: left;\">Ces fruits l\u00e0 ont le go\u00fbt d\u2019un cadeau inattendu, comme quand un visage familier surgit d\u2019un lieu et nous l\u2019\u00e9gaye pour quelques secondes. Ils ont le go\u00fbt de la sueur de la marche qui ne sait pas quand elle finira. Ils ne sont plus des produits consomm\u00e9s pour satisfaire un plaisir, ils sont un \u00e9v\u00e9nement, attach\u00e9s \u00e0 un lieu, au vent qui soufflait ce jour-l\u00e0, au chant des cigales ou au bruissement des feuilles sous les pieds. Ces fruits-l\u00e0, on les mange toujours en riant. On se sent privil\u00e9gi\u00e9. On retrouve le plaisir d\u2019avoir les doigts qui collent.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1684 alignright\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21-225x300.jpg\" alt=\"fruits2\" width=\"225\" height=\"300\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21-225x300.jpg 225w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21-113x150.jpg 113w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21-768x1024.jpg 768w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21-600x800.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits21.jpg 864w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Ils ont surtout le go\u00fbt d\u2019une saison. Il y a une jouissance incommensurable \u00e0 retrouver chaque ann\u00e9e un fruit qu\u2019on n\u2019a pas mang\u00e9 pendant dix mois. \u00c0\u00a0 go\u00fbter les premiers et \u00e0 se dire que les suivants seront de plus en plus bons. Quelque chose qui s\u2019apparente \u00e0 l\u2019effervescence des jours de march\u00e9 en montagne, quand tous les habitants descendent dans la vall\u00e9e et convergent vers la m\u00eame place. Ici la rencontre a un go\u00fbt particulier. Celui que n\u2019ont que les choses dont on a ressenti le manque. Le manque, qui est consid\u00e9r\u00e9 comme le mal absolu dans nos soci\u00e9t\u00e9s qui nous vantent les m\u00e9rites de l\u2019abondance. Mais il n\u2019y a d\u2019abondance que dans l\u2019alternance entre le manque et la satisfaction. Si tout m\u2019\u00e9tait disponible en tout temps, je n&#8217;aurais plus de d\u00e9sir. Mon plaisir n\u2019existe que dans un relief.<\/p>\n<p>Une personne travaillant dans une de ces boulangeries devenue institution dans un quartier de grande ville m&#8217;a racont\u00e9 un petit changement apparu r\u00e9cemment. On se mettait \u00e0 refaire des viennoiseries et de p\u00e2tisseries en fin de journ\u00e9e, car les clients venant \u00e0 18h n\u2019\u00e9taient pas satisfaits de ne plus trouver la tarte mirabelle, et ne pouvait se r\u00e9soudre \u00e0 prendre une tarte abricot. De ce fait, au lieu de finir la journ\u00e9e avec tr\u00e8s peu de restes, assez peu pour pouvoir les partager entre les employ\u00e9s, la boulangerie finissait avec une vitrine remplie comme aux heures de pointe.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4.png\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1685 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4-300x200.png\" alt=\"fruits4\" width=\"300\" height=\"200\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4-300x200.png 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4-150x100.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4-600x401.png 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4-440x293.png 440w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/fruits4.png 623w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ce m\u00e9canisme, nous le mettons en place pour satisfaire cet enfant que nous avons tous crois\u00e9 dans un rayon de magasin, celui qui crie en \u00e9tirant la main\u00a0: \u00ab\u00a0 Je veux\u2026 ! Je veux\u2026 ! Je veux\u2026 !\u00a0\u00bb Cet enfant-l\u00e0 ne conna\u00eetra pas le plaisir de ratisser la derni\u00e8re tartelette du rayon, ni celui de l\u2019enfant derri\u00e8re lui qui devra go\u00fbter \u00e0 quelque chose de nouveau.<\/p>\n<p>Quelle esp\u00e8ce de temps plat avons-nous invent\u00e9 qui rend tout ce que nous mangeons disponible \u00e0 tout moment, qui le d\u00e9connecte d\u2019un cycle au sein duquel le travail de l\u2019homme prend tout son sens, et qui, en nous faisant croire qu\u2019il nous comble, tue en nous le d\u00e9sir ? Il serait peut-\u00eatre temps pour nous de retrouver le manque, pour savoir jouir \u00e0 nouveau.<\/p>\n<p>Sarah Roubato a publi\u00e9 :<\/p>\n<p><a href=\"http:\/\/www.michel-lafon.fr\/livre\/1687-Lettres_a_ma_generation.html\"><em><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1091  alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-103x150.jpg\" alt=\"livre sarah\" width=\"129\" height=\"188\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-103x150.jpg 103w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-205x300.jpg 205w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah.jpg 341w\" sizes=\"auto, (max-width: 129px) 100vw, 129px\" \/><\/em><\/a>Cliquez <strong><a href=\"https:\/\/mrmondialisation.org\/sarah-roubato-lettres-a-ma-generation\/\" target=\"_blank\" rel=\"noopener noreferrer\">ici\u00a0<\/a><\/strong>pour en savoir plus et lire des extraits. Cliquez sur le livre pour le commander directement chez l&#8217;\u00e9diteur ou commandez-le dans n&#8217;importe quelle librairie<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/oeuvres\/trouveleverbesonore\/\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-2348  alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg\" alt=\"\" width=\"142\" height=\"219\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg 662w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-97x150.jpg 97w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-194x300.jpg 194w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-600x928.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse.jpg 779w\" sizes=\"auto, (max-width: 142px) 100vw, 142px\" \/><\/a><\/p>\n<p>Cliquez\u00a0<strong><a href=\"https:\/\/dev.sarahroubato.com\/acheter\/trouveleverbe\/\">ici\u00a0<\/a><\/strong>pour commander le livre (6.50 euros) chez l&#8217;\u00e9diteur ou commandez-le dans n&#8217;importe quelle librairie.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 649px; left: 507px;\">Enregistrer<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>J\u2019ai le souvenir d\u2019exp\u00e9riences jouissives avec les fruits. Ce ne sont pas ceux que j\u2019aurais pu trouver sur le march\u00e9, ou qu\u2019on m\u2019aurait fait go\u00fbter. Ce sont les fruits que j\u2019ai pu trouver en me promenant, par hasard. Les prunes au bord d\u2019un verger entre deux villages du Gers, sur une route \u00e9cras\u00e9e de chaleur. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[27,12,478],"class_list":["post-1680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive","tag-consommation","tag-nature","tag-saison"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le go\u00fbt des fruits qu&#039;on trouve sur le chemin - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le go\u00fbt des fruits qu&#039;on trouve sur le chemin - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"J\u2019ai le souvenir d\u2019exp\u00e9riences jouissives avec les fruits. Ce ne sont pas ceux que j\u2019aurais pu trouver sur le march\u00e9, ou qu\u2019on m\u2019aurait fait go\u00fbter. Ce sont les fruits que j\u2019ai pu trouver en me promenant, par hasard. Les prunes au bord d\u2019un verger entre deux villages du Gers, sur une route \u00e9cras\u00e9e de chaleur. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-09T14:30:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-19T05:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/le-go\u00fbt-des-fruits-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/le-go\u00fbt-des-fruits-scaled.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/le-go\u00fbt-des-fruits-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/\",\"name\":\"Le go\u00fbt des fruits qu'on trouve sur le chemin - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#primaryimage\"},\"datePublished\":\"2017-09-09T14:30:51+00:00\",\"dateModified\":\"2021-08-19T05:51:55+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le go\u00fbt des fruits qu&#8217;on trouve sur le chemin\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le go\u00fbt des fruits qu'on trouve sur le chemin - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/","og_locale":"es_ES","og_type":"article","og_title":"Le go\u00fbt des fruits qu'on trouve sur le chemin - Sarah Roubato","og_description":"J\u2019ai le souvenir d\u2019exp\u00e9riences jouissives avec les fruits. Ce ne sont pas ceux que j\u2019aurais pu trouver sur le march\u00e9, ou qu\u2019on m\u2019aurait fait go\u00fbter. Ce sont les fruits que j\u2019ai pu trouver en me promenant, par hasard. Les prunes au bord d\u2019un verger entre deux villages du Gers, sur une route \u00e9cras\u00e9e de chaleur. [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2017-09-09T14:30:51+00:00","article_modified_time":"2021-08-19T05:51:55+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/le-go\u00fbt-des-fruits-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/le-go\u00fbt-des-fruits-scaled.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/le-go\u00fbt-des-fruits-scaled.jpg","width":1920,"height":2560},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/","name":"Le go\u00fbt des fruits qu'on trouve sur le chemin - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#primaryimage"},"datePublished":"2017-09-09T14:30:51+00:00","dateModified":"2021-08-19T05:51:55+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/fruits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Le go\u00fbt des fruits qu&#8217;on trouve sur le chemin"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=1680"}],"version-history":[{"count":10,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1680\/revisions"}],"predecessor-version":[{"id":5434,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1680\/revisions\/5434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/5421"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=1680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=1680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=1680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}