
{"id":1722,"date":"2017-09-24T06:19:35","date_gmt":"2017-09-24T04:19:35","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=1722"},"modified":"2020-05-14T18:08:57","modified_gmt":"2020-05-14T16:08:57","slug":"chezsoi","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/","title":{"rendered":"Qu&#8217;est-ce qu&#8217;un chez soi ?"},"content":{"rendered":"<p><strong><em>Quand les petites impressions r\u00e9v\u00e8lent les grandes questions\u2026 voici quelques sc\u00e8nes r\u00e9colt\u00e9es en parcourant une France qui ne se montre ni dans les journaux ni sur les guides touristiques, et qui nous racontent quelque chose sur l&#8217;humain auquel nous participons, et celui qu&#8217;il nous reste \u00e0 inventer.\u00a0<a href=\"http:\/\/paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1605 size-large\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/06\/Capture-d\u2019e\u0301cran-2017-06-04-a\u0300-11.54.49-1024x205.png\" alt=\"Capture d\u2019e\u0301cran 2017-06-04 a\u0300 11.54.49\" width=\"1024\" height=\"205\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/06\/Capture-d\u2019e\u0301cran-2017-06-04-a\u0300-11.54.49-1024x205.png 1024w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/06\/Capture-d\u2019e\u0301cran-2017-06-04-a\u0300-11.54.49-150x30.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/06\/Capture-d\u2019e\u0301cran-2017-06-04-a\u0300-11.54.49-300x60.png 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/06\/Capture-d\u2019e\u0301cran-2017-06-04-a\u0300-11.54.49-600x120.png 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/06\/Capture-d\u2019e\u0301cran-2017-06-04-a\u0300-11.54.49.png 1168w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/em><\/strong>Je crois avoir pass\u00e9 bien plus de la moiti\u00e9 de ma vie d\u2019adulte \u00e0 vivre chez les autres. J\u2019ai v\u00e9cu dans des maisons somptueuses avec du marbre partout, dans des vieilles b\u00e2tisses de campagne, des petits appartements de banlieue, des studios d\u2019\u00e9tudiants. Des inconnus m\u2019ont fait go\u00fbt\u00e9 un peu de leur chez soi. Mais qu\u2019est-ce qui fait qu\u2019un lieu de vie devient un chez soi ?<\/p>\n<p>Pour beaucoup, un chez soi est l\u2019accomplissement d\u2019une \u0153uvre. De murs b\u00e2tis, de meubles polis, d\u2019objets choisis. Pour certains, chez soi c\u2019est la terre qu\u2019on cultive, qu\u2019on laboure, qui nous nourrit. Pour d\u2019autres encore, c\u2019est un petit nid, un cocon qui accueille les ann\u00e9es de doute, de recherche ou de partage. Pour la plupart, c\u2019est un lieu de souvenirs et de projections. C\u2019est l\u00e0 que s\u2019installent les \u00e9v\u00e9nements qui font de nous ce que nous sommes.<\/p>\n<p>Mais il y en a pour qui un chez soi n\u2019est ni une \u0153uvre, ni un coin de terre, ni un lieu de souvenirs. Un endroit qui n\u2019a m\u00eame pas n\u00e9cessairement l\u2019apparence d\u2019une maison. Qui est simplement un refuge. Un lieu o\u00f9 quelque chose de moi se d\u00e9pose. O\u00f9 on se sent en s\u00e9curit\u00e9. Un endroit qui nous autorise \u00e0 \u00eatre complet. Comme un pianiste devant ses quatre-vingt huit touches.<a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/maison-japon.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1725\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/maison-japon-300x200.jpg\" alt=\"maison japon\" width=\"300\" height=\"200\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/maison-japon-300x200.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/maison-japon-150x100.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/maison-japon.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/maison-japon-440x293.jpg 440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Il y eut plusieurs fois par semaine pendant quelques ann\u00e9es, le coin d\u2019une table dans un dr\u00f4le de quartier de Montr\u00e9al. Un appartement toujours calme, o\u00f9 je venais d\u00e9poser pr\u00e8s d\u2019un caf\u00e9 br\u00fblant mes doutes, mes coups de gueule, mes espoirs et mes d\u00e9ceptions. \u00c0 vif. Il y eut un bol en bois de noyer retourn\u00e9 qui me tenait lieu de si\u00e8ge, devant le feu d\u2019une pi\u00e8ce toute en terre couverte de suie, avec les yeux espi\u00e8gles de celle qui fut ma forteresse dans un village du Haut Atlas. Et puis il y eut un coin de for\u00eat en Ontario, dans une r\u00e9serve naturelle, au bout d\u2019un lac qui devient presque mar\u00e9cage, un tapis de mousse o\u00f9 je m\u2019endormais \u00e0 chaque fois que je suis revenue.<\/p>\n<p>Depuis, je cherche cette for\u00eat dans toutes les for\u00eats que je parcours. Et je ne trouve pas. Je cherche dans toutes les tasses de caf\u00e9 pos\u00e9es sur une table de quoi m\u2019\u00e9pancher. L\u2019odeur du feu me rappelle celui de cette femme, sans parvenir \u00e0 me r\u00e9chauffer enti\u00e8rement. Un coin de table, une cuisine qui ressemble \u00e0 une grotte, une for\u00eat. Des lieux qui m\u2019habitent plus longtemps que je ne les ai habit\u00e9s. Comme il est des voix qui nous habitent et o\u00f9 on se sent chez soi, avant m\u00eame de savoir \u00e0 qui elles appartiennent. J\u2019ai grandi avec des voix, narrateurs de contes ou de films, chanteurs, dont j\u2019ai d\u00e9couvert bien plus tard qu\u2019ils s\u2019appelaient Jean Toppart, Jacques Brel, Quincy Jones.<\/p>\n<figure id=\"attachment_1724\" aria-describedby=\"caption-attachment-1724\" style=\"width: 200px\" class=\"wp-caption alignright\"><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/R0013970.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1724\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/R0013970-200x300.jpg\" alt=\"Exif_JPEG_PICTURE\" width=\"200\" height=\"300\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/R0013970-200x300.jpg 200w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/R0013970-100x150.jpg 100w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/R0013970-683x1024.jpg 683w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/R0013970-600x900.jpg 600w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><figcaption id=\"caption-attachment-1724\" class=\"wp-caption-text\">Devant son feu, au Maroc.<\/figcaption><\/figure>\n<p>On demande toujours \u00e0 quelqu\u2019un o\u00f9 il habite. Mais r\u00e9sider n\u2019est pas n\u00e9cessairement habiter. Qu\u2019est-ce qu\u2019habiter une maison, habiter le temps, habiter sa vie ? Investir chaque recoin, \u00eatre pr\u00e9sent au lieu, au temps, au mouvement, aux rencontres. Nous vivons dans une soci\u00e9t\u00e9 qui nous apprend \u00e0 acqu\u00e9rir, \u00e0 am\u00e9nager, \u00e0 r\u00e9sider, mais pas \u00e0 habiter.<\/p>\n<p>Quand on voyage l\u2019hiver en campagne, on traverse des villages pleins de maisons d\u00e9sertes. Des r\u00e9sidences secondaires, occup\u00e9es quelques semaines par an. Des maisons, des villages, des coins entiers qui g\u00e9missent de ne pas \u00eatre habit\u00e9s. Pas question de les ouvrir \u00e0 des inconnus qui pourraient les faire vivre. Propri\u00e9t\u00e9 priv\u00e9e.<\/p>\n<p><strong>\u00ab\u00a0<em>Ils n\u2019avaient pas de nom, mais leurs voix m\u2019\u00e9taient aussi r\u00e9elles et intimes que celles de <\/em><em>mes grands-parents. En enfance, les mots ont un autre relief, une autre \u00e9paisseur.<\/em>\u00a0\u00bb (Lettre \u00e0 une cassette, <em>Lettres \u00e0 ma g\u00e9n\u00e9rations, <\/em>ed Michel Lafon)<br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sarah Roubato\u00a0a publi\u00e9<\/p>\n<p><a href=\"https:\/\/lanagedelourse.fr\/Sarah_Roubato01.html\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-2348 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg\" alt=\"couv Nage de l'ourse\" width=\"201\" height=\"310\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-662x1024.jpg 662w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-97x150.jpg 97w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-194x300.jpg 194w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse-600x928.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/12\/couv-Nage-de-lourse.jpg 779w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/p>\n<p><em>Trouve le verbe de ta vie\u00a0<\/em>ed La Nage de l&#8217;Ourse. Cliquez\u00a0<strong>ici\u00a0<\/strong>pour en savoir plus. Cliquez sur le livre pour le commander chez l&#8217;\u00e9diteur.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><a href=\"http:\/\/www.michel-lafon.fr\/livre\/1687-Lettres_a_ma_generation.html\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1091  alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-205x300.jpg\" alt=\"livre sarah\" width=\"158\" height=\"230\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-205x300.jpg 205w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah-103x150.jpg 103w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2016\/02\/livre-sarah.jpg 341w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a>\u00a0 \u00a0Lettres \u00e0 ma g\u00e9n\u00e9ration\u00a0<\/em>ed Michel Lafon.\u00a0Cliquez\u00a0<strong><a href=\"https:\/\/mrmondialisation.org\/sarah-roubato-lettres-a-ma-generation\/\" target=\"_blank\" rel=\"noopener noreferrer\">ici\u00a0<\/a><\/strong>pour en savoir plus et lire des extraits. Cliquez sur le livre pour le commander chez l&#8217;\u00e9diteur.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer;\">Enregistrer<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Quand les petites impressions r\u00e9v\u00e8lent les grandes questions\u2026 voici quelques sc\u00e8nes r\u00e9colt\u00e9es en parcourant une France qui ne se montre ni dans les journaux ni sur les guides touristiques, et qui nous racontent quelque chose sur l&#8217;humain auquel nous participons, et celui qu&#8217;il nous reste \u00e0 inventer.\u00a0Je crois avoir pass\u00e9 bien plus de la moiti\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[153,111],"class_list":["post-1722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive","tag-france","tag-rencontre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu&#039;est-ce qu&#039;un chez soi ? - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;est-ce qu&#039;un chez soi ? - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Quand les petites impressions r\u00e9v\u00e8lent les grandes questions\u2026 voici quelques sc\u00e8nes r\u00e9colt\u00e9es en parcourant une France qui ne se montre ni dans les journaux ni sur les guides touristiques, et qui nous racontent quelque chose sur l&#8217;humain auquel nous participons, et celui qu&#8217;il nous reste \u00e0 inventer.\u00a0Je crois avoir pass\u00e9 bien plus de la moiti\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-24T04:19:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T16:08:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/nest-dina-nargo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/nest-dina-nargo.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/nest-dina-nargo.jpg\",\"width\":718,\"height\":900},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/\",\"name\":\"Qu'est-ce qu'un chez soi ? - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#primaryimage\"},\"datePublished\":\"2017-09-24T04:19:35+00:00\",\"dateModified\":\"2020-05-14T16:08:57+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&#8217;est-ce qu&#8217;un chez soi ?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'est-ce qu'un chez soi ? - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/","og_locale":"es_ES","og_type":"article","og_title":"Qu'est-ce qu'un chez soi ? - Sarah Roubato","og_description":"Quand les petites impressions r\u00e9v\u00e8lent les grandes questions\u2026 voici quelques sc\u00e8nes r\u00e9colt\u00e9es en parcourant une France qui ne se montre ni dans les journaux ni sur les guides touristiques, et qui nous racontent quelque chose sur l&#8217;humain auquel nous participons, et celui qu&#8217;il nous reste \u00e0 inventer.\u00a0Je crois avoir pass\u00e9 bien plus de la moiti\u00e9 [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2017-09-24T04:19:35+00:00","article_modified_time":"2020-05-14T16:08:57+00:00","og_image":[{"width":718,"height":900,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/nest-dina-nargo.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/nest-dina-nargo.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2017\/09\/nest-dina-nargo.jpg","width":718,"height":900},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/","name":"Qu'est-ce qu'un chez soi ? - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#primaryimage"},"datePublished":"2017-09-24T04:19:35+00:00","dateModified":"2020-05-14T16:08:57+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/chezsoi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Qu&#8217;est-ce qu&#8217;un chez soi ?"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=1722"}],"version-history":[{"count":7,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1722\/revisions"}],"predecessor-version":[{"id":4368,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/1722\/revisions\/4368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/1723"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=1722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=1722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=1722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}