
{"id":2477,"date":"2018-06-10T02:00:03","date_gmt":"2018-06-10T00:00:03","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=2477"},"modified":"2021-04-12T15:15:03","modified_gmt":"2021-04-12T13:15:03","slug":"avorte","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/","title":{"rendered":"Rencontres avort\u00e9es : serrer la main \u00e0 l&#8217;\u00e9chec"},"content":{"rendered":"<p>On m\u2019a dit que c\u2019\u00e9tait \u00e0 vingt minutes. C\u2019\u00e9tait \u00e0 une heure de route. On m\u2019a dit que c\u2019\u00e9tait \u00e0 droite : c\u2019\u00e9tait en face. La nuit va bient\u00f4t tomber. Je n\u2019aurai pas le temps d\u2019aller jusqu\u2019au bout. Si j\u2019\u00e9tais partie une heure plus t\u00f4t\u2026 J\u2019attends de trouver le point o\u00f9 je vais d\u00e9cider de faire demi tour.<\/p>\n<p><a href=\"http:\/\/paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-2631 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/06\/Capture-d\u2019e\u0301cran-2018-07-31-a\u0300-15.49.59.png\" alt=\"Capture d\u2019e\u0301cran 2018-07-31 a\u0300 15.49.59\" width=\"702\" height=\"306\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/06\/Capture-d\u2019e\u0301cran-2018-07-31-a\u0300-15.49.59.png 702w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/06\/Capture-d\u2019e\u0301cran-2018-07-31-a\u0300-15.49.59-150x65.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/06\/Capture-d\u2019e\u0301cran-2018-07-31-a\u0300-15.49.59-300x131.png 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/06\/Capture-d\u2019e\u0301cran-2018-07-31-a\u0300-15.49.59-600x262.png 600w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/a><\/p>\n<p>Le maquis n\u2019en finit pas de d\u00e9rouler ses chemins blancs. \u00c0 chaque tournant il me fait croire que la mer va se pointer derri\u00e8re. Mes pas sur les cailloux font un boucan effrayant. J\u2019ai honte pour le silence qui m\u2019entoure. Et pour cet arbre que le paysage ne suit pas dans son \u00e9panchement. Il est isol\u00e9. Mais ici tous les arbres sont isol\u00e9s. Je m\u2019approche. Son tronc est calcin\u00e9. S\u00fbrement l\u2019incendie de l\u2019\u00e9t\u00e9 dernier. Ses feuilles affichent pourtant leur vert printanier, comme si de rien n\u2019\u00e9tait. Ce sera d\u2019ici que je ferai demi tour.<\/p>\n<p>Je<img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-2481 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996-1024x616.jpg\" alt=\"mujer-en-la-lluvia,-pista,-la-estacion-de-tren-187996\" width=\"429\" height=\"258\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996-1024x616.jpg 1024w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996-150x90.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996-300x180.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996-600x361.jpg 600w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996.jpg 1600w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/> repars sans avoir vu la mer. Comme je suis repartie tant de fois en ayant manqu\u00e9 une rencontre. Parce qu\u2019arriv\u00e9e un peu trop tard, beaucoup trop t\u00f4t, ou bien trop vite. Parce que l\u2019autre n\u2019avait pas le temps de se poser, d\u2019\u00e9couter, de regarder par-dessus mon \u00e9paule, si des fois il n\u2019y avait pas un petit bout de chemin qu\u2019on aurait pu suivre ensemble. Ou peut-\u00eatre qu&#8217;il avait le temps, et que\u00a0je n&#8217;avais tout simplement pas assez d&#8217;importance pour lui. Les rencontres ressemblent \u00e0 une aum\u00f4ne que l\u2019autre me fait entre deux urgences. Il n\u2019a pas le temps pour quelques pas, ni pour un caf\u00e9, ni pour une cr\u00e8me glac\u00e9e. D\u00e9j\u00e0 engag\u00e9 sur des rails qui ne s\u2019arr\u00eatent pas dans ma gare. Et puis les chiens qui bavent trop fort quand ils ont\u00a0soif, on s&#8217;en m\u00e9fie.<\/p>\n<p>Il est tr\u00e8s mal \u00e9lev\u00e9 de\u00a0dire aux gens qu&#8217;ils comptent pour nous. \u00a0Je glisse sur les cailloux comme sur les malentendus. Je vois les traces de ceux qui sont venus au bon moment. Il y en aura toujours pour qui les chemins finissent par mener quelque part. Tant mieux.<\/p>\n<p>\u00ab\u00a0Mais tu vas toujours quelque part\u00a0!\u00a0Si \u00e7a n\u2019est pas arriv\u00e9 c\u2019est que \u00e7a ne devait pas se faire. Et puis tu sais, si tu ne mets pas les bonnes intentions\u2026\u00a0\u00bb\u00a0Heureusement il y en a toujours pour nous rappeler que tout d\u00e9pend de nous. De quoi se rassurer. Il n\u2019y a pas de poisse, il n\u2019y a que de mauvaises \u00e9nergies. Ceux qui envoient de bonnes ondes sont r\u00e9compens\u00e9s. Le monde est pas mal foutu, finalement.\u00a0Alors le petit gar\u00e7on \u00e9chou\u00e9 sur une plage turque, il n\u2019a pas envoy\u00e9 de bonnes ondes ?\u00a0Mais non, c\u2019est pas pareil, l\u00e0 tu prends un exemple extr\u00eame\u00a0!<\/p>\n<p>Je comprends que ces r\u00e8gles de fonctionnement de l\u2019univers ne s\u2019appliquent pas \u00e0 tous. Seulement \u00e0 ceux qui ont le luxe d\u2019y croire. Tant pis pour ceux dont le bateau n\u2019arrivera pas de l\u2019autre c\u00f4t\u00e9 de la M\u00e9diterran\u00e9e. Tant pis pour ceux qui voient l\u2019obus tomber sur la maison voisine o\u00f9 ils se trouvaient cinq minutes plus t\u00f4t.\u00a0Cette nouvelle croyance place l&#8217;individu au centre de tout. Rien d&#8217;\u00e9tonnant dans une culture o\u00f9 il\u00a0assiste \u00e0 sa perte de puissance tout en restant l&#8217;\u00e9talon r\u00e9f\u00e9rent.<a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/mujer-en-la-lluvia-pista-la-estacion-de-tren-187996.jpg\"><br \/>\n<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-2483 alignright\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.42.png\" alt=\"Capture d\u2019e\u0301cran 2018-05-30 a\u0300 00.11.42\" width=\"420\" height=\"216\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.42.png 420w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.42-150x77.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.42-300x154.png 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/>Imaginez un peu, si \u00e7a n\u2019\u00e9tait pas le cas. S\u2019il suffisait d\u2019un peu de l\u2019indiff\u00e9rence des uns, de la paresse des autres, de l\u2019inconstance de tous, d\u2019un contexte social hostile, d\u2019encha\u00eenements malheureux de circonstances. Ce serait insupportable. Je d\u00e9teste les jeux o\u00f9 je ne suis pas responsable de ma d\u00e9faite.<\/p>\n<p>Depuis quelques ann\u00e9es, j\u2019entends beaucoup parler de longueurs d\u2019onde, de bonnes \u00e9nergies, du pouvoir de l\u2019intention, et du fameux <em>c\u2019est que \u00e7a ne devait pas se faire<\/em>. Un nouveau credo pour ne pas accepter les d\u00e9s\u00e9quilibres du monde. La culture occidentale est si peu attentive aux relations entre les \u00eatres, les choses et les \u00e9v\u00e9nements, que lorsque nous les d\u00e9couvrons enfin, nous voulons en faire un principe absolu. Nous prenons conscience que la mani\u00e8re dont on accueille\u00a0les situations, la fa\u00e7on dont on se pr\u00e9sente, tout cela\u00a0influe sur la mani\u00e8re dont les choses se d\u00e9roulent. Et tr\u00e8s vite on glisse vers une loi o\u00f9 le hasard et l\u2019\u00e9chec n\u2019auraient plus leur place. Alors \u00e0 chaque rendez-vous manqu\u00e9, \u00e0 chaque revers, nous nous disons que <em>c\u2019est que \u00e7a ne devait pas arriver. <\/em>Ou que <em>La Vie t\u2019envoie un message. <\/em>Fut un temps o\u00f9 on parlait de Dieu.<\/p>\n<p>Si je me rends \u00e0 une soir\u00e9e dans un \u00e9tat d\u2019esprit ferm\u00e9, n\u00e9gatif, je n\u2019ai aucune chance de rencontrer la personne qui peut-\u00eatre changera le cours de ma vie. Si je me rends disponible, cela peut arriver. Mais si la personne vient la veille ou le lendemain, si elle part dix minutes avant que j\u2019arrive, je n\u2019y peux rien. Si le soir d&#8217;une \u00e9clipse de lune qui arrive une fois par si\u00e8cle, le ciel est encombr\u00e9 alors que la veille et le lendemain, il sera clair et la lune \u00e9norme, dois-je me dire que c&#8217;est que la lune ne voulait pas que je la voie rougir ?<\/p>\n<p>Je revendique le droit \u00e0 l\u2019\u00e9chec. Quand on \u00e9coute tous\u00a0ceux qui ont r\u00e9ussi \u00e0 vivre ce qu&#8217;ils portaient en eux, ils parlent toujours de rencontres et de chances exceptionnelles sans lesquelles ils n&#8217;auraient pas pu. Nous les oublions, et tout ce qu&#8217;on retient est qu&#8217;il\/elle avait du talent de la volont\u00e9 et de la sueur, et que cela suffit.<\/p>\n<p>De ce que j\u2019ai manqu\u00e9, je ram\u00e8ne des mots. C\u2019est tout ce que je peux. Derri\u00e8re chaque texte il y a toujours le m\u00eame aveu\u00a0: celui de mon impuissance devant ce qui n&#8217;a pas lieu.\u00a0Tant pis si la mer est peut-\u00eatre au prochain tournant.<a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.39.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\" size-large wp-image-2484 alignleft\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.39.png\" alt=\"Capture d\u2019e\u0301cran 2018-05-30 a\u0300 00.11.39\" width=\"436\" height=\"129\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.39.png 436w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.39-150x44.png 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/Capture-d\u2019e\u0301cran-2018-05-30-a\u0300-00.11.39-300x89.png 300w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>On m\u2019a dit que c\u2019\u00e9tait \u00e0 vingt minutes. C\u2019\u00e9tait \u00e0 une heure de route. On m\u2019a dit que c\u2019\u00e9tait \u00e0 droite : c\u2019\u00e9tait en face. La nuit va bient\u00f4t tomber. Je n\u2019aurai pas le temps d\u2019aller jusqu\u2019au bout. Si j\u2019\u00e9tais partie une heure plus t\u00f4t\u2026 J\u2019attends de trouver le point o\u00f9 je vais d\u00e9cider de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rencontres avort\u00e9es : serrer la main \u00e0 l&#039;\u00e9chec - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rencontres avort\u00e9es : serrer la main \u00e0 l&#039;\u00e9chec - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"On m\u2019a dit que c\u2019\u00e9tait \u00e0 vingt minutes. C\u2019\u00e9tait \u00e0 une heure de route. On m\u2019a dit que c\u2019\u00e9tait \u00e0 droite : c\u2019\u00e9tait en face. La nuit va bient\u00f4t tomber. Je n\u2019aurai pas le temps d\u2019aller jusqu\u2019au bout. Si j\u2019\u00e9tais partie une heure plus t\u00f4t\u2026 J\u2019attends de trouver le point o\u00f9 je vais d\u00e9cider de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-10T00:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-12T13:15:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/photos-qui-prouvent-que-nos-grandparents-sont-balaises-jouer-voix-feree.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/photos-qui-prouvent-que-nos-grandparents-sont-balaises-jouer-voix-feree.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/photos-qui-prouvent-que-nos-grandparents-sont-balaises-jouer-voix-feree.jpg\",\"width\":500,\"height\":318},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/\",\"name\":\"Rencontres avort\u00e9es : serrer la main \u00e0 l'\u00e9chec - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#primaryimage\"},\"datePublished\":\"2018-06-10T00:00:03+00:00\",\"dateModified\":\"2021-04-12T13:15:03+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rencontres avort\u00e9es : serrer la main \u00e0 l&rsquo;\u00e9chec\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rencontres avort\u00e9es : serrer la main \u00e0 l'\u00e9chec - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/","og_locale":"es_ES","og_type":"article","og_title":"Rencontres avort\u00e9es : serrer la main \u00e0 l'\u00e9chec - Sarah Roubato","og_description":"On m\u2019a dit que c\u2019\u00e9tait \u00e0 vingt minutes. C\u2019\u00e9tait \u00e0 une heure de route. On m\u2019a dit que c\u2019\u00e9tait \u00e0 droite : c\u2019\u00e9tait en face. La nuit va bient\u00f4t tomber. Je n\u2019aurai pas le temps d\u2019aller jusqu\u2019au bout. Si j\u2019\u00e9tais partie une heure plus t\u00f4t\u2026 J\u2019attends de trouver le point o\u00f9 je vais d\u00e9cider de [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2018-06-10T00:00:03+00:00","article_modified_time":"2021-04-12T13:15:03+00:00","og_image":[{"width":500,"height":318,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/photos-qui-prouvent-que-nos-grandparents-sont-balaises-jouer-voix-feree.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/photos-qui-prouvent-que-nos-grandparents-sont-balaises-jouer-voix-feree.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/05\/photos-qui-prouvent-que-nos-grandparents-sont-balaises-jouer-voix-feree.jpg","width":500,"height":318},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/","name":"Rencontres avort\u00e9es : serrer la main \u00e0 l'\u00e9chec - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#primaryimage"},"datePublished":"2018-06-10T00:00:03+00:00","dateModified":"2021-04-12T13:15:03+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/avorte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Rencontres avort\u00e9es : serrer la main \u00e0 l&rsquo;\u00e9chec"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/2477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=2477"}],"version-history":[{"count":13,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/2477\/revisions"}],"predecessor-version":[{"id":5197,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/2477\/revisions\/5197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/2482"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=2477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=2477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=2477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}