
{"id":2821,"date":"2018-10-06T13:32:35","date_gmt":"2018-10-06T11:32:35","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=2821"},"modified":"2021-04-12T04:07:47","modified_gmt":"2021-04-12T02:07:47","slug":"extrait2","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/acheter\/extrait2\/","title":{"rendered":"Demain, \u00e0 l&#8217;heure des oiseaux migrateurs : extrait du livre \u00ab30 ans dans une heure\u00bb"},"content":{"rendered":"<p>Elle se tord dans le cendrier comme quelqu\u2019un qui vient de recevoir une balle dans le ventre. Elle sautille encore entre mes doigts, et puis s\u2019effondre au milieu des autres.\u00a0Le cendrier est plein. Demain il faudra que je le vide. Demain c&#8217;est dans une heure.<\/p>\n<p>Demain, il n\u2019y aura plus de place dans ma vie pour les r\u00eaveries de balcon. Il y aura le g\u00e9n\u00e9rique de la matinale \u00e0 la radio comme r\u00e9veil, le fond de c\u00e9r\u00e9ales qui aura toute la journ\u00e9e pour coller au fond du bol, le coup de eyeliner sur l\u2019oeil gauche toujours moins bien fait que le droit, le miroir de l\u2019entr\u00e9e qui va retrouver une existence.<\/p>\n<p>Demain je serai la fille de l\u2019appart d\u2019en face. Celle qui n\u2019a pas le temps d\u2019aller sur son balcon, sauf le weekend quand elle re\u00e7oit des amis. Celle qui pr\u00e9pare \u00e0 manger en coin\u00e7ant son t\u00e9l\u00e9phone avec son \u00e9paule. Qui dit <em>Je te rappelle <\/em>mais qui n\u2019a pas le temps de rappeler.<\/p>\n<p>Un agenda, des rendez-vous, des cong\u00e9s, et un chemin \u00e0 prendre tous les matins. Des immeubles et des visages qu\u2019on ne voit pas, t\u00eate baiss\u00e9e dans le couloir des urgences \u00e0 anticiper. Je me demande si les oies traversent le ciel de la m\u00eame mani\u00e8re. Il faudra que je pr\u00e9vienne Madame Jeannine qu\u2019elle trouve quelqu\u2019un d\u2019autre pour l\u2019aider \u00e0 \u00e9tendre son linge les mardis. Les oies devront se trouver d\u2019autres fronts \u00e0 relever. Parce qu\u2019elles finiront bien par la prendre, la route. Il faut bien la prendre un jour. Elles seront juste un peu en retard, c\u2019est tout.<\/p>\n<p>Demain, loin du balcon, \u00e0 l\u2019heure des oiseaux migrateurs, j\u2019aurai les yeux riv\u00e9s sur un \u00e9cran. Le dos vo\u00fbt\u00e9, le cou tendu, les yeux inject\u00e9s de pixels. C\u2019est ainsi que chaque jour je paierai mon ticket d\u2019entr\u00e9e pour le parc d\u2019attraction o\u00f9 j\u2019accepte de passer ma vie.<\/p>\n<p>Cliquez<a href=\"https:\/\/www.leslibraires.fr\/livre\/14412924-30-ans-dans-une-heure-roubato-sarah-publienet\"> i<strong>ci<\/strong><\/a> pour le commander chez un libraire<\/p>\n<div style=\"position: relative; height: 0; padding-bottom: 56.25%;\"><iframe loading=\"lazy\" style=\"position: absolute; width: 100%; height: 100%; left: 0;\" src=\"https:\/\/www.youtube.com\/embed\/GhbnrEuAcA0?ecver=2\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p>Cliquez<a href=\"http:\/\/publie.net\/livre\/30-ans-heure-sarah-roubato\/\"><strong> ici<\/strong><\/a> pour le commander chez l&#8217;\u00e9diteur<\/p>","protected":false},"excerpt":{"rendered":"<p>Elle se tord dans le cendrier comme quelqu\u2019un qui vient de recevoir une balle dans le ventre. Elle sautille encore entre mes doigts, et puis s\u2019effondre au milieu des autres.\u00a0Le cendrier est plein. Demain il faudra que je le vide. Demain c&#8217;est dans une heure. Demain, il n\u2019y aura plus de place dans ma vie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[483],"tags":[],"class_list":["post-2821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acheter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Demain, \u00e0 l&#039;heure des oiseaux migrateurs : extrait du livre &quot;30 ans dans une heure&quot; - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demain, \u00e0 l&#039;heure des oiseaux migrateurs : extrait du livre &quot;30 ans dans une heure&quot; - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Elle se tord dans le cendrier comme quelqu\u2019un qui vient de recevoir une balle dans le ventre. Elle sautille encore entre mes doigts, et puis s\u2019effondre au milieu des autres.\u00a0Le cendrier est plein. Demain il faudra que je le vide. Demain c&#8217;est dans une heure. Demain, il n\u2019y aura plus de place dans ma vie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-06T11:32:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-12T02:07:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/10\/leman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/10\/leman.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/10\/leman.jpg\",\"width\":750,\"height\":562},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/\",\"name\":\"Demain, \u00e0 l'heure des oiseaux migrateurs : extrait du livre \\\"30 ans dans une heure\\\" - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#primaryimage\"},\"datePublished\":\"2018-10-06T11:32:35+00:00\",\"dateModified\":\"2021-04-12T02:07:47+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demain, \u00e0 l&rsquo;heure des oiseaux migrateurs : extrait du livre \u00ab\u00a030 ans dans une heure\u00a0\u00bb\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demain, \u00e0 l'heure des oiseaux migrateurs : extrait du livre \"30 ans dans une heure\" - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/","og_locale":"es_ES","og_type":"article","og_title":"Demain, \u00e0 l'heure des oiseaux migrateurs : extrait du livre \"30 ans dans une heure\" - Sarah Roubato","og_description":"Elle se tord dans le cendrier comme quelqu\u2019un qui vient de recevoir une balle dans le ventre. Elle sautille encore entre mes doigts, et puis s\u2019effondre au milieu des autres.\u00a0Le cendrier est plein. Demain il faudra que je le vide. Demain c&#8217;est dans une heure. Demain, il n\u2019y aura plus de place dans ma vie [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2018-10-06T11:32:35+00:00","article_modified_time":"2021-04-12T02:07:47+00:00","og_image":[{"width":750,"height":562,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/10\/leman.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/10\/leman.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2018\/10\/leman.jpg","width":750,"height":562},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#webpage","url":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/","name":"Demain, \u00e0 l'heure des oiseaux migrateurs : extrait du livre \"30 ans dans une heure\" - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#primaryimage"},"datePublished":"2018-10-06T11:32:35+00:00","dateModified":"2021-04-12T02:07:47+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/acheter\/extrait2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Demain, \u00e0 l&rsquo;heure des oiseaux migrateurs : extrait du livre \u00ab\u00a030 ans dans une heure\u00a0\u00bb"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/2821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=2821"}],"version-history":[{"count":7,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/2821\/revisions"}],"predecessor-version":[{"id":5148,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/2821\/revisions\/5148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/2824"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=2821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=2821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=2821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}