
{"id":307,"date":"2015-06-09T15:52:35","date_gmt":"2015-06-09T15:52:35","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=307"},"modified":"2020-05-14T18:27:30","modified_gmt":"2020-05-14T16:27:30","slug":"telephone","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/","title":{"rendered":"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ?"},"content":{"rendered":"<p><a href=\"https:\/\/www.paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1026 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg\" alt=\"mafalda9\" width=\"300\" height=\"214\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-150x107.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9.jpg 378w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00ab\u00a0Tu n\u2019as pas re\u00e7u mon texto\u00a0?<\/p>\n<p>&#8211; Je n\u2019ai pas de cellulaire, alors je ne peux pas recevoir de textos.<\/p>\n<p>&#8211; T\u2019as pas de cell\u00a0?<\/p>\n<p>&#8211; Eh non. Et pas de t\u00e9l\u00e9\u00a0non plus. Mais je vais tr\u00e8s bien, tu sais. \u00bb<\/p>\n<p>Stupeur. Aurions-nous affaire \u00e0 un vieux r\u00e9actionnaire aigri et nostalgique, ou \u00e0 un de ces jeunes aux cheveux longs qui partent vivre en nature\u00a0? Il faut que ce soit un original en tous cas, un d\u00e9cal\u00e9. Voil\u00e0 ce qui vient tout de suite \u00e0 l\u2019esprit, tant la pression sociale exige qu\u2019un individu normalement constitu\u00e9 soit en possession d\u2019un cellulaire. Avoir un cellulaire devient un rite de passage pour un enfant.<\/p>\n<p>On lit bien des \u00e9tudes sur les cons\u00e9quences des nouvelles technologies sur notre sant\u00e9 et sur nos habitudes sociologiques, on voit bien des reportages sur ses d\u00e9rives. Mais difficile de se sentir concern\u00e9\u00a0: moi je sais ce que je fais, moi je suis mod\u00e9r\u00e9, et de toute fa\u00e7on, moi je n\u2019ai pas le choix. Et puis on conna\u00eet le refrain\u00a0: \u00e0 chaque \u00e9poque les hommes ont eu peur des nouvelles technologies et pr\u00e9disaient la fin du monde.<\/p>\n<p>Pourtant il y a une diff\u00e9rence fondamentale entre nos t\u00e9l\u00e9phones, iphones, tablettes, et le gramophone, le t\u00e9l\u00e9gramme\u00a0ou l\u2019appareil photographique : chacun de ces nouveaux appareils est simultan\u00e9ment un appareil de communication <em>et <\/em>un appareil de projection de sa propre image. En touchant \u00e0 notre langage et \u00e0 notre image, il fait partie de la construction d\u2019un individu.<\/p>\n<p>Dans le mouvement de ceux qui cherchent \u00e0 sortir du mode de vie dict\u00e9 par le consum\u00e9risme lib\u00e9ral, on trouve des originaux qui partent voyager avec un dollar par jour, d\u2019autres qui n\u2019utilisent que de la technologie des ann\u00e9es quatre-vingt, d\u2019autres encore qui vont vivre dans des villages \u00e9colo. On sourit, c\u2019est cocasse. Mais ces exp\u00e9riences radicales se situent \u00e0 des ann\u00e9es lumi\u00e8re de nos vies, et en attendant, rien ne change pour la majorit\u00e9.<\/p>\n<p>Il existe pourtant un changement plus petit, plus intime, plus humble peut-\u00eatre, \u00e0 la port\u00e9e de tous\u00a0: adapter notre usage de ces technologies. Et pour cela, nul besoin de guide spirituel. Je d\u00e9cide d\u2019\u00e9vacuer tous les plaisirs qui m\u2019asservissent, et de ne plus chercher que le plaisir dans ma libert\u00e9. \u00c0 partir de l\u00e0, mon utilisation des technologies ne suit plus qu\u2019un seul principe. Ce principe est simple, mais il est \u00e0 appliquer dans chaque utilisation\u00a0: <em>Je n\u2019utilise une technologie que si elle ne parasite pas ma rencontre directe avec un lieu, un objet, une id\u00e9e ou une personne.<\/em><\/p>\n<p>Faisons donc une exp\u00e9rience de pens\u00e9e, en prenant deux usages du t\u00e9l\u00e9phone\u00a0: la communication et l\u2019image.<\/p>\n<p><strong>Un t\u00e9l\u00e9phone au service de mon intelligence<br \/>\n<\/strong><\/p>\n<p>Mon t\u00e9l\u00e9phone cellulaire me permet d\u2019\u00eatre joignable non pas en tout temps, mais aux temps o\u00f9 je le souhaite. Si je retrouve un ami dans un caf\u00e9, le t\u00e9l\u00e9phone est \u00e9teint, au fond de mon sac. Et m\u00eame s\u2019il se mettait \u00e0 sonner, je n\u2019interromprai pas ma conversation pour dire \u00e0 quelqu\u2019un \u00ab\u00a0Ouais salut, je peux te rappeler plus tard\u00a0?\u00a0\u00bb Une urgence\u00a0? Si c\u2019est une urgence, je le saurai bien assez vite.<\/p>\n<p>Dans le m\u00e9tro, gr\u00e2ce \u00e0 mon t\u00e9l\u00e9phone je peux \u00e9couter de la musique, une \u00e9mission de radio, lire des articles. Le transport est peut-\u00eatre le seul moment de la journ\u00e9e o\u00f9 je me retrouve avec moi-m\u00eame. Et on voudrait me l\u2019enlever avec des cases, des boules de couleurs et des courses, tous ces jeux sur t\u00e9l\u00e9phone pour combler le vide, pour m\u2019emp\u00eacher de m\u2019\u00e9vader, ou tout simplement, de suivre le flot de mes pens\u00e9es\u00a0? Non merci, je ne consomme que des plaisirs \u00e9lev\u00e9s en libert\u00e9.<\/p>\n<p>Mon t\u00e9l\u00e9phone n\u2019est pas intelligent. (Ah bon\u00a0?) Non, il n\u2019est pas dou\u00e9 d\u2019intelligibilit\u00e9 (Comment \u00e7a\u00a0?). Mon t\u00e9l\u00e9phone ne comprend rien. (Pourtant\u2026) Mon t\u00e9l\u00e9phone ne fait que r\u00e9agir \u00e0 ce que je lui dicte. (Bah \u00e7a alors\u00a0!).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Une photo qui me rappelle un moment v\u00e9cu<br \/>\n<\/strong><\/p>\n<p>Les photographes professionnels sont avant tout de grands observateurs, tr\u00e8s attentifs et enti\u00e8rement pr\u00e9sents l\u00e0 o\u00f9 ils sont. Leur appareil photo est le prolongement de leur rencontre avec un lieu.<\/p>\n<p>Je suis en vacances. Je visite un des plus beaux monuments au monde, une cath\u00e9drale. Je prends le temps de rencontrer ce lieu, d\u2019y \u00eatre pr\u00e9sent, de sentir la pierre, d\u2019\u00e9couter l\u2019\u00e9cho des voix, d\u2019admirer les reliefs. Je ne brandis pas mon objectif pour saisir la beaut\u00e9 plastique qui figure sur toutes les cartes postales de la boutique \u00e0 souvenirs.<\/p>\n<p>Me voici devant un paysage magnifique. Lac, montagnes, for\u00eat. Je veux vivre ce paysage, me sentir dedans. Je m\u00e9dite, j\u2019admire, je reste disponible. Je ne laisserai pas l\u2019appareil interrompre cette rencontre, je ne prendrai une photo que si elle prolonge ma rencontre avec le paysage ou le monument. Alors quand je la regarderai, elle me rappellera ce moment que j\u2019aurais v\u00e9cu. Elle me rappellera le vent sur ma peau ce jour-l\u00e0, le chant dans la cath\u00e9drale. La photo sera un pont vers le lieu que j\u2019aurais rencontr\u00e9, pas un mur pour le cacher.<\/p>\n<p><strong>\u00ab\u00a0Cette esp\u00e8ce de petite libert\u00e9\u00a0\u00bb<br \/>\n<\/strong><\/p>\n<p>Ainsi le t\u00e9l\u00e9phone connect\u00e9 \u00e0 internet me permet de rencontrer des choses, des lieux, des objets, des id\u00e9es, des personnes, qui d\u00e9passent le point de l\u2019espace-temps o\u00f9 je me trouve. Mais jamais il ne me retire \u00e0 la pr\u00e9sence aux \u00eatres et aux choses ici et maintenant. En tout temps je pr\u00e9f\u00e8re la pr\u00e9sence\u00a0: je choisis d\u2019entendre la voix d\u2019un ami plut\u00f4t que de communiquer par messages silencieux en permanence.<\/p>\n<p>La simple recherche du plaisir d\u2019exister aux autres et au monde peut nous amener \u00e0 couper le son lors des publicit\u00e9s et \u00e0 \u00e9teindre le cellulaire sans s\u2019inqui\u00e9ter d\u2019avoir manqu\u00e9 un appel dont la bo\u00eete vocale se chargera tr\u00e8s bien. Par ces petits gestes, je me d\u00e9sintoxique, je nettoie mon espace personnel pour mieux l\u2019ouvrir au monde qui m\u2019entoure. Et en faisant cela, je ne me prive de rien, au contraire. Je m\u2019offre davantage de plaisirs, car j\u2019aurai toujours plus de plaisir \u00e0 \u00eatre totalement pr\u00e9sent dans une conversation ou un voyage qu\u2019\u00e0 n\u2019y \u00eatre que par intermittence. Je m\u2019applique \u00e0 cultiver une micror\u00e9sistance. Elle consiste \u00e0 inverser mon rapport aux technologies\u00a0: ce sont elles qui me servent, elles servent ma libert\u00e9 et mon plaisir d\u2019apprendre, de communiquer, de d\u00e9couvrir. J\u2019y travaille d\u00e8s maintenant, car demain viendront les lunettes google, les t\u00e9l\u00e9phones incorpor\u00e9s, les objets connect\u00e9s.<\/p>\n<p>Dans une entrevue de Claude Santelli en 1969, Georges Brassens, interrog\u00e9 sur ce qu\u2019il pense du monde qui se dessine, exprime sa peur de perdre \u00ab\u00a0cette esp\u00e8ce de petite libert\u00e9 de penser tout seul\u00a0\u00bb. C\u2019est elle qui est en jeu dans nos petits gestes. Elle est pas bien grande, cette libert\u00e9, \u00e7a n\u2019est pas celle qui est \u00e9crite dans les grands discours politiques et dans certaines devises. Humble comme ce grand homme, elle est peut-\u00eatre ce qui nous est \u00e0 la fois le plus fragile et le plus n\u00e9cessaire.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.mixcloud.com\/widget\/iframe\/?hide_cover=1&amp;light=1&amp;feed=%2FSarahRoubato%2Fbrassens-cette-esp%C3%A8ce-de-petite-libert%C3%A9%2F\" width=\"100%\" height=\"120\" frameborder=\"0\"><\/iframe><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 36px; left: 226px;\">Enregistrer<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Tu n\u2019as pas re\u00e7u mon texto\u00a0? &#8211; Je n\u2019ai pas de cellulaire, alors je ne peux pas recevoir de textos. &#8211; T\u2019as pas de cell\u00a0? &#8211; Eh non. Et pas de t\u00e9l\u00e9\u00a0non plus. Mais je vais tr\u00e8s bien, tu sais. \u00bb Stupeur. Aurions-nous affaire \u00e0 un vieux r\u00e9actionnaire aigri et nostalgique, ou \u00e0 un de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[27,28,481],"class_list":["post-307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive","tag-consommation","tag-liberte","tag-technologies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ? - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ? - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0Tu n\u2019as pas re\u00e7u mon texto\u00a0? &#8211; Je n\u2019ai pas de cellulaire, alors je ne peux pas recevoir de textos. &#8211; T\u2019as pas de cell\u00a0? &#8211; Eh non. Et pas de t\u00e9l\u00e9\u00a0non plus. Mais je vais tr\u00e8s bien, tu sais. \u00bb Stupeur. Aurions-nous affaire \u00e0 un vieux r\u00e9actionnaire aigri et nostalgique, ou \u00e0 un de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-09T15:52:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T16:27:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/manger-ipod.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"989\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/manger-ipod.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/manger-ipod.jpg\",\"width\":780,\"height\":989},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/\",\"name\":\"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ? - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#primaryimage\"},\"datePublished\":\"2015-06-09T15:52:35+00:00\",\"dateModified\":\"2020-05-14T16:27:30+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ? - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/","og_locale":"es_ES","og_type":"article","og_title":"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ? - Sarah Roubato","og_description":"\u00ab\u00a0Tu n\u2019as pas re\u00e7u mon texto\u00a0? &#8211; Je n\u2019ai pas de cellulaire, alors je ne peux pas recevoir de textos. &#8211; T\u2019as pas de cell\u00a0? &#8211; Eh non. Et pas de t\u00e9l\u00e9\u00a0non plus. Mais je vais tr\u00e8s bien, tu sais. \u00bb Stupeur. Aurions-nous affaire \u00e0 un vieux r\u00e9actionnaire aigri et nostalgique, ou \u00e0 un de [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-06-09T15:52:35+00:00","article_modified_time":"2020-05-14T16:27:30+00:00","og_image":[{"width":780,"height":989,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/manger-ipod.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/manger-ipod.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/manger-ipod.jpg","width":780,"height":989},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/","name":"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ? - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#primaryimage"},"datePublished":"2015-06-09T15:52:35+00:00","dateModified":"2020-05-14T16:27:30+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/telephone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Les nouvelles technologies et notre petite libert\u00e9 : comment apprendre \u00e0 \u00e9teindre son t\u00e9l\u00e9phone ?"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=307"}],"version-history":[{"count":7,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/307\/revisions"}],"predecessor-version":[{"id":4379,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/307\/revisions\/4379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/408"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}