
{"id":314,"date":"2015-01-15T16:09:11","date_gmt":"2015-01-15T22:09:11","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=314"},"modified":"2020-05-14T18:31:41","modified_gmt":"2020-05-14T16:31:41","slug":"charlie-hebdo-et-13-novembre","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/","title":{"rendered":"Les attentats de Charlie Hebdo : le poids des petites choses"},"content":{"rendered":"<p><a href=\"https:\/\/www.paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1026 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg\" alt=\"mafalda9\" width=\"300\" height=\"214\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-150x107.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9.jpg 378w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Un article a normalement une dur\u00e9e de vie tr\u00e8s courte. Mais l&#8217;histoire se r\u00e9p\u00e8te, et voici qu&#8217;au lendemain des \u00abattentats du vendredi 13\u00bb, nous vivons un grand bis. Sauf que cette fois nous n&#8217;avons plus de symbole, plus de libert\u00e9 de presse \u00e0 crier. La seule chose \u00e0 crier, c&#8217;est la vie, la vie de ces jeunes, qui auraient pu \u00eatre moi, qui pourra demain \u00eatre toi. <\/em><\/p>\n<p>BIS pour \u00abCes barbares\u00bb<br \/>\nBIS pour \u00ab\u00c7a n&#8217;a rien \u00e0 voir avec l&#8217;islam\u00bb<br \/>\nBIS pour Beyrouth oubli\u00e9e pendant que Paris est pleur\u00e9e. L&#8217;ann\u00e9e derni\u00e8re c&#8217;\u00e9tait le Kenya<br \/>\nAlors \u00e0 relire, et \u00e0 ruminer.<\/p>\n<p>Je suis en ce moment \u00e0 Paris. La France vient de vivre son 11 septembre. Un 11 septembre moins sanglant en termes de victimes que celui des \u00c9tats-Unis, et moins sanglant que les r\u00e9centes 2000 victimes du djihadisme au Nigeria qui ne fait pas la une des journaux. Mais comme le 11 septembre avait frapp\u00e9 le symbole de la puissance \u00e9conomique des USA, le 7 janvier a frapp\u00e9 la France l\u00e0 o\u00f9 \u00e7a fait mal. Les djihadistes que nous prenons pour des fous ont vis\u00e9 tr\u00e8s juste. Car l\u2019esprit critique et la satire sont une des grandes marques de l\u2019identit\u00e9 fran\u00e7aise et du rayonnement du pays des Lumi\u00e8res. \u00c0 la diff\u00e9rence pr\u00e8s qu\u2019ici, ce sont des Fran\u00e7ais qui ont commis ces actes. Oui, <em>des Fran\u00e7ais<\/em>. Depuis une semaine, les r\u00e9actions des individus, des m\u00e9dias, des politiciens, expriment toutes les contradictions de nos soci\u00e9t\u00e9s. De petits gestes, de petites phrases, qu\u2019il est temps de prendre au s\u00e9rieux.<\/p>\n<p><strong>\u00ab\u00a0Ces barbares, ces terroristes, ces fous\u00a0\u00bb<br \/>\n<\/strong><\/p>\n<p>Les Barbares sont les \u00e9trangers \u00e0 la Cit\u00e9, ceux qui ne parlent pas la m\u00eame langue. Or ceux qui ont commis ces crimes sont des Fran\u00e7ais <em>\u00e0 part enti\u00e8re<\/em>. Dire \u00ab\u00a0ce sont des barbares\u00a0\u00bb, dire que Hitler \u00e9tait un monstre, c\u2019est mettre le mal \u00e0 distance comme quelque chose qui serait n\u00e9 ailleurs qui sait de Satan lui-m\u00eame, qui ne peut pas avoir ses racines chez nous. Le djihadisme est une graine qui ne pousse que sur des sols fertiles. Et la France, oui le pays des libert\u00e9s, de la r\u00e9publique et de la la\u00efcit\u00e9, est une terre tr\u00e8s fertile, si on en juge par le nombre de jeunes qui partent faire le djihad en Syrie (plus de 1200) pour faire pousser les graines du djihadisme, car elle n\u2019a pas encore trouv\u00e9 de mod\u00e8le pour int\u00e9grer totalement l\u2019islam \u00e0 sa soci\u00e9t\u00e9. La France n\u2019est pas un pays multiculturel car elle ne d\u00e9finit pas un individu d\u2019apr\u00e8s son sang, sa religion ou son origine g\u00e9ographique mais seulement en tant que citoyen (\u00e9galit\u00e9) adh\u00e9rant aux valeurs r\u00e9publicaines, donnant ainsi \u00e0 tous la possibilit\u00e9 d\u2019\u00eatre \u2018fr\u00e8res\u2019 ind\u00e9pendamment de leur religion ou origine culturelle (fraternit\u00e9). Elle doit donc inventer un islam de France.<\/p>\n<p>L\u2019ancien avocat de Kouachi, le preneur d\u2019otages de l\u2019\u00e9picerie casher, raconte que lorsqu\u2019il avait comparu en justice, il avait dit en voyant arriver la juge : \u00ab\u00a0Je ne me l\u00e8ve pas devant une femme ni devant\u00a0la R\u00e9publique\u00a0\u00bb.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Il avait \u00e9t\u00e9 condamn\u00e9 \u00e0 une peine avec sursis, \u00e9tant consid\u00e9r\u00e9 comme \u00ab\u00a0un gamin perdu\u00a0\u00bb. Personne n\u2019a cru bon de sanctionner ce petit geste \u2013 en fait ce non geste \u2013 qui aurait pu en toute logique, entra\u00eener le retrait de la nationalit\u00e9 fran\u00e7aise. Mais \u00e0 quoi bon se dire qu\u2019on aurait pu, puisque ce gamin insolent \u00e9tait en fait un barbare dans les murs de notre cit\u00e9\u2026<\/p>\n<p><strong><em>\u00ab\u00a0Mal nommer les choses, c\u2019est ajouter au malheur du monde\u00a0\u00bb, Camus.<\/em><br \/>\n<\/strong><\/p>\n<p><strong>\u00ab\u00a0La communaut\u00e9 musulmane\u00a0\u00bb, \u00ab\u00a0Les musulmans de France\u00a0\u00bb<br \/>\n<\/strong><\/p>\n<p>Et pourtant, malgr\u00e9 ce mod\u00e8le r\u00e9publicain, la France a eu des relents de multiculturalisme. Le multiculturalisme, c\u2019est le fait de d\u00e9signer et de cat\u00e9goriser un individu en fonction de crit\u00e8res ethniques, raciaux ou religieux \u2013 bien s\u00fbr pour mieux respecter sa diff\u00e9rence, sa diff\u00e9rence <em>fondamentale<\/em>, <em>naturelle<\/em>. C\u2019est le mod\u00e8le canadien avec ses fameuses\u00a0\u00ab\u00a0minorit\u00e9s visibles\u00a0\u00bb qui distinguent par la <em>race<\/em> les minorit\u00e9s et la norme<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>. Ainsi dans tous les formulaires d\u2019embauche de fonctionnaires ou pour des demandes de bourse, il faut cocher la case de son appartenance, avec des cat\u00e9gories qui en disent long sur le degr\u00e9 d\u2019ignorance de la complexit\u00e9 du monde, o\u00f9 le Maroc est au Moyen-Orient et o\u00f9 les Juifs sont une case \u00e0 part comme si on ne pouvait pas \u00eatre Juif arabe de Tunisie ou du Liban.<\/p>\n<p>La France, en th\u00e9orie, ne pratique pas cette cat\u00e9gorisation. Mais depuis une semaine, on entend parler de \u00ab\u00a0communaut\u00e9\u00a0\u00bb musulmane, et des \u00ab\u00a0musulmans de France\u00a0\u00bb, au lieu de parler des Fran\u00e7ais de confession musulmane. \u2018Mais c\u2019est pareil\u00a0! Faut pas chercher la petite b\u00eate\u00a0!\u2019, dira-t-on. Le diable est dans les d\u00e9tails. Si les Fran\u00e7ais musulmans se mettent \u00e0 r\u00e9agir en tant que musulmans d\u2019abord, serait-ce donc qu\u2019ils sont musulmans avant d\u2019\u00eatre fran\u00e7ais\u00a0? Qu\u2019ils seraient alors non pas des fran\u00e7ais musulmans, mais des musulmans vivant en France ? Et voil\u00e0 pos\u00e9 le probl\u00e8me de la possibilit\u00e9 ou de l\u2019impossibilit\u00e9 de construire une identit\u00e9 fran\u00e7aise r\u00e9publicaine et musulmane. Jusqu\u2019o\u00f9 la cohabitation entre identit\u00e9 nationale et identit\u00e9 religieuse est-elle possible\u00a0? Probl\u00e8me qui ne se r\u00e9soudra que par un long et fastidieux travail de recherche, d\u2019\u00e9ducation, de d\u00e9bats, o\u00f9 des penseurs r\u00e9formistes de l\u2019islam que l\u2019on n\u2019entend pas assez seraient consult\u00e9s par le Conseil du Culte Musulman pour \u00e9tablir une branche fran\u00e7aise de l\u2019islam, pour ouvrir le Coran et dire clairement\u00a0: ceci nous le reconnaissons, cela peut faire l\u2019objet d\u2019interpr\u00e9tation extr\u00e9mistes et nous allons le clarifier, cela nous ne le reconnaissons pas comme la parole r\u00e9v\u00e9l\u00e9e, le Coran pr\u00e9voit-il des mesures pour les musulmans qui vivent dans un pays non musulman, etc.<\/p>\n<p>\u00ab\u00a0Pas en mon nom\u00a0\u00bb signifie en fait \u00ab\u00a0pas au nom de ma religion\u00a0\u00bb. Sauf que le djihad est bien inscrit dans l\u2019islam. Ceux qui disent le contraire op\u00e8rent le m\u00eame d\u00e9ni que celui qui refuse de reconna\u00eetre que ces djihadistes sont en partie un produit de la France. On peut dire \u00ab\u00a0l\u2019interpr\u00e9tation djihadiste actuelle de l\u2019islam est erron\u00e9e\u00a0\u00bb, que prendre comme mod\u00e8le le d\u00e9part de Mahomet \u00e0 M\u00e9dine comme mod\u00e8le pour le djihad en Syrie est une manipulation, et d\u00e9battre de cela, clarifier les choses, sans dire pour autant que cela \u00ab\u00a0n\u2019a rien \u00e0 voir\u00a0\u00bb. L\u2019expression \u00ab\u00a0application stricte de la charia\u00a0\u00bb utilis\u00e9e \u00e0 tort et \u00e0 travers par tous les m\u00e9dias porte en elle-m\u00eame cette contradiction. Elle est utilis\u00e9e comme un euph\u00e9misme prudent qui croit \u00e9viter l\u2019amalgame, mais qui en fait le cr\u00e9e. Car si la charia est bien l\u2019islam, alors \u00ab\u00a0l\u2019application stricte de la charia\u00a0\u00bb est bien une <em>variante possible de l\u2019islam<\/em>.<\/p>\n<p>Tout syst\u00e8me de pens\u00e9e et d\u2019organisation sociale porte en lui la possibilit\u00e9 de sa d\u00e9rive fanatique. D\u00e8s lors que l\u2019on a le courage d\u2019admettre cela, alors nous pouvons lutter efficacement contre lui. En d\u00e9finissant clairement les limites de ce que nous posons comme juste\/injuste, acceptable\/r\u00e9pr\u00e9hensible, etc. C\u2019est ce que s\u2019attachent \u00e0 faire nombre de penseurs musulmans qui proposent des r\u00e9formes de l\u2019islam mais qui n\u2019ont pas acc\u00e8s aux grands m\u00e9dias dans les pays occidentaux et qui sont r\u00e9prim\u00e9s dans les pays musulmans. Alors si \u00ab\u00a0\u00e7a n\u2019a rien \u00e0 voir\u00a0\u00bb, \u00e7a vient d\u2019o\u00f9\u00a0? D\u2019une ancienne tradition papoue\u00a0? Ce n\u2019est qu\u2019en reconnaissant justement que le djihadisme est une d\u00e9rive de l\u2019islam que, avec tous les musulmans qui le condamnent, on pourra le combattre.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019\u00e9cran-2015-06-09-\u00e0-12.14.35.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-315\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019\u00e9cran-2015-06-09-\u00e0-12.14.35.png\" alt=\"Capture d\u2019\u00e9cran 2015-06-09 \u00e0 12.14.35\" width=\"221\" height=\"295\" \/><\/a><\/p>\n<p><strong>La visite de Benyamin Netanyahou \u00e0 l\u2019\u00e9picerie casher et \u00e0 la synagogue<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Le chef de l\u2019\u00c9tat isra\u00e9lien n\u2019est pas le repr\u00e9sentant des Juifs sur terre. Si la majorit\u00e9 silencieuse des musulmans ne souhaite pas \u00eatre amalgam\u00e9e avec les djihadistes, la majorit\u00e9 silencieuse des Fran\u00e7ais de confession ou de culture juive qui ne vit pas \u00e0 Sarcelles ni dans le quartier des Rosiers, qui ne porte pas la kippa, qui ne va pas dans les \u00e9piceries casher, ne souhaite pas \u00eatre identifi\u00e9e \u00e0 la politique isra\u00e9lienne et m\u00eame \u00e0 ce pays qui n\u2019est pas le sien. Car cette majorit\u00e9 silencieuse juive fran\u00e7aise se fera enterrer en France, parmi leurs compatriotes, et non en Isra\u00ebl comme les victimes de cet attentat qui, nous dit-on pourtant, \u00e9taient des mod\u00e8les d\u2019int\u00e9gration. Accepter que le premier ministre isra\u00e9lien soit sorti du lot des politiciens comme s\u2019il \u00e9tait un peu plus concern\u00e9, c\u2019est ent\u00e9riner l\u2019id\u00e9e que les Fran\u00e7ais de confession juive sont tous des Isra\u00e9liens potentiels. C\u2019est entretenir la confusion entre culture juive et sionisme, ce qui est justement la cause du nouvel antis\u00e9mitisme, puisque les djihadistes ont bien revendiqu\u00e9 qu\u2019ils s\u2019attaquaient \u00e0 l\u2019\u00e9picerie pour se venger de ce que \u00ab\u00a0les Juifs\u00a0\u00bb font aux Palestiniens.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019\u00e9cran-2015-06-09-\u00e0-12.21.59.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-316\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019\u00e9cran-2015-06-09-\u00e0-12.21.59.png\" alt=\"Capture d\u2019\u00e9cran 2015-06-09 \u00e0 12.21.59\" width=\"266\" height=\"270\" \/><\/a><\/p>\n<p><strong>\u00ab\u00a0Mais quand m\u00eame\u00a0\u00bb<br \/>\n<\/strong><\/p>\n<p>C\u2019est pas bien de se moquer\u00a0! Le jugement du politiquement correct est sans appel. On a entendu et lu dans les m\u00e9dias <em>certains<\/em> musulmans dire qu\u2019ils condamnaient ces attentats, mais que \u00ab\u00a0quand m\u00eame\u2026\u00a0\u00bb petite phrase qui est devenue dans la bouche de certains lyc\u00e9ens \u00ab\u00a0ils avaient qu\u2019\u00e0 pas\u2026\u00a0\u00bb.<\/p>\n<p>Le politiquement correct, c\u2019est dire qu\u2019il y a les bons et les m\u00e9chants, que les religions c\u2019est que du bon (\u00ab\u00a0Je pense pas qu\u2019il existe un bouquin qui dise de tuer son prochain\u00a0\u00bb comme le dit la chanson sur musique de Renaud qui a fait un gros buzz sur internet). C\u2019est beau, c\u2019est joli, c\u2019est simple. Tout le monde voudrait vivre en paix dans le respect des diff\u00e9rences, mais glisser vers un d\u00e9ni de la complexit\u00e9 du ph\u00e9nom\u00e8ne religieux n\u2019aidera en rien. Car c\u2019est ainsi que nous nous d\u00e9culpabilisons de toutes les d\u00e9rives de nos soci\u00e9t\u00e9s dont nous sommes, \u00e0 un moment donn\u00e9, les acteurs. Acteurs d\u00e8s que nous achetons d\u2019un produit derri\u00e8re lequel se cache de l\u2019esclavage et la destruction de notre terre, acteurs d\u00e8s que nous prenons les journaux gratuits financ\u00e9s par les plus grosses compagnies publicitaires contre lesquels la presse ind\u00e9pendante payante ne peut pas lutter, acteurs d\u00e8s que nous entrons dans une boutique \u00e0 touriste qui d\u00e9truit l\u2019authenticit\u00e9 d\u2019un lieu que nous pr\u00e9tendons aimer, acteurs d\u00e8s que nous mettons 3$ dans le chapeau d\u2019un artiste et trois fois plus dans la bi\u00e8re et que nous compatissons \u00e0 la dure vie des artistes, acteurs d\u00e8s que nous ne faisons rien quand les locaux d\u2019un journal satirique sont br\u00fbl\u00e9s et que les journalistes sont menac\u00e9s de mort. Mais nous on n\u2019a rien fait de mal, on a simplement achet\u00e9 du poulet pas cher, un sandwich, pris un journal gratuit, pas r\u00e9pondu \u00e0 l\u2019appel aux dons de Charlie Hebdo. Nous sommes des acteurs dans un second r\u00f4le\u2026 mais nous sommes des millions.<\/p>\n<p>Si tu dis que le djihadisme vient de l\u2019islam et en est la manifestation fanatique, tu es contre les musulmans. Si tu es musulman r\u00e9formiste et que tu dis la m\u00eame chose, tu re\u00e7ois une fatwa. Si tu es dessinateur et que tu dessines le proph\u00e8te les fesses \u00e0 l\u2019air devant une cam\u00e9ra, tu n\u2019es pas respectueux (bien que le propos du dessin ne concerne absolument pas le proph\u00e8te lui-m\u00eame mais une repr\u00e9sentation de la situation engendr\u00e9e par un film anti musulman). Charlie Hebdo est un rempart contre la hantise de froisser les esprits, qui domine tant nos soci\u00e9t\u00e9s et emp\u00eache d\u2019avoir de vrais d\u00e9bats. Et quand bien m\u00eame nous ne serions pas d\u2019accord, que nous trouvions leurs caricatures du plus mauvais go\u00fbt, insolentes, cela ne saurait entra\u00eener la condamnation du principe de repr\u00e9senter et de se moquer.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019\u00e9cran-2015-06-09-\u00e0-12.24.34.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-317\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019\u00e9cran-2015-06-09-\u00e0-12.24.34-250x300.png\" alt=\"Capture d\u2019\u00e9cran 2015-06-09 \u00e0 12.24.34\" width=\"250\" height=\"300\" \/><\/a><\/p>\n<p>Aurait-on donc le droit de rire de tout sauf de l\u2019islam\u00a0? Ou bien de tout sauf des religions\u00a0? \u00a0Comme tout syst\u00e8me de pens\u00e9e qui repose sur l\u2019autorit\u00e9 et sur le sacr\u00e9 (la religion et la politique ont ceci en commun), la religion n\u2019a jamais regard\u00e9 le rire d\u2019un bon \u0153il. Dans le roman <em>Le nom de la rose <\/em>de Umberto Eco, c\u2019est bien le manuscrit d\u2019Aristote sur le rire que l\u2019\u00c9glise veut d\u00e9truire. Pourtant, au si\u00e8cle humaniste, pendant l\u2019\u00e9change \u00e9pistolaire de 1550 qu\u2019on appela la controverse de Valladolid, entre Las Casas et Sepulveda, sur la l\u00e9gitimit\u00e9 de coloniser le Nouveau Monde et d\u2019assujettir ses premiers habitants, l\u2019une des questions pour \u00e9tablir l\u2019humanit\u00e9 des Am\u00e9rindiens \u00e9tait de savoir s\u2019ils \u00e9taient capables de rire (on ne savait pas \u00e0 l\u2019\u00e9poque que les singes aussi riaient)\u2026 Rire, une composante essentielle de notre humanit\u00e9.<\/p>\n<p>Dans un pays o\u00f9 la satire est une composante essentielle et reconnue comme n\u00e9cessaire \u00e0 la bonne sant\u00e9 de la soci\u00e9t\u00e9, s\u2019interdire de rire d\u2019une certaine cat\u00e9gorie d\u2019individus est la meilleure fa\u00e7on de les mettre \u00e0 part. Le caricaturiste a un langage qui s\u2019appelle la caricature, faite d\u2019exag\u00e9ration et d\u2019insolence, comme le chercheur a pour langage un essai, le cin\u00e9aste un film, etc. \u00catre bless\u00e9 par une caricature, c\u2019est ne pas comprendre ce qu\u2019est une caricature, c\u2019est croire que ce qu\u2019elle montre est \u00e0 prendre au pied de la lettre, que \u00e7a n\u2019est pas une repr\u00e9sentation. Mitterrand rencontrant un des dessinateurs de Charlie Hebdo qui ne l\u2019avait pas \u00e9pargn\u00e9 s\u2019est \u00e9cri\u00e9\u00a0: \u00ab\u00a0Ah, voici le ma\u00eetre\u00a0!\u00a0\u00bb. La caricature permet de mettre \u00e0 distance, de d\u00e9sacraliser. Charb avait expliqu\u00e9 qu\u2019il avait eu du mal \u00e0 caricaturer Hollande et son gouvernement car ils l\u2019avaient eux-m\u00eames soutenu. Mais ils l\u2019ont fait, ils ont pris de la distance par rapport \u00e0 leur sensibilit\u00e9 personnelle, pour inclure tout le monde dans la satire. \u00ab\u00a0Mais quand m\u00eame, \u00e7a n\u2019est pas respectueux pour les millions de militants du parti socialiste.\u00a0\u00bb<\/p>\n<p>Les attentats de Charlie Hebdo sont un cataclysme de par leur violence et leur puissance symbolique, mais aussi parce qu\u2019ils d\u00e9plient un \u00e0 un des probl\u00e8mes qui sont au c\u0153ur de la soci\u00e9t\u00e9 fran\u00e7aise, d\u2019autant plus difficiles \u00e0 r\u00e9soudre qu\u2019ils concernent l\u2019identit\u00e9, la culture, le symbolique. Si certains souhaitent que la loi fran\u00e7aise se soumette \u00e0 l\u2019interdit religieux en condamnant le blasph\u00e8me, cela pose \u00e9videmment le probl\u00e8me de l\u2019int\u00e9gration, c\u2019est-\u00e0-dire de l\u2019adh\u00e9sion de personnes, immigr\u00e9es ou non, aux valeurs d\u2019une soci\u00e9t\u00e9. Il n\u2019y a que dans les pays religieux o\u00f9 le blasph\u00e8me soit condamn\u00e9. La France ne reconna\u00eet pas Mahomet comme un proph\u00e8te, elle reconna\u00eet \u00e0 ses citoyens le droit de croire ou de ne pas croire que c\u2019est un proph\u00e8te, ce qui est bien diff\u00e9rent. Sa Majest\u00e9 marocaine alli\u00e9e de la France l\u2019a peut-\u00eatre oubli\u00e9 en refusant de venir \u00e0 la marche <em>R\u00e9publicaine<\/em> et a refus\u00e9 de reconna\u00eetre la libert\u00e9 d\u2019expression, c\u2019est-\u00e0-dire le droit d\u2019exprimer son opinion <em>ind\u00e9pendamment<\/em> du fait qu\u2019on ne soit pas d\u2019accord avec le contenu ou que l\u2019on trouve l\u2019humour de mauvais go\u00fbt. Sa Majest\u00e9 s\u2019est content\u00e9e de condamner les crimes, \u00ab\u00a0mais quand m\u00eame\u2026.\u00a0\u00bb C\u2019est en riant de tout que nous faisons un nous.<\/p>\n<p>\u00ab\u00a0Charlie Hebdo a le droit de dessiner ce qu\u2019il veut, tant que cela ne tombe pas sous le coup de la loi de la R\u00e9publique.\u00a0\u00bb Abdelali Mamoun, imam de Alfortville.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a><\/p>\n<p><strong>\u00ab\u00a0Nous sommes Charlie\u00a0\u00bb<br \/>\n<\/strong><\/p>\n<p><strong>\u00a0\u00a0 <\/strong>Nous sommes tous Charlie, car les balles qui ont touch\u00e9 les membres de Charlie, les policiers et les otages, ont atteint ce qui fait la France. Nous sommes Charlie, cet enfant de la R\u00e9publique que nous avons si mal trait\u00e9. Car comme partout, la plupart des Fran\u00e7ais consomme plut\u00f4t du divertissement de masse, dans la ligne du politiquement correct contre lequel luttait Charlie Hebdo, qui ne tirait qu\u2019\u00e0 50 000 exemplaires. Il faut croire que la plupart des Fran\u00e7ais n\u2019avait pas le budget de 3 euros (5$) par semaine \u00e0 mettre dans cette libert\u00e9.<\/p>\n<p>Et maintenant\u00a0? Apr\u00e8s avoir march\u00e9, apr\u00e8s avoir chang\u00e9 nos photos de profil facebook et lev\u00e9 nos stylos, qui fera l\u2019effort de se rendre dans un point de presse pour acheter la presse ind\u00e9pendante, qui, comme Charlie, ne vit que des lecteurs\u00a0? Qui ira encourager les artistes ind\u00e9pendants\u00a0qui brandissent leurs stylos et doivent qu\u00e9mander ce qu\u2019on n\u2019oserait m\u00eame pas nommer un salaire\u00a0? Qui aimera assez la libert\u00e9 d\u2019expression et l\u2019ind\u00e9pendance pour sortir du confort de la gratuit\u00e9 \u00e0 tout prix\u00a0? Qui sera Charlie demain\u00a0?<\/p>\n<p><em><strong>\u00ab\u00a0Il a fallu douze cadavres pour qu&#8217;on soit enfin un peu compris apr\u00e8s avoir \u00e9t\u00e9 ha\u00efs, conspu\u00e9s\u00a0\u00bb Zineb El Rhazoui, journaliste \u00e0 Charlie Hebdo<\/strong> <\/em><\/p>\n<p><strong>Le poids des petites choses<br \/>\n<\/strong><\/p>\n<p>Charlie Hebdo, un petit canard devenu le symbole mondial de la libert\u00e9 d\u2019expression. Une poign\u00e9e de journalistes qui s\u2019acharnaient \u00e0 d\u00e9culotter le politiquement correct avec quelques coups de crayon. Quelques dessins ont suffi \u00e0 d\u00e9cha\u00eener un plan de plusieurs ann\u00e9es pour \u00e9radiquer la r\u00e9daction de ce journal.<\/p>\n<p>En France un d\u00e9bat s\u2019engage sur l\u2019\u00e9ducation et les efforts qui doivent \u00eatre faits pour lutter en amont contre la radicalisation des jeunes. Mais tous les acteurs qui sont sur le terrain le disent\u00a0: ce seront des petites choses qui changeront tout. Des initiatives d\u2019associations locales pour permettre aux jeunes de lire, de se documenter, de d\u00e9couvrir la complexit\u00e9 du monde, des ateliers de th\u00e9\u00e2tre pour leur permettre de cr\u00e9er ensemble des pi\u00e8ces et de mettre en sc\u00e8ne leur r\u00e9alit\u00e9 et leurs questionnements.<\/p>\n<p>Il est temps de mesurer le poids des petites choses, ce que cette chronique tente de faire dans chaque article non r\u00e9mun\u00e9r\u00e9, en montrant comment notre quotidien est plein de petits gestes, de petites paroles, de petites indiff\u00e9rences, qui p\u00e8sent un peu plus que le poids d\u2019un journal.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> C\u00e9line Rastello, <em>Nouvel Obs <\/em>8 janvier 2015.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> \u00ab\u00a0Font partie des minorit\u00e9s visibles les personnes, autres que les autochtones, qui ne sont pas de race blanche ou qui n\u2019ont pas la peau blanche\u00a0\u00bb, <em>Loi sur l\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi, <\/em>1995.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> http:\/\/actu.orange.fr\/video\/charlie-hebdo\/mahomet-en-une-de-charlie-hebdo-la-reaction-de-l-imam-d-alfortville-magic_CNT0000006UOwz.html<\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer;\">Enregistrer<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer;\">Enregistrer<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Un article a normalement une dur\u00e9e de vie tr\u00e8s courte. Mais l&#8217;histoire se r\u00e9p\u00e8te, et voici qu&#8217;au lendemain des \u00abattentats du vendredi 13\u00bb, nous vivons un grand bis. Sauf que cette fois nous n&#8217;avons plus de symbole, plus de libert\u00e9 de presse \u00e0 crier. La seule chose \u00e0 crier, c&#8217;est la vie, la vie de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[96,41],"class_list":["post-314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequinousarrive","tag-attentats","tag-identite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les attentats de Charlie Hebdo : le poids des petites choses - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les attentats de Charlie Hebdo : le poids des petites choses - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Un article a normalement une dur\u00e9e de vie tr\u00e8s courte. Mais l&#8217;histoire se r\u00e9p\u00e8te, et voici qu&#8217;au lendemain des \u00abattentats du vendredi 13\u00bb, nous vivons un grand bis. Sauf que cette fois nous n&#8217;avons plus de symbole, plus de libert\u00e9 de presse \u00e0 crier. La seule chose \u00e0 crier, c&#8217;est la vie, la vie de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-15T22:09:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T16:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/01\/911-French.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"48 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/01\/911-French.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/01\/911-French.jpg\",\"width\":515,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/\",\"name\":\"Les attentats de Charlie Hebdo : le poids des petites choses - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#primaryimage\"},\"datePublished\":\"2015-01-15T22:09:11+00:00\",\"dateModified\":\"2020-05-14T16:31:41+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les attentats de Charlie Hebdo : le poids des petites choses\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les attentats de Charlie Hebdo : le poids des petites choses - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/","og_locale":"es_ES","og_type":"article","og_title":"Les attentats de Charlie Hebdo : le poids des petites choses - Sarah Roubato","og_description":"Un article a normalement une dur\u00e9e de vie tr\u00e8s courte. Mais l&#8217;histoire se r\u00e9p\u00e8te, et voici qu&#8217;au lendemain des \u00abattentats du vendredi 13\u00bb, nous vivons un grand bis. Sauf que cette fois nous n&#8217;avons plus de symbole, plus de libert\u00e9 de presse \u00e0 crier. La seule chose \u00e0 crier, c&#8217;est la vie, la vie de [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-01-15T22:09:11+00:00","article_modified_time":"2020-05-14T16:31:41+00:00","og_image":[{"width":515,"height":720,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/01\/911-French.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"48 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/01\/911-French.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/01\/911-French.jpg","width":515,"height":720},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#webpage","url":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/","name":"Les attentats de Charlie Hebdo : le poids des petites choses - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#primaryimage"},"datePublished":"2015-01-15T22:09:11+00:00","dateModified":"2020-05-14T16:31:41+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/es\/cequinousarrive\/charlie-hebdo-et-13-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Les attentats de Charlie Hebdo : le poids des petites choses"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=314"}],"version-history":[{"count":10,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/314\/revisions"}],"predecessor-version":[{"id":4382,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/314\/revisions\/4382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/413"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}