
{"id":341,"date":"2014-03-03T23:19:53","date_gmt":"2014-03-03T23:19:53","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=341"},"modified":"2020-05-18T17:27:19","modified_gmt":"2020-05-18T15:27:19","slug":"sur-quel-fil-chante-marcie","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/","title":{"rendered":"Sur quel fil chante Marcie ?"},"content":{"rendered":"<p><a href=\"https:\/\/www.paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1026 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg\" alt=\"mafalda9\" width=\"300\" height=\"214\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-150x107.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9.jpg 378w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Nous marchons dans nos vies comme sur un fil, entre les rochers de nos obstacles et la mer de nos r\u00eaves qui s\u2019y cognent, entre les for\u00eats sombres de nos troubles int\u00e9rieurs et les ciels d\u00e9gag\u00e9s de nos apparences, entre les d\u00e9serts de nos deuils et les prairies verdoyantes de nos r\u00e9jouissances. L\u2019\u00e9quilibre est pr\u00e9caire, et toujours \u00e0 r\u00e9inventer, \u00e0 chaque pas. Marcie, qui chantait lundi dernier au Verre Bouteille, marche sur plusieurs fils. Accompagn\u00e9e de Ludo Pin (le r\u00e9alisateur de son album) \u00e0 la guitare, de Simon Dolan \u00e0 la basse et de Mathieu Vezo \u00e0 la batterie, elle s\u2019est livr\u00e9e tout en \u00e9quilibre, en gardant sa part de myst\u00e8re.<\/p>\n<p><strong>Entre la fille et la femme<br \/>\n<\/strong><\/p>\n<p><strong>\u00a0\u00a0 <\/strong>Marcie laisse une impression insaisissable. Il y a quelque chose de myst\u00e9rieux chez cette jeune fille \u00e0 l\u2019air timide, et qui d\u00e8s qu\u2019elle est sur sc\u00e8ne, se m\u00e9tamorphose. Robe noire et talons hauts, les yeux maquill\u00e9s d\u2019un trait noir. La timidit\u00e9 devient une pudeur avec laquelle Marcie enveloppe la puissance de ses textes. Sa musique \u00e0 l\u2019harmonie minimaliste et aux m\u00e9lodies qui se r\u00e9p\u00e8tent \u2013 certains diraient, trop simples \u2013 laissent place aux mots en cr\u00e9ant un \u00e9tat envo\u00fbtant. La sc\u00e8ne lib\u00e8re les choses enfouies. Marcie devient puissante dans sa fragilit\u00e9 m\u00eame, avec sa voix chaude et parfois \u00e9raill\u00e9e, comme une caresse sur des graviers. Elle est enti\u00e8rement pr\u00e9sente et vit ses chansons de l\u2019int\u00e9rieur en les incarnant totalement.<\/p>\n<p><strong>Entre pr\u00e9sence et absence<br \/>\n<\/strong><\/p>\n<p>Marcie incarne la chanson comme peu savent le faire. Elle danse avec ses mains, comme si elle cherchait \u00e0 cueillir ses propres mots ou \u00e0 les retenir pour ne pas qu\u2019ils tombent. Elle fixe un point au loin, elle voit ce qu\u2019elle chante. Dans <em>Fais moi pleurer<\/em>, elle se panche, elle titube, comme si elle \u00e9tait saoule. Et quand elle se risque a capella sur une nouvelle chanson, elle est encore plus pr\u00e9sente dans sa nudit\u00e9.<\/p>\n<p>C\u2019est pourtant l\u2019absence que Marcie d\u00e9cline de toute sa pr\u00e9sence de sc\u00e8ne. Elle nous la dit sous toutes ses formes. L\u2019absence qu\u2019on choisit\u00a0: \u00ab\u00a0J\u2019ai compris qu\u2019il valait Mieux pour moi d\u2019avoir fait Mes valises avant l\u2019aube\u00a0\u00bb, celle que l\u2019on subit, immobile, impuissant\u00a0: \u00ab\u00a0La neige tombe tombe tombe, L\u00e0 partout sur les toits \u00c7a va site vite. Il fait si sombre Et des feuilles tombent de moi\u00a0\u00bb. L\u2019absence qui s\u2019en vient, comme un papillon blanc qui va s\u2019envoler et qu\u2019on veut retenir. L\u2019absence qu\u2019on refuse, l\u2019absence qu\u2019on supplie, l\u2019absence qu\u2019on d\u00e9fie. Cette absence aux cent morceaux, c\u2019est la chanson qui viendra la recoudre\u00a0: \u00ab\u00a0J\u2019\u00e9cris pour rassembler les pages des amours dispers\u00e9es\u00a0\u00bb.<\/p>\n<p><strong>Entre le silence et les mots<br \/>\n<\/strong><\/p>\n<p>Marcie fait vivre ses textes, elle rend les mots palpables. Ses respirations sont sonores, elles font partie du texte. Elle semble parfois h\u00e9siter sur les mots tant elle conna\u00eet leur poids. Sa musique ne noie jamais ce qu\u2019elle dit, et fabrique pour chaque chanson un petit film o\u00f9 pour quelques minutes, la rose, l\u2019arbre, les sir\u00e8nes, le papillon, sont ici, devant nous. Marcie r\u00e9ussit presque \u00e0 chaque chanson le miracle des fractions de seconde apr\u00e8s la derni\u00e8re note o\u00f9 le public retient son souffle. Ce silence qui suit la chanson, elle l\u2019habite encore.<\/p>\n<p>Entre le silence et les mots, il y a la musique. Une musique int\u00e9rieure qui est la n\u00f4tre et que Marcie nous livre, entre ses mains funambules.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nous marchons dans nos vies comme sur un fil, entre les rochers de nos obstacles et la mer de nos r\u00eaves qui s\u2019y cognent, entre les for\u00eats sombres de nos troubles int\u00e9rieurs et les ciels d\u00e9gag\u00e9s de nos apparences, entre les d\u00e9serts de nos deuils et les prairies verdoyantes de nos r\u00e9jouissances. L\u2019\u00e9quilibre est pr\u00e9caire, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cequilsnousracontent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sur quel fil chante Marcie ? - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sur quel fil chante Marcie ? - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Nous marchons dans nos vies comme sur un fil, entre les rochers de nos obstacles et la mer de nos r\u00eaves qui s\u2019y cognent, entre les for\u00eats sombres de nos troubles int\u00e9rieurs et les ciels d\u00e9gag\u00e9s de nos apparences, entre les d\u00e9serts de nos deuils et les prairies verdoyantes de nos r\u00e9jouissances. L\u2019\u00e9quilibre est pr\u00e9caire, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-03T23:19:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-18T15:27:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.29.23.png\" \/>\n\t<meta property=\"og:image:width\" content=\"389\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.29.23.png\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.29.23.png\",\"width\":389,\"height\":395},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/\",\"name\":\"Sur quel fil chante Marcie ? - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#primaryimage\"},\"datePublished\":\"2014-03-03T23:19:53+00:00\",\"dateModified\":\"2020-05-18T15:27:19+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sur quel fil chante Marcie ?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sur quel fil chante Marcie ? - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/","og_locale":"es_ES","og_type":"article","og_title":"Sur quel fil chante Marcie ? - Sarah Roubato","og_description":"Nous marchons dans nos vies comme sur un fil, entre les rochers de nos obstacles et la mer de nos r\u00eaves qui s\u2019y cognent, entre les for\u00eats sombres de nos troubles int\u00e9rieurs et les ciels d\u00e9gag\u00e9s de nos apparences, entre les d\u00e9serts de nos deuils et les prairies verdoyantes de nos r\u00e9jouissances. L\u2019\u00e9quilibre est pr\u00e9caire, [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2014-03-03T23:19:53+00:00","article_modified_time":"2020-05-18T15:27:19+00:00","og_image":[{"width":389,"height":395,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.29.23.png","type":"image\/png"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.29.23.png","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/Capture-d\u2019e\u0301cran-2015-06-09-a\u0300-16.29.23.png","width":389,"height":395},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/","name":"Sur quel fil chante Marcie ? - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#primaryimage"},"datePublished":"2014-03-03T23:19:53+00:00","dateModified":"2020-05-18T15:27:19+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/cequilsnousracontent\/sur-quel-fil-chante-marcie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Sur quel fil chante Marcie ?"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":4,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"predecessor-version":[{"id":4492,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/341\/revisions\/4492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/331"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}