
{"id":373,"date":"2015-06-10T01:17:45","date_gmt":"2015-06-10T01:17:45","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=373"},"modified":"2020-05-18T15:43:36","modified_gmt":"2020-05-18T13:43:36","slug":"le-quebec-un-modele-de-resistance-culturelle-et-politique","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/","title":{"rendered":"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ?"},"content":{"rendered":"<p><a href=\"https:\/\/www.paypal.me\/sarahroubatofr\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-1026 aligncenter\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg\" alt=\"mafalda9\" width=\"300\" height=\"214\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-300x214.jpg 300w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9-150x107.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/12\/mafalda9.jpg 378w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Publi\u00e9 dans <em>Cassandre Hors Champ : <a href=\"http:\/\/www.horschamp.org\/spip.php?rubrique327\">100 \u00abDe vents et de mar\u00e9es\u00bb <\/a><\/em><\/p>\n<p><em>2012, ann\u00e9e qui restera grav\u00e9e dans l\u2019histoire du Qu\u00e9bec comme celle d\u2019un \u00e9veil. Le Printemps \u00c9rable comme on l\u2019a appel\u00e9, est un mouvement contestataire, parti d\u2019une gr\u00e8ve \u00e9tudiante, qui a dur\u00e9 huit mois. Ce mouvement a d\u00e9clench\u00e9 des \u00e9lections anticip\u00e9es et la destitution du gouvernement lib\u00e9ral de Jean Charest. Gabriel Nadeau-Dubois, porte-parole d\u2019une association \u00e9tudiante, la CLASSE (Coalition large de l&#8217;association pour une solidarit\u00e9 syndicale \u00e9tudiante), s\u2019est fait remarquer comme l\u2019une des figures de proue de ce mouvement. Depuis, le toujours-\u00e9tudiant est en train de devenir une figure majeure du paysage politico-culturel et m\u00e9diatique du Qu\u00e9bec.<\/em><\/p>\n<p><em>En novembre dernier, GND a re\u00e7u le prix du Gouverneur G\u00e9n\u00e9ral pour son livre Tenir t\u00eate, un essai sur le Printemps \u00c9rable et ses cons\u00e9quences dans la soci\u00e9t\u00e9 qu\u00e9b\u00e9coise, devenant ainsi le plus jeune r\u00e9cipiendaire de ce prix qu\u2019il a h\u00e9sit\u00e9 \u00e0 accepter (le gouverneur g\u00e9n\u00e9ral \u00e9tant le repr\u00e9sentant de la reine donc de l\u2019autorit\u00e9 f\u00e9d\u00e9rale du Canada). GND a remis les 25 000 $ qui accompagnent le prix aux mouvements citoyens qui luttent contre le projet d\u2019ol\u00e9oduc de Transcanada. Un projet qui consiste \u00e0 faire acheminer les sables bitumineux d\u2019Alberta par le fleuve Saint-Laurent, joyau naturel et culturel du Qu\u00e9bec, l\u2019un des plus grands fleuves du monde avec son bassin de drainage de 1 610 000 km2. GND a lanc\u00e9 un appel pour doubler la mise. En quelques jours, il a r\u00e9colt\u00e9 380 000$.<\/em><\/p>\n<p><em>Comme le mouvement \u00e9tudiant, le projet d\u2019ol\u00e9oduc soul\u00e8ve des enjeux politiques majeurs, et r\u00e9veille la question de la souverainet\u00e9 qu\u00e9b\u00e9coise. GND l\u2019a bien compris et c\u2019est pour cela qu\u2019il a d\u00e9cid\u00e9 de s\u2019engager dans ce nouveau combat. Ce jeune homme de vingt-quatre ans a des id\u00e9es mais sait aussi que l\u2019argent est le moteur des actions. C\u2019est pourquoi son action risque fort de mettre un sacr\u00e9 frein, voire un frein d\u00e9finitif \u00e0 ce projet. Lors de son annonce, GND a affirm\u00e9 que c\u2019est en posant d\u2019abord des d\u00e9cisions souveraines que le Qu\u00e9bec pourra marcher vers l\u2019ind\u00e9pendance. Entretien avec celui qui redonne \u00e0 beaucoup de Qu\u00e9b\u00e9cois de plusieurs g\u00e9n\u00e9rations la perspective d\u2019une prise en main de leur avenir. Entretien en tutoiement, comme il se doit au Qu\u00e9bec<\/em>.<\/p>\n<p><strong>Qu\u2019est-ce qu\u2019il reste aujourd\u2019hui du Printemps \u00c9rable, au-del\u00e0 des retomb\u00e9es imm\u00e9diates de l\u2019arr\u00eat de la hausse des frais de scolarit\u00e9 et de la destitution du gouvernement ?<\/strong><\/p>\n<p><strong>\u00a0<\/strong>La premi\u00e8re chose c\u2019est l\u2019effet d\u2019\u00e9ducation politique. Cette mobilisation a introduit \u00e0 des centaines de milliers de personnes aux enjeux sociopolitiques. Et pas seulement des jeunes. D\u2019autres g\u00e9n\u00e9rations qui s\u2019\u00e9taient d\u00e9politis\u00e9es avec le temps ont renou\u00e9 avec la chose publique, d\u2019autres qui ne s\u2019\u00e9taient jamais politis\u00e9es se sont engag\u00e9es pour la premi\u00e8re fois.<\/p>\n<p>L\u2019autre chose c\u2019est que certains enjeux ont \u00e9t\u00e9 remis sur la place publique. Par exemple la question de la transformation des universit\u00e9s. Avant 2012 le seul discours sur la place publique \u00e9tait celui de la marchandisation des universit\u00e9s. En prenant pr\u00e9texte du sous-financement, on introduisait l\u2019investissement priv\u00e9 des universit\u00e9s. C\u2019\u00e9tait le seul discours qu\u2019on entendait depuis une dizaine d\u2019ann\u00e9es. C\u2019\u00e9tait un vrai mart\u00e8lement id\u00e9ologique : \u00ab il faut entrer dans la comp\u00e9tition interuniversitaire, il faut rattraper les \u00c9tats-Unis et le Canada anglais \u00bb. La mobilisation a introduit une autre vision de l\u2019\u00e9ducation qui n\u2019\u00e9tait pas audible, et a acc\u00e9l\u00e9r\u00e9 le clivage gauche-droite au Qu\u00e9bec qui avait \u00e9t\u00e9 effac\u00e9. L\u2019enjeu pour le mouvement de 2012 c\u2019\u00e9tait de construire un mod\u00e8le qu\u00e9b\u00e9cois d\u2019\u00e9ducation sup\u00e9rieure bas\u00e9 sur la gratuit\u00e9 scolaire qui soit diff\u00e9rent du mod\u00e8le fran\u00e7ais ou du mod\u00e8le scandinave.<\/p>\n<p><strong>On sait au Qu\u00e9bec \u00e0 quel point les Fran\u00e7ais connaissent mal les Qu\u00e9b\u00e9cois. En France, le pays des r\u00e9volutions et des gr\u00e8ves, on a \u00e9t\u00e9 tr\u00e8s surpris de ce qui s\u2019est pass\u00e9 en 2012, comme si les Qu\u00e9b\u00e9cois n\u2019\u00e9taient pas per\u00e7us comme un peuple habitu\u00e9 aux r\u00e9voltes. Est-ce que tu vois dans la soci\u00e9t\u00e9 qu\u00e9b\u00e9coise une hantise du conflit qui expliquerait notamment la difficult\u00e9 d\u2019avoir des d\u00e9bats et des perspectives critiques ?<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Ton impression est juste et s\u2019explique par le statut des Qu\u00e9b\u00e9cois, un petit peuple noy\u00e9 dans une mer anglophone. Il y a toujours eu le sentiment dans la culture politique qu\u00e9b\u00e9coise qu\u2019on est une famille, et qu\u2019on n\u2019a pas les moyens de se chicaner (se disputer) parce que si on le fait, on va s\u2019affaiblir. J\u2019ai ressenti \u00e7a en 2012 : ce qui d\u00e9rangeait une bonne partie de la population qui \u00e9tait hostile au mouvement, \u00e7a n\u2019\u00e9tait pas tant nos revendications, mais le simple fait qu\u2019on \u00e9tait l\u00e0, qu\u2019on parlait, qu\u2019on d\u00e9rangeait, qu\u2019on bousculait, qu\u2019on ne retournait pas \u00e0 nos petites affaires. Il y a cet esp\u00e8ce d\u2019amour de la tranquillit\u00e9 chez les Qu\u00e9b\u00e9cois. Mais il y a aussi une tradition de lutte sociale au Qu\u00e9bec excessivement riche. Le Qu\u00e9bec reste l\u2019endroit en Am\u00e9rique du Nord, et de loin, o\u00f9 il y a le plus de mobilisation sociale. Depuis les ann\u00e9es soixante il y a au moins deux mouvements \u00e9tudiants par d\u00e9cennie. C\u2019est le paradoxe d\u2019un \u00e9thos politique assez tranquille, et une tradition tr\u00e8s riche de syndicalisme combattif.<\/p>\n<p>Un homme d\u2019une cinquantaine d\u2019ann\u00e9es s\u2019approche alors de notre table et tend la main \u00e0 Gabriel. Rencontre \u00e9clair d\u2019une seule phrase qui en dit long sur la d\u00e9sillusion, que nous connaissons aussi en France, des peuples envers leurs dirigeants, et qui m\u00e9rite d\u2019\u00eatre cit\u00e9e : \u00ab Vous avez un admirateur, et je souhaite que jamais vous ne vous lanciez en politique \u00bb.<\/p>\n<p><strong>Qu\u2019est-ce qui a \u00e9merg\u00e9 comme formes d\u2019art lors du mouvement \u00e9tudiant ?<\/strong><\/p>\n<p>Ce qu\u2019il faut pr\u00e9ciser d\u2019abord, c\u2019est que toute cette expressivit\u00e9 est arriv\u00e9e relativement tard dans le mouvement, vers avril. La condition de possibilit\u00e9 de cette \u00e9mergence artistique, c\u2019\u00e9tait le travail pratique des militants sur le terrain. Donc cette sensibilit\u00e9 artistique est apparue parce qu\u2019un espace de libert\u00e9 a \u00e9t\u00e9 ouvert, parce que les contraintes quotidiennes \u00e9taient abolies, et parce que la rue \u00e9tait devenue un nouvel espace d\u2019expression. Ces espaces ne sont pas suffisants mais ils sont n\u00e9cessaires pour que cette sensibilit\u00e9 artistique puisse s\u2019exprimer.<\/p>\n<p>Ces arts urbains ont aliment\u00e9 un sentiment d\u2019appartenance, une v\u00e9ritable identification et pour certains, un vrai sens \u00e0 leur vie. Et c\u2019\u00e9tait l\u00e0 une des grandes forces du mouvement, qui explique aussi sa r\u00e9silience \u00e0 la brutalit\u00e9 m\u00e9diatique et polici\u00e8re, \u00e0 la r\u00e9pression juridique et au fait qu\u2019une bonne partie de la population \u00e9tait hostile au mouvement. C\u2019est aussi ce qui a rendu si difficile l\u2019arr\u00eat de ce mouvement, par d\u00e9finition \u00e9ph\u00e9m\u00e8re, mais encore aujourd\u2019hui j\u2019en entends qui cherchent \u00e0 retrouver ce sentiment.<\/p>\n<p><strong>Justement une fois que le mouvement est fini : quelle est la place des arts dans une soci\u00e9t\u00e9 du divertissement et du loisir ? Crois-tu qu\u2019il soit possible que les arts soient porteurs de ce sentiment d\u2019appartenance qui pourrait pr\u00e9parer \u00e0 un projet de soci\u00e9t\u00e9 ?<\/strong><\/p>\n<p>Au Qu\u00e9bec, la culture est quand m\u00eame bien plus pr\u00e9sente et forte que dans le Canada anglophone. Les gens sont fiers de notre cin\u00e9ma, de notre musique, et de tout ce qui est fait ici. 65% des produits culturels consomm\u00e9s au Qu\u00e9bec sont faits au Qu\u00e9bec. Au Canada, 85% des produits consomm\u00e9s viennent des \u00c9tats-Unis. C\u2019est l\u2019avantage de notre statut de minorit\u00e9. Apr\u00e8s c\u2019est s\u00fbr que la culture ne se porte pas si bien, et que l\u2019\u00c9tat doit valoriser et prot\u00e9ger la culture, surtout en r\u00e9gion.<\/p>\n<p><strong>M\u00eame si les gens consomment leur propre culture, penses-tu qu\u2019on soit \u00e0 l\u2019abri de la monoculture du divertissement, o\u00f9 les gens consomment leur produit culturel et passent \u00e0 autre chose ? Donc de quelque chose d\u2019o\u00f9 le sentiment d\u2019appartenance et l\u2019engagement citoyen est absent ?<\/strong><\/p>\n<p>C\u2019est un ph\u00e9nom\u00e8ne r\u00e9el. Et la solution c\u2019est de donner le go\u00fbt de l\u2019art et de la culture rapidement. Et \u00e7a passe par l\u2019\u00e9ducation. Malheureusement notre syst\u00e8me d\u2019\u00e9ducation prend la direction inverse. Il faut que d\u00e8s le primaire l\u2019\u00e9cole soit un lieu de culture au sens plein du terme : culture artistique, culture scientifique, culture intellectuelle. Il faut que l\u2019\u00e9cole redevienne un lieu de culture plut\u00f4t qu\u2019un lieu de formation. Je pense que c\u2019est une des raisons pour lesquelles on s\u2019est mobilis\u00e9 en 2012. Si une institution publique comme l\u2019\u00e9ducation ne valorise pas la culture, c\u2019est s\u00fbr que c\u2019est perdu d\u2019avance. Le go\u00fbt de l\u2019art n\u2019est pas inn\u00e9, \u00e7a s\u2019apprend, comme on apprend \u00e0 parler, \u00e0 compter, \u00e0 d\u00e9guster un bon vin.<\/p>\n<p><strong>Radio Canada a subi cette ann\u00e9e une nouvelle vague de coupures drastiques et de licenciements. On parle de la mort de Radio Canada. Qu\u2019est-ce que tu en penses, toi qui y travailles depuis cette ann\u00e9e comme intervenant dans une \u00e9mission ?<\/strong><\/p>\n<p>Radio Canada est de moins en moins conforme \u00e0 sa mission. Mais elle reste quand m\u00eame bien au-dessus de ce qui se fait avant. Il y a quand m\u00eame un espace de discussion et de culture. Sans Radio Canada il y a tant d\u2019artistes dont on aurait jamais entendu parler.<\/p>\n<p>Alors vu l\u2019\u00e9tat de la presse, de l\u2019\u00e9ducation, de la culture, la solution part d\u2019o\u00f9 selon toi ? Du gouvernement ou bien des comportements individuels ? Si on prend par exemple la presse, les gens ne veulent plus acheter des journaux et on sait bien que cela joue beaucoup dans la disparition de journaux ind\u00e9pendants.<\/p>\n<p>C\u2019est vrai que les comportements individuels sont \u00e0 changer. Mais on ne peut pas tout faire reposer sur des efforts individuels que tout le monde n\u2019a pas les moyens de poser. Au final, ce qui est d\u00e9terminant, c\u2019est la volont\u00e9 politique.<\/p>\n<p><strong>Est-ce que ton engagement irait du c\u00f4t\u00e9 de la politique ?<\/strong><\/p>\n<p>En ce moment je suis un \u00e9tudiant qui intervient dans certains m\u00e9dias qui sont pour moi des tribunes pour faire avancer des id\u00e9es. Mon engagement politique va continuer c\u2019est s\u00fbr, mais je ne sais pas quelle forme \u00e7a va prendre.<\/p>\n<p><strong>Est-ce que notre g\u00e9n\u00e9ration n\u2019est pas condamn\u00e9e \u00e0 des actions qui seront toujours des oppositions au syst\u00e8me lib\u00e9ral et capitaliste qu\u2019on nous impose ? Serons-nous la g\u00e9n\u00e9ration qui aura d\u00fb faire le m\u00e9nage pour poser les bases d\u2019une autre soci\u00e9t\u00e9 ?<\/strong><\/p>\n<p>Je pense que dans tout refus il y a une valeur positive. En refusant le projet d\u2019ol\u00e9oduc, on freine l\u2019expansion des sables bitumeux, donc on contribue \u00e0 freiner le changement climatique \u00e0 l\u2019\u00e9chelle globale. Car refuser la destruction de l\u2019environnement c\u2019est le prot\u00e9ger. Emp\u00eacher la privatisation du service public c\u2019est le renforcer. Il va y avoir beaucoup de luttes d\u00e9fensives \u00e0 mener. \u00c7a n\u2019est s\u00fbrement pas suffisant, car il va falloir \u00eatre capable d\u2019articuler un projet positif et de proposer un projet politique. On est la premi\u00e8re g\u00e9n\u00e9ration o\u00f9 ce projet est \u00e0 repenser. Nos parents avaient le choix entre deux syst\u00e8mes d\u00e9j\u00e0 d\u00e9finis, le capitalisme et la sociale d\u00e9mocratie. Nous n\u2019avons pas le luxe de ces utopies politiques parce que nous vivons dans un monde o\u00f9 un seul syst\u00e8me domine. On vit avec le double \u00e9chec du communisme et de la sociale d\u00e9mocratie. Il nous reste tout \u00e0 inventer.<\/p>\n<p>Pendant que les Fran\u00e7ais dissertent sur la l\u00e9gitimit\u00e9 de leur pr\u00e9sident et sur les cons\u00e9quences de l\u2019affaire du barrage de Sivens, les Qu\u00e9b\u00e9cois sont all\u00e9s au bout de leurs combats. Qu\u2019on se le dise : une gr\u00e8ve \u00e9tudiante qui d\u00e9clenche un mouvement social, un mouvement social qui entra\u00eene un changement de gouvernement, une r\u00e9sistance \u00e0 un projet massif de destruction de l\u2019environnement qui trouve les moyens de sa lutte gr\u00e2ce au livre d\u2019un jeune homme de vingt-quatre ans. La France, pays des Lumi\u00e8res, des r\u00e9volutions et des gr\u00e8ves constantes, puissance mondiale en perte de vitesse et en crise identitaire, a peut-\u00eatre beaucoup \u00e0 apprendre de ce petit peuple sans pays. Il serait temps de rattraper notre ignorance sur nos cousins nord-am\u00e9ricains qui sont d\u00e9cid\u00e9ment autre chose que des com\u00e9dies musicales et des chanteurs \u00e0 l\u2019accent folklorique.<\/p>","protected":false},"excerpt":{"rendered":"<p>Publi\u00e9 dans Cassandre Hors Champ : 100 \u00abDe vents et de mar\u00e9es\u00bb 2012, ann\u00e9e qui restera grav\u00e9e dans l\u2019histoire du Qu\u00e9bec comme celle d\u2019un \u00e9veil. Le Printemps \u00c9rable comme on l\u2019a appel\u00e9, est un mouvement contestataire, parti d\u2019une gr\u00e8ve \u00e9tudiante, qui a dur\u00e9 huit mois. Ce mouvement a d\u00e9clench\u00e9 des \u00e9lections anticip\u00e9es et la destitution [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"tags":[163,148,166,161,153,167,162,165,164,160],"class_list":["post-373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyses","tag-carre-rouge","tag-culture","tag-engagement-citoyen","tag-environnement","tag-france","tag-gabriel-nadeau-dubois","tag-gaz-de-schistes","tag-greve","tag-mouvement-etudiant","tag-quebec"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ? - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ? - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Publi\u00e9 dans Cassandre Hors Champ : 100 \u00abDe vents et de mar\u00e9es\u00bb 2012, ann\u00e9e qui restera grav\u00e9e dans l\u2019histoire du Qu\u00e9bec comme celle d\u2019un \u00e9veil. Le Printemps \u00c9rable comme on l\u2019a appel\u00e9, est un mouvement contestataire, parti d\u2019une gr\u00e8ve \u00e9tudiante, qui a dur\u00e9 huit mois. Ce mouvement a d\u00e9clench\u00e9 des \u00e9lections anticip\u00e9es et la destitution [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-10T01:17:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-18T13:43:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/gnd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"33 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/gnd.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/gnd.jpg\",\"width\":435,\"height\":290},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/\",\"name\":\"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ? - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#primaryimage\"},\"datePublished\":\"2015-06-10T01:17:45+00:00\",\"dateModified\":\"2020-05-18T13:43:36+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ? - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/","og_locale":"es_ES","og_type":"article","og_title":"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ? - Sarah Roubato","og_description":"Publi\u00e9 dans Cassandre Hors Champ : 100 \u00abDe vents et de mar\u00e9es\u00bb 2012, ann\u00e9e qui restera grav\u00e9e dans l\u2019histoire du Qu\u00e9bec comme celle d\u2019un \u00e9veil. Le Printemps \u00c9rable comme on l\u2019a appel\u00e9, est un mouvement contestataire, parti d\u2019une gr\u00e8ve \u00e9tudiante, qui a dur\u00e9 huit mois. Ce mouvement a d\u00e9clench\u00e9 des \u00e9lections anticip\u00e9es et la destitution [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-06-10T01:17:45+00:00","article_modified_time":"2020-05-18T13:43:36+00:00","og_image":[{"width":435,"height":290,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/gnd.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"33 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/gnd.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/06\/gnd.jpg","width":435,"height":290},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/","name":"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ? - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#primaryimage"},"datePublished":"2015-06-10T01:17:45+00:00","dateModified":"2020-05-18T13:43:36+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/analyses\/le-quebec-un-modele-de-resistance-culturelle-et-politique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Le Qu\u00e9bec : un mod\u00e8le de r\u00e9sistance culturelle et politique ?"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":15,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"predecessor-version":[{"id":4464,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/373\/revisions\/4464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/375"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}