
{"id":4179,"date":"2020-04-07T23:04:12","date_gmt":"2020-04-07T21:04:12","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=4179"},"modified":"2023-10-15T23:21:58","modified_gmt":"2023-10-15T21:21:58","slug":"covid19","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/lettres\/covid19\/","title":{"rendered":"Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[:"},"content":{"rendered":"<p><em>Cada mes, Sarah Roubato escribe una carta abierta sobre un tema de actualidad. Y para este mes de abril, \u00bfqu\u00e9 otra pregunta podr\u00eda imponerse aparte de la crisis vinculada al coronavirus? Una crisis que revela todo lo que nuestra sociedad puede tener de peor, de mejor y las lecciones que ser\u00eda prudente aprender de ella?<\/em><\/p>\n<p align=\"justify\"><strong>Un hurac\u00e1n microsc\u00f3pico<\/strong><\/p>\n<p>\u00a1Bien visto! Ten\u00eda que dar un gran golpe. \u00bfLos incendios de la Amazonia y de Australia? Demasiado lejos. \u00bfLas inundaciones y las tormentas? No son lo suficientemente espectaculares todav\u00eda. \u00bfLas crisis financieras? \u00bfRecuperadas in extremis. \u00bfLos movimientos sociales masivos? No est\u00e1n suficientemente organizados para derrocar los gobiernos. \u00bfLa muerte del viviente? Demasiado lenta en la escala de vidas humanas. Se necesitaba algo que fuera m\u00e1s all\u00e1 de la ef\u00edmera emoci\u00f3n medi\u00e1tica o el bloqueo temporal de un pa\u00eds. Que nos tetanice. \u00a1Qu\u00e9 hallazgo! Un hurac\u00e1n microsc\u00f3pico que nos azota. Que de repente paraliza todo lo que cre\u00edamos destinado a mantener su ritmo inexorable. Un culpable sin rostro, que revela todas las fallas de este mundo que hemos creado.<\/p>\n<p>Vimos las aguas claras de Venecia y las escenas de p\u00e1nico para arrojarse sobre las pastas y el papel higi\u00e9nico. Hemos visto los conciertos de balc\u00f3n en Australia y las palabras de apoyo en los ascensores. La extraordinaria creatividad de los artistas frente a un ma\u00f1ana amenazado y el hero\u00edsmo de los profesionales sanitarios. Los picnics a orillas del Sena y los aplausos a las 8 de la noche. Porque esta es tu terrible belleza: revelas las fragilidades, pero tambi\u00e9n fuerza, ego\u00edsmo y hero\u00edsmo. Es s\u00f3lo frente a ti que el ser humano se interroga y por fin piensa en cambiar. Al golpear al mundo entero, al hacernos a todos vulnerables, nos obligas a cuestionarlo todo.<\/p>\n<p>La interdependencia de los pa\u00edses sobre los bienes esenciales como los equipos m\u00e9dicos, la de nuestras actividades con respecto a lo que viene de lejos, la fragilidad de los equilibrios financieros y planetarios cuando se desacelera la m\u00e1quina. La relevancia de poder controlar nuestras fronteras, la relaci\u00f3n entre l\u00edderes y ciudadanos a la hora de protegernos. Descubrimos, sin sorpresa, que se pueden encontrar miles de millones cuando queramos, que las cotizaciones pueden ser suspendidas, que el sacrosanto rigor presupuestario que estaba estrangulando los servicios p\u00fablicos, en particular los hospitales puede ser aflojado. Descubrimos tambi\u00e9n, quiz\u00e1s con m\u00e1s sorpresa, c\u00f3mo podemos habitar de una manera diferente nuestro tiempo y nuestros espacios vitales.<\/p>\n<p align=\"justify\"><strong>Otro tiempo, otro espacio para habitar<\/strong><\/p>\n<p>Para muchos, todo est\u00e1 en suspenso, mientras que para otros, aquellos cuyo papel esencial se descubre de repente en nuestras sociedades es la aceleraci\u00f3n infernal. Y sin embargo, tetanizados (inquietos y tensos, sentimos que hay una \u00faltima lecci\u00f3n que aprender.<\/p>\n<p>Desde nuestras ventanas, podemos ver lo que podr\u00eda parecerse a un mundo sin nosotros: un mundo que respira y canta, donde lo viviente vuelve a ocupar su lugar. Una ventana milagrosa ofrecida como se obligar\u00eda a un ni\u00f1o testarudo a mirar (lo que hemos estado tratando de mostrarle desde hace mucho tiempo. Una ventana abierta tambi\u00e9n a nosotros mismos: frenados en nuestro consumo, cada uno de nosotros se encuentra ante lo que somos cuando ya no somos el consumidor destinado a hacer funcionar la m\u00e1quina: un padre, un c\u00f3nyuge, un hijo, un vecino, un ciudadano. Este repliegue sobre nosotros mismos nos invita a abrirnos a los dem\u00e1s y a tomar conciencia de lo que estamos participando. As\u00ed que lo que hago y lo que no hago tiene un impacto fuera de m\u00ed&#8230; &#8230;una evidencia que nuestra cultura de <i>homo consomicus<\/i> ha tardado unas cuantas generaciones en borrar.<\/p>\n<p>Ahora nuestros espacios vitales se est\u00e1n convirtiendo en algo m\u00e1s que un dormitorio: un espacio de trabajo, un lugar de escolaridad para los ni\u00f1os, un parque infantil, un espacio de deportes. Todo debe tener lugar en 50 o 200 metros cuadrados. El infierno para algunos, el redescubrimiento para otros. Los padres deben asumir el papel de instructores y descubrir todas las dificultades. A veces los ni\u00f1os descubren a sus padres trabajando, y tienen que aprender a respetar ese momento. Estos ni\u00f1os, a los que se les suelen atiborrar con actividades y conocimientos, pueden volver a aprender a aburrirse, a relajarse, a ser actores de su tiempo, a dormir el tiempo que el cuerpo necesita.<\/p>\n<p>Mientras que el tiempo bate su terrible cuenta regresiva para los peque\u00f1os agricultoros sin m\u00e1s mercados, se acelera para los cuidadores, los trabajadoros del sector agroalimentario, y para todos aquellos que empacan los paquetes y las comidas que pedimos, para otros el tiempo se estira. Se suspende. Fluye de nuevo. \u00bfQu\u00e9 vamos a hacer con \u00e9l? \u00bfVolver a lo esencial? \u00bfRecalibrar nuestras prioridades? \u00bfDescubrir que sabemos adaptarnos m\u00e1s de lo que pens\u00e1bamos? \u00bfQu\u00e9 otras formas de trabajar y vivir en familia son posibles? \u00bfO pisotear y atiborrarse de pantallas hasta que podamos volver de nuevo a las tiendas y a los viajes de bajo coste?<\/p>\n<p align=\"justify\"><strong>Un revelador de desigualdades<\/strong><\/p>\n<p>Sabes c\u00f3mo presionar donde duele: bajo tu presi\u00f3n, las desigualdades y las fracturas sociales se revelan. En primer lugar, entre los que tienen que permanecer atr\u00e1s y los que tienen que quedarse en la cubierta: profesionales de la salud, trabajadores postales, recolectores de basura, cajeros, agricultores, transportistas. Luego entre aquellos para quienes el cese de actividad significa una cambio de calendario y una ralentizaci\u00f3n de la actividad, y aquellos para quienes es un peligro de muerte: peque\u00f1os comerciantes, productores en circuitos cortos, trabajadores independientes, intermitentes, temporales, etc. Por \u00faltimo, las desigualdades en el confinamiento: los que viven cinco en 50 metros cuadrados y los que tienen espacio, los que est\u00e1n en la ciudad y los que est\u00e1n en el campo, los que viven en el campo y los que van a la residencia secundaria, los que tienen hijos y los que no. Por \u00faltimo, entre nosotros y nuestros ancianos, ya sea en sus casas o en una instituci\u00f3n, que descienden un piso m\u00e1s en el aislamiento permanente en el que los dejamos.<\/p>\n<p>Las heridas se abren. Y al hacerlo, se aprende a cauterizarlas. Surgen nuevas solidaridades. Los abogados han creado un colectivo para ofrecer asesoramiento gratuito. Los profesionales de la salud se prestan asistencia mutua entre distintos servicios que nunca hab\u00edan cre\u00eddo posible. Lo que antes y todav\u00eda en algunos pa\u00edses era un gesto natural y que hemos transformado en un servicio de pago, lo redescubrimos como un deber ciudadano: los vecinos\u00a0 cuidan\u00a0 los hijos de los dem\u00e1s, los j\u00f3venes del edificio van a hacer las compras para los ancianos a los que apenas saludaban\u00a0 hace unas semanas, cuyo nombre probablemente no sab\u00edan. \u00bfEs esto un entusiasmo solidario pasajero o\u00a0 un comienzo de una nueva organizaci\u00f3n de las relaciones sociales?<\/p>\n<p><b>Un acelerador de transici\u00f3n<\/b><\/p>\n<p>Aquellos que creen en una voluntad superior ya te convierten en la herramienta de un justo restablecimiento de los equilibrios que hemos destruido.<a name=\"s2_31\"><\/a>La La advertencia suprema. <a name=\"s2_41\"><\/a>Nuestros cerebros siempre necesitan un sentido. <a name=\"s2_51\"><\/a>Si debe tener un sentido, debemos conquistarlo. <a name=\"s2_61\"><\/a>Ya se oye el estribillo \u00abNunca m\u00e1s como antes\u00bb que el humano ha ridiculizado en todas las horas de las grandes cat\u00e1strofes, antes de hundirse a\u00fan m\u00e1s r\u00e1pido en su locura.<\/p>\n<p>As\u00ed que, para aquellos cuya movilizaci\u00f3n consiste en permanecer en casa, tom\u00e9monos el tiempo de preguntarnos en qu\u00e9 estamos participando. Porque el ser humano tambi\u00e9n tiene esta excepcional capacidad de transformar lo tr\u00e1gico en potencial creativo, lo inaceptable en una oportunidad, la injusticia en un nuevo motivo de esperanza. Los imperativos ya est\u00e1n ah\u00ed y se precisar\u00e1n: reinvertir en lo local, tender hacia la autonom\u00eda, basar nuestras vidas en algo diferente del consumo, hacer de la ayuda mutua y del compromiso ciudadano una herramienta de cohesi\u00f3n social, recuperar la libertad individual que siempre respete el bienestar colectivo.<\/p>\n<p>Cuando podamos salir de nuevo, cuando los noticieros televisivos desgranen las cifras de\u00a0 la recuperaci\u00f3n, cuando sea la hora de volver a abalanzarse\u00a0 sobre todo lo que se fabrica innecesariamente en el otro extremo del mundo, cuando de nuevo pasemos delante de nuestro vecino y apenas nos saludemos, que cada uno reanude su fren\u00e9tica carrera\u00a0 para seguir\u00a0 la m\u00e1xima <i>Trabaja para consumir, consuma para descansar de trabajar<\/i>, cuando los transatl\u00e1nticos gigantes invadan nuevamente Venecia, cuando\u00a0 los p\u00e1jaros de nuestras ciudades canten sin ser escuchados, \u00bfqu\u00e9 quedar\u00e1 de esta formidable palanca de cambio que nos tiendes? El mayor peligro ser\u00eda un retorno a lo que llam\u00e1bamos \u00abnormal\u00bb. Entonces regresar\u00e9is, en formas que ni siquiera podemos imaginar. Osemos, pues, el \u00fanico hero\u00edsmo que nos queda\u00a0: el de exigir un cambio radical. Porque ya es hora.<\/p>\n<p>Gracias a <a href=\"http:\/\/www.tlaxcala-int.org\/article.asp?reference=28584\">Tlaxcala<\/a> por la traduccion<\/p>","protected":false},"excerpt":{"rendered":"<p>Cada mes, Sarah Roubato escribe una carta abierta sobre un tema de actualidad. Y para este mes de abril, \u00bfqu\u00e9 otra pregunta podr\u00eda imponerse aparte de la crisis vinculada al coronavirus? Una crisis que revela todo lo que nuestra sociedad puede tener de peor, de mejor y las lecciones que ser\u00eda prudente aprender de ella? [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-4179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lettres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[: - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[: - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Cada mes, Sarah Roubato escribe una carta abierta sobre un tema de actualidad. Y para este mes de abril, \u00bfqu\u00e9 otra pregunta podr\u00eda imponerse aparte de la crisis vinculada al coronavirus? Una crisis que revela todo lo que nuestra sociedad puede tener de peor, de mejor y las lecciones que ser\u00eda prudente aprender de ella? [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-07T21:04:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-15T21:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2020\/04\/munch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2020\/04\/munch.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2020\/04\/munch.jpg\",\"width\":768,\"height\":432},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/\",\"name\":\"Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[: - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#primaryimage\"},\"datePublished\":\"2020-04-07T21:04:12+00:00\",\"dateModified\":\"2023-10-15T21:21:58+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[:fr] Lettre \u00e0 la crise sanitaire[:es]Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[:\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[: - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/","og_locale":"es_ES","og_type":"article","og_title":"Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[: - Sarah Roubato","og_description":"Cada mes, Sarah Roubato escribe una carta abierta sobre un tema de actualidad. Y para este mes de abril, \u00bfqu\u00e9 otra pregunta podr\u00eda imponerse aparte de la crisis vinculada al coronavirus? Una crisis que revela todo lo que nuestra sociedad puede tener de peor, de mejor y las lecciones que ser\u00eda prudente aprender de ella? [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2020-04-07T21:04:12+00:00","article_modified_time":"2023-10-15T21:21:58+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2020\/04\/munch.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2020\/04\/munch.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2020\/04\/munch.jpg","width":768,"height":432},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#webpage","url":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/","name":"Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[: - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#primaryimage"},"datePublished":"2020-04-07T21:04:12+00:00","dateModified":"2023-10-15T21:21:58+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/lettres\/covid19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/lettres\/covid19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"[:fr] Lettre \u00e0 la crise sanitaire[:es]Carta a la crisis sanitaria: Covid-19, \u00bfla \u00faltima lecci\u00f3n?[:"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/4179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=4179"}],"version-history":[{"count":7,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/4179\/revisions"}],"predecessor-version":[{"id":6170,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/4179\/revisions\/6170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/4180"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=4179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=4179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=4179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}