
{"id":613,"date":"2015-07-11T13:22:24","date_gmt":"2015-07-11T19:22:24","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=613"},"modified":"2020-05-17T17:40:29","modified_gmt":"2020-05-17T15:40:29","slug":"lettre-en-morceaux-a-emile-zola-5","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/lettres\/lettre-en-morceaux-a-emile-zola-5\/","title":{"rendered":"Lettre en morceaux \u00e0 \u00c9mile Zola 5"},"content":{"rendered":"<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg\" alt=\"Lettre Zola5\" width=\"400\" height=\"310\" class=\"alignnone size-full wp-image-601\" srcset=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg 400w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5-150x116.jpg 150w, https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5-300x233.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Le 10 juillet 2015<\/p>\n<\/p>\n<p>Monsieur Zola,<\/p>\n<\/p>\n<p> Vous avez \u00e9t\u00e9 le premier \u00e0 bien des choses : le premier \u00e0 faire entrer le vrai langage du peuple en litt\u00e9rature, le premier intellectuel  \u00e0 \u00eatre descendu  dans les mines, le premier journaliste \u00e0 se mettre volontairement un proc\u00e8s \u00e0 dos pour faire triompher la v\u00e9rit\u00e9. Vous avez pressenti que des forces psychologiques inconscientes faisaient agir les hommes, vous avez vu l\u2019\u00e9mergence de la consommation de masse.<\/p>\n<\/p>\n<p> Mais vous \u00e9tiez aussi un homme de votre \u00e9poque. Pour qui la femme n\u2019est que f\u00e9condit\u00e9. Je suis femme et je veux \u00e9crire. Mais je ne revendique aucune f\u00e9minit\u00e9 de mon \u00e9criture. Quand je cherche, quand je pense, quand j\u2019\u00e9cris, je n\u2019ai pas de sexe. Une femme \u00e9crivain a r\u00e9dig\u00e9 un jour un essai pour r\u00e9pondre \u00e0 la question: Que faut-il  \u00e0 une femme pour \u00eatre \u00e9crivain ? Sa r\u00e9ponse : une chambre \u00e0 soi et quelque argent . Elle s\u2019appelait Virginia Woolf. Cependant, elle avait encore oubli\u00e9 un aspect, que vous et elles aviez : des domestiques. M\u00eame dans la mis\u00e8re, vous ne vous pr\u00e9pariez pas votre propres repas trois fois par jour, vous ne faisiez pas le m\u00e9nage dans votre chambre et n\u2019alliez pas laver votre linge au lavoir. Ensuite vous avez eu votre femme, puis des domestiques. On s\u2019\u00e9tonne souvent de la force de travail de vous, hommes et femmes de lettres, d\u2019art, de musique, de science. Mais on oublie qu\u2019\u00e0 vos \u00e9poques, vous pouviez passer une semaine enti\u00e8re \u00e0 votre table de travail du matin au soir, vous auriez tout de m\u00eame des repas pr\u00eats et l\u2019entretien de votre maison.<\/p>\n<\/p>\n<p> Je ne demande que l\u2019espace et le temps pour travailler correctement. Je demande que soit reconnu celui qui donne chaque jour de sa vie (en dehors des taches de la vie quotidienne) \u00e0 comprendre la soci\u00e9t\u00e9, un salaire digne de celui des vigiles de supermarch\u00e9s. Je demande l\u2019impossible, Monsieur Zola. Car dans la soci\u00e9t\u00e9 o\u00f9 je vis mon travail ne vaut rien. Je gagne plus d\u2019argent \u00e0 changer les couches d\u2019un b\u00e9b\u00e9 ou \u00e0 rester derri\u00e8re un comptoir \u00e0 ne rien faire. C\u2019est le lot de tous ceux qui travaillent \u00e0 la sant\u00e9 de l\u2019esprit et de l\u2019\u00e2me : savez-vous que celui qui pendant une heure prendra soin de votre corps (nous appelons cela ost\u00e9opathe, kin\u00e9sith\u00e9rapeute, massoth\u00e9rapeute, acuponcteur, et bien d\u2019autres termes), gagnera autour de 100$ (120 euros). Mais le musicien qui prend soin de votre \u00e2me et de votre esprit pendant trois heures, et qui est l\u00e0 depuis l\u2019apr\u00e8s-midi, lui ne touchera parfois pas 50$. On d\u00e9pense 2euros pour un caf\u00e9, mais on n\u2019en verserait pas la m\u00eame chose pour un journal.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-1.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-1.png\" alt=\"signature Sarah 1\" width=\"1392\" height=\"672\" class=\"alignnone size-full wp-image-621\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le 10 juillet 2015 Monsieur Zola, Vous avez \u00e9t\u00e9 le premier \u00e0 bien des choses : le premier \u00e0 faire entrer le vrai langage du peuple en litt\u00e9rature, le premier intellectuel \u00e0 \u00eatre descendu dans les mines, le premier journaliste \u00e0 se mettre volontairement un proc\u00e8s \u00e0 dos pour faire triompher la v\u00e9rit\u00e9. Vous avez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-613","post","type-post","status-publish","format-standard","hentry","category-lettres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lettre en morceaux \u00e0 \u00c9mile Zola 5 - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettre en morceaux \u00e0 \u00c9mile Zola 5 - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Le 10 juillet 2015 Monsieur Zola, Vous avez \u00e9t\u00e9 le premier \u00e0 bien des choses : le premier \u00e0 faire entrer le vrai langage du peuple en litt\u00e9rature, le premier intellectuel \u00e0 \u00eatre descendu dans les mines, le premier journaliste \u00e0 se mettre volontairement un proc\u00e8s \u00e0 dos pour faire triompher la v\u00e9rit\u00e9. Vous avez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-11T19:22:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-17T15:40:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg\",\"width\":400,\"height\":310},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/\",\"name\":\"Lettre en morceaux \u00e0 \u00c9mile Zola 5 - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#primaryimage\"},\"datePublished\":\"2015-07-11T19:22:24+00:00\",\"dateModified\":\"2020-05-17T15:40:29+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettre en morceaux \u00e0 \u00c9mile Zola 5\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettre en morceaux \u00e0 \u00c9mile Zola 5 - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/","og_locale":"es_ES","og_type":"article","og_title":"Lettre en morceaux \u00e0 \u00c9mile Zola 5 - Sarah Roubato","og_description":"Le 10 juillet 2015 Monsieur Zola, Vous avez \u00e9t\u00e9 le premier \u00e0 bien des choses : le premier \u00e0 faire entrer le vrai langage du peuple en litt\u00e9rature, le premier intellectuel \u00e0 \u00eatre descendu dans les mines, le premier journaliste \u00e0 se mettre volontairement un proc\u00e8s \u00e0 dos pour faire triompher la v\u00e9rit\u00e9. Vous avez [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-07-11T19:22:24+00:00","article_modified_time":"2020-05-17T15:40:29+00:00","og_image":[{"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/Lettre-Zola5.jpg","width":400,"height":310},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/","name":"Lettre en morceaux \u00e0 \u00c9mile Zola 5 - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#primaryimage"},"datePublished":"2015-07-11T19:22:24+00:00","dateModified":"2020-05-17T15:40:29+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-en-morceaux-a-emile-zola-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Lettre en morceaux \u00e0 \u00c9mile Zola 5"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":3,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/613\/revisions"}],"predecessor-version":[{"id":4436,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/613\/revisions\/4436"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}