
{"id":787,"date":"2015-09-03T16:10:20","date_gmt":"2015-09-03T22:10:20","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=787"},"modified":"2020-05-17T14:44:51","modified_gmt":"2020-05-17T12:44:51","slug":"lettre-a-leurope-4","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/lettres\/lettre-a-leurope-4\/","title":{"rendered":"Lettre \u00e0 l&#8217;Europe 4"},"content":{"rendered":"<p>Europe,<\/p>\n<p>Tu sais, je te dis tu, mais je pourrais te dire vous. Ceux qui ont voulu faire de toi un espace de pur \u00e9change \u00e9conomique ont eu peur de tes multiples cultures. Ils ont fait des billets de banque sans aucune r\u00e9f\u00e9rence nationale. Porutant Mozart, Goethe, Hugo, Tchaikovsky, Chopin, Churchill, Einstein, Da Vinci appartiennent \u00e0 tous les Europ\u00e9ens.<\/p>\n<p>Ce n\u2019est pas parce que je m\u2019adresse \u00e0 l\u2019Europe que j\u2019ignore la force de l\u2019identit\u00e9 de chacun de tes enfants \u2013 ou plut\u00f4t de tes parents. Au contraire. Ici au Canada, \u00eatre canadien ne signifie pas grand-chose pour les gens. C\u2019est \u00eatre nord-am\u00e9ricain sans \u00eatre \u00e9tats-unien, c\u2019est \u00eatre qu\u00e9b\u00e9cois sans avoir un pays.<\/p>\n<p>Dans les livres d\u2019histoire, \u00eatre Europ\u00e9en c\u2019est \u00eatre sujet d\u2019un empire, c\u2019est participer aux grandes d\u00e9couvertes des si\u00e8cles derniers. \u00c7a n\u2019est pas \u00e0 cette Europe des id\u00e9es et des guerres que je parle, \u00e0 cette civilisation qui est peut-\u00eatre d\u00e9j\u00e0 morte. C\u2019est \u00e0 toi, fille de chair et de pierre, de rues tordues, de petits villages escarp\u00e9s, de clochers d\u2019\u00e9glises, de quais de gare avec trois personnes qui attendent, de campagnes o\u00f9 en une journ\u00e9e de marche on peut passer devant un mar\u00e9cage, une for\u00eat, un champ, un village, une petite ville. Tu es cette exp\u00e9rience tr\u00e8s physique qui r\u00e9siste aux mots et que seuls mes sens, agress\u00e9s dans les villes nord am\u00e9ricaines ou perdus dans l\u2019immensit\u00e9 de sa nature, me rappellent. Chez toi l\u2019infini se cache dans le petit.<\/p>\n<p><a href=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-NB.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-696\" src=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/07\/signature-Sarah-NB-300x145.png\" alt=\"signature Sarah NB\" width=\"300\" height=\"145\" \/><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Europe, Tu sais, je te dis tu, mais je pourrais te dire vous. Ceux qui ont voulu faire de toi un espace de pur \u00e9change \u00e9conomique ont eu peur de tes multiples cultures. Ils ont fait des billets de banque sans aucune r\u00e9f\u00e9rence nationale. Porutant Mozart, Goethe, Hugo, Tchaikovsky, Chopin, Churchill, Einstein, Da Vinci appartiennent [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[203,188,190],"class_list":["post-787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lettres","tag-europe","tag-lettre-en-morceaux","tag-sarah-roubato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lettre \u00e0 l&#039;Europe 4 - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettre \u00e0 l&#039;Europe 4 - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Europe, Tu sais, je te dis tu, mais je pourrais te dire vous. Ceux qui ont voulu faire de toi un espace de pur \u00e9change \u00e9conomique ont eu peur de tes multiples cultures. Ils ont fait des billets de banque sans aucune r\u00e9f\u00e9rence nationale. Porutant Mozart, Goethe, Hugo, Tchaikovsky, Chopin, Churchill, Einstein, Da Vinci appartiennent [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-03T22:10:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-17T12:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/08\/Europe4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/08\/Europe4.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/08\/Europe4.jpg\",\"width\":400,\"height\":310},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/\",\"name\":\"Lettre \u00e0 l'Europe 4 - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#primaryimage\"},\"datePublished\":\"2015-09-03T22:10:20+00:00\",\"dateModified\":\"2020-05-17T12:44:51+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettre \u00e0 l&#8217;Europe 4\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettre \u00e0 l'Europe 4 - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/","og_locale":"es_ES","og_type":"article","og_title":"Lettre \u00e0 l'Europe 4 - Sarah Roubato","og_description":"Europe, Tu sais, je te dis tu, mais je pourrais te dire vous. Ceux qui ont voulu faire de toi un espace de pur \u00e9change \u00e9conomique ont eu peur de tes multiples cultures. Ils ont fait des billets de banque sans aucune r\u00e9f\u00e9rence nationale. Porutant Mozart, Goethe, Hugo, Tchaikovsky, Chopin, Churchill, Einstein, Da Vinci appartiennent [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-09-03T22:10:20+00:00","article_modified_time":"2020-05-17T12:44:51+00:00","og_image":[{"width":400,"height":310,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/08\/Europe4.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/08\/Europe4.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/08\/Europe4.jpg","width":400,"height":310},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/","name":"Lettre \u00e0 l'Europe 4 - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#primaryimage"},"datePublished":"2015-09-03T22:10:20+00:00","dateModified":"2020-05-17T12:44:51+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/lettres\/lettre-a-leurope-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Lettre \u00e0 l&#8217;Europe 4"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":5,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/787\/revisions"}],"predecessor-version":[{"id":804,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/787\/revisions\/804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/782"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}