
{"id":843,"date":"2015-10-01T11:33:54","date_gmt":"2015-10-01T17:33:54","guid":{"rendered":"https:\/\/dev.sarahroubato.com\/?p=843"},"modified":"2021-11-04T12:13:50","modified_gmt":"2021-11-04T11:13:50","slug":"hella","status":"publish","type":"post","link":"https:\/\/dev.sarahroubato.com\/es\/extraquotidien\/hella\/","title":{"rendered":"Hella : la libert\u00e9 qui s&#8217;adapte"},"content":{"rendered":"<p>Quand elle a quitt\u00e9 une vie de ch\u00e2teau &#8211; litt\u00e9ralement &#8211; en Normandie pour traverser la France avec ses chevaux de course, Hella ne savait pas o\u00f9 elle allait. Dans la montagne dans le sud de la France, les chevaux, comme elle, ont d\u00fb r\u00e9apprendre \u00e0 vivre autrement. Les chevaux en troupeau pastoral, et elle dans un hameau, sans argent.<\/p>\n<p>Au-del\u00e0 des chevaux, Hella parle surtout d&#8217;adaptation, de libert\u00e9, et de l&#8217;art de r\u00e9parer, de redonner confiance. Car Hella r\u00e9cup\u00e8re aussi des chevaux maltrait\u00e9s et leur r\u00e9apprend \u00e0 vivre.<\/p>\n<p>M\u00eame si on ne s&#8217;int\u00e9resse pas aux chevaux, \u00e9couter Hella nous en apprend beaucoup sur nous. Comment pr\u00e9server sa libert\u00e9 sans l&#8217;imposer aux autres ? Comment l&#8217;homme et le cheval s&#8217;adaptent \u00e0 un changement de vie radical ?<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.mixcloud.com\/widget\/iframe\/?feed=https%3A%2F%2Fwww.mixcloud.com%2FSarahRoubato%2Fhella-la-libert%25C3%25A9-qui-sadapte-extraits%2F&amp;hide_cover=1&amp;light=1\" width=\"100%\" height=\"120\" frameborder=\"0\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Quand elle a quitt\u00e9 une vie de ch\u00e2teau &#8211; litt\u00e9ralement &#8211; en Normandie pour traverser la France avec ses chevaux de course, Hella ne savait pas o\u00f9 elle allait. Dans la montagne dans le sud de la France, les chevaux, comme elle, ont d\u00fb r\u00e9apprendre \u00e0 vivre autrement. Les chevaux en troupeau pastoral, et elle [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[193],"tags":[215,217,153,28,218,190],"class_list":["post-843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-extraquotidien","tag-chevaux","tag-eleveur","tag-france","tag-liberte","tag-portrait-audio","tag-sarah-roubato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hella : la libert\u00e9 qui s&#039;adapte - Sarah Roubato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hella : la libert\u00e9 qui s&#039;adapte - Sarah Roubato\" \/>\n<meta property=\"og:description\" content=\"Quand elle a quitt\u00e9 une vie de ch\u00e2teau &#8211; litt\u00e9ralement &#8211; en Normandie pour traverser la France avec ses chevaux de course, Hella ne savait pas o\u00f9 elle allait. Dans la montagne dans le sud de la France, les chevaux, comme elle, ont d\u00fb r\u00e9apprendre \u00e0 vivre autrement. Les chevaux en troupeau pastoral, et elle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/\" \/>\n<meta property=\"og:site_name\" content=\"Sarah Roubato\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SarahRubato\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-01T17:33:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-04T11:13:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/hella-recadr\u00e9e-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1506\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@SarahRubato\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Roubato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\",\"url\":\"https:\/\/dev.sarahroubato.com\/\",\"name\":\"Sarah Roubato\",\"description\":\"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.sarahroubato.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/hella-recadr\u00e9e-scaled.jpg\",\"contentUrl\":\"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/hella-recadr\u00e9e-scaled.jpg\",\"width\":1506,\"height\":2560},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#webpage\",\"url\":\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/\",\"name\":\"Hella : la libert\u00e9 qui s'adapte - Sarah Roubato\",\"isPartOf\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#primaryimage\"},\"datePublished\":\"2015-10-01T17:33:54+00:00\",\"dateModified\":\"2021-11-04T11:13:50+00:00\",\"author\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dev.sarahroubato.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hella : la libert\u00e9 qui s&#8217;adapte\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04\",\"name\":\"Sarah Roubato\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.sarahroubato.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g\",\"caption\":\"Sarah Roubato\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SarahRubato\",\"https:\/\/twitter.com\/SarahRubato\"],\"url\":\"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hella : la libert\u00e9 qui s'adapte - Sarah Roubato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/","og_locale":"es_ES","og_type":"article","og_title":"Hella : la libert\u00e9 qui s'adapte - Sarah Roubato","og_description":"Quand elle a quitt\u00e9 une vie de ch\u00e2teau &#8211; litt\u00e9ralement &#8211; en Normandie pour traverser la France avec ses chevaux de course, Hella ne savait pas o\u00f9 elle allait. Dans la montagne dans le sud de la France, les chevaux, comme elle, ont d\u00fb r\u00e9apprendre \u00e0 vivre autrement. Les chevaux en troupeau pastoral, et elle [&hellip;]","og_url":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/","og_site_name":"Sarah Roubato","article_author":"https:\/\/www.facebook.com\/SarahRubato","article_published_time":"2015-10-01T17:33:54+00:00","article_modified_time":"2021-11-04T11:13:50+00:00","og_image":[{"width":1506,"height":2560,"url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/hella-recadr\u00e9e-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@SarahRubato","twitter_misc":{"Escrito por":"Sarah Roubato","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.sarahroubato.com\/#website","url":"https:\/\/dev.sarahroubato.com\/","name":"Sarah Roubato","description":"Changer nos repr\u00e9sentations de la soci\u00e9t\u00e9 pour envisager d&#039;autres possibles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sarahroubato.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#primaryimage","inLanguage":"es","url":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/hella-recadr\u00e9e-scaled.jpg","contentUrl":"https:\/\/dev.sarahroubato.com\/wp-content\/uploads\/2015\/10\/hella-recadr\u00e9e-scaled.jpg","width":1506,"height":2560},{"@type":"WebPage","@id":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#webpage","url":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/","name":"Hella : la libert\u00e9 qui s'adapte - Sarah Roubato","isPartOf":{"@id":"https:\/\/dev.sarahroubato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#primaryimage"},"datePublished":"2015-10-01T17:33:54+00:00","dateModified":"2021-11-04T11:13:50+00:00","author":{"@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04"},"breadcrumb":{"@id":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sarahroubato.com\/en\/extraquotidien\/hella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev.sarahroubato.com\/"},{"@type":"ListItem","position":2,"name":"Hella : la libert\u00e9 qui s&#8217;adapte"}]},{"@type":"Person","@id":"https:\/\/dev.sarahroubato.com\/#\/schema\/person\/2685c6d7bef7b9e1a4080510ea89fc04","name":"Sarah Roubato","image":{"@type":"ImageObject","@id":"https:\/\/dev.sarahroubato.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ff5767013415228dadde23f73429454700345cf695f41f6d5607336f8439a2d?s=96&d=mm&r=g","caption":"Sarah Roubato"},"sameAs":["https:\/\/www.facebook.com\/SarahRubato","https:\/\/twitter.com\/SarahRubato"],"url":"https:\/\/dev.sarahroubato.com\/es\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/comments?post=843"}],"version-history":[{"count":30,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/843\/revisions"}],"predecessor-version":[{"id":5505,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/posts\/843\/revisions\/5505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media\/5307"}],"wp:attachment":[{"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/media?parent=843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/categories?post=843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sarahroubato.com\/es\/wp-json\/wp\/v2\/tags?post=843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}